{"id":11310,"date":"2010-11-03T10:41:40","date_gmt":"2010-11-03T09:41:40","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=11310"},"modified":"2025-03-21T11:59:35","modified_gmt":"2025-03-21T10:59:35","slug":"fragen-personalausweis","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/fragen-personalausweis-1011310\/","title":{"rendered":"Fragen zum neuen Personalausweis"},"content":{"rendered":"<table style=\"float: left; height: 115px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"123\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>mtG demonstrierte auf der IT-Sicherheitsmesse in N\u00fcrnberg den elektronischen Identit\u00e4tsserver (mtG-eID) f\u00fcr sicheren eCommerce und eGovernment<\/p> <p>N\u00fcrnberg\/Darmstadt, 2. November 2010.- Bei seinem Messerundgang auf der it-sa 2010 informierte sich Franz Josef Pschierer, Staatssekret\u00e4r im bayerischen Finanzministerium, bei media transfer AG (mtG) \u00fcber den neuen Personalausweis (nPA) der Bundesrepublik Deutschland. Der Security-Spezialist mtG hat den elektronischen Identit\u00e4tsserver (eID-Server) entwickelt, der mit dem im Ausweis integrierten Chip kommuniziert.<!--more--> Pschierer, der auch Chief Information Officer (CIO) des Freistaates Bayern ist, interessierte sich f\u00fcr die elektronische Identit\u00e4tsfunktion und die qualifizierte Signatur.<\/p> <p>Kernkomponente f\u00fcr die Einbindung der Identit\u00e4tsfunktion in eine Online-Anwendung ist ein elektronischer Identit\u00e4tsserver, der von media transfer AG unter dem Namen mtG-eID entwickelt und vertrieben wird. Andrea Klenk, Vorstand der media transfer AG, erl\u00e4uterte: \u201eDer Identit\u00e4tsserver erm\u00f6glicht es, dass B\u00fcrger sich problemlos und schnell bei Webanwendungen mit dem neuen Personalausweis anmelden k\u00f6nnen, um Shops, Online-Banking oder B\u00fcrgerportale zu nutzen. Der Server baut einen sicheren Kommunikationskanal mit dem Ausweis auf, um die Identit\u00e4tsdaten auszulesen. Das entlastet die Webanwendungen von der komplexen Kommunikation mit dem Chip und mit Clientkomponenten wie der Ausweis-App.\u201c Bei der Entwicklung des Identit\u00e4tsservers seien auch die f\u00fcr alle Diensteanbieter wichtigen Aspekte der Mandantenf\u00e4higkeit, Performanz und Skalierbarkeit umgesetzt worden.<\/p> <p>Technischer Hintergrund<br \/> Im neuen Personalausweis (nPA) ist ein Chip integriert, auf dem die Daten des B\u00fcrgers (zum Beispiel Name und Vorname, Adresse, Geburtsort und  datum) gespeichert sind. Wenn der Ausweisinhaber zustimmt, k\u00f6nnen diese Daten \u00fcber die sogenannte elektronische Identit\u00e4tsfunktion von Web-Shops, im Online-Banking oder von B\u00fcrgerportalen genutzt werden, um Kunden zu identifizieren und zu authentifizieren.<\/p> <p>Dar\u00fcber hinaus bietet der Personalausweis Funktionen zur Altersabfrage (\u201eIst der Inhaber bereits 18?\u201c) und zur Wohnortverifikation, die auch anonym \uf02d also ohne Kenntnis der sonstigen Personendaten \uf02d verwendet werden k\u00f6nnen. Sinnvoll erg\u00e4nzt wird die Identit\u00e4tsfunktion durch die M\u00f6glichkeit, ein Zertifikat zur Erstellung einer rechtsg\u00fcltigen Signatur auf den Ausweis zu laden. Der neue Personalausweis der Bundesrepublik Deutschland wird zum 1. November 2010 eingef\u00fchrt.<\/p> <p>F\u00fcr Diensteanbieter, die den nPA zur Identifizierung und Authentifizierung von Nutzern einsetzen m\u00f6chten, ist neben der Anbindung des eID-Servers ein Berechtigungszertifikat notwendig, das sie beim Bundesverwaltungsamt beantragen k\u00f6nnen. Der eID Server verwaltet das Zertifikat und setzt es in den komplexen Kommunikationsabl\u00e4ufen ein. Es dient als Ausweis des Diensteanbieters gegen\u00fcber dem B\u00fcrger und dem nPA-Chip und gibt Auskunft \u00fcber Namen und Sitz des Anbieters, den Zweck der Anwendung und die daf\u00fcr ben\u00f6tigten Daten.<\/p> <p>media transfer AG stellt zusammen mit dem mtG-eID Server eine Client-Bibliothek zur einfachen Anbindung sowie Installations-, Schulungs- und Supportleistungen bereit. Au\u00dferdem ber\u00e4t und unterst\u00fctzt mtG beim Einsatz und der Integration des neuen Personalausweises in eCommerce- und eGovernment-Anwendungen und erm\u00f6glicht Diensteanbietern One-Stop-Shopping aus einer Hand.<\/p> <p>Technischer Kontakt:<br \/> G\u00fcnter Hirschmann, 06151-8193-29, ghirschmann@mtg.de, <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.mtg.de\"  >www.mtg.de<\/a><\/p> <p>Dolivostra\u00dfe 11<br \/> D-64293 Darmstadt<\/p> <p>456 Worte, 3162 Zeichen<\/p> <p>\u00dcber media transfer AG<br \/> media transfer (mtG) entwickelt und vermarktet seit 1995 Sicherheitstechnologie und Multimedia-Anwendungen. Der Spezialist f\u00fcr Public Key Infrastructure (PKI) und Trust-Center-Produkte bietet neben dem mtG-eID Server eine Plattform f\u00fcr Certification Authority (mtG-CA) f\u00fcr Unternehmen und Beh\u00f6rden an. mtG-CA wird von der Bundesrepublik Deutschland als Root Instanz f\u00fcr die PKI Systeme von elektronischem Reisepass, neuem Personalausweis und Verwaltungs-PKI betrieben.<\/p>","protected":false},"excerpt":{"rendered":"<p>mtG demonstrierte auf der IT-Sicherheitsmesse in N\u00fcrnberg den elektronischen Identit\u00e4tsserver (mtG-eID) f\u00fcr sicheren eCommerce und eGovernment N\u00fcrnberg\/Darmstadt, 2. November 2010.- Bei seinem Messerundgang auf der it-sa 2010 informierte sich Franz Josef Pschierer, Staatssekret\u00e4r im bayerischen Finanzministerium, bei media transfer AG (mtG) \u00fcber den neuen Personalausweis (nPA) der Bundesrepublik Deutschland. Der Security-Spezialist mtG hat den elektronischen<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11310","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/11310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=11310"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/11310\/revisions"}],"predecessor-version":[{"id":276851,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/11310\/revisions\/276851"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=11310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=11310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=11310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}