{"id":11685,"date":"2010-11-17T11:20:29","date_gmt":"2010-11-17T10:20:29","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=11685"},"modified":"2010-11-17T11:20:29","modified_gmt":"2010-11-17T10:20:29","slug":"snack-ruesselspringer","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/snack-ruesselspringer-1011685\/","title":{"rendered":"Ungew\u00f6hnliche Best\u00e4ubertiere"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/images.springer.com\/cda\/content\/image\/cda_displayimage.jpg?SGWID=0-0-16-835469-0\" alt=\"\" width=\"95\" height=\"127\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Erstmals wird nachgewiesen, dass R\u00fcsselspringer sich am Nektar von Lilien laben und diese best\u00e4uben<\/p> <p>New York \/ Heidelberg, 16. November 2010<\/p> <p>Langschnauzige R\u00fcsselspringer lieben klebrige Leckereien. Dieses Fazit hat Dr. Petra Wester von der University Stellenbosch in S\u00fcdafrika aus ihren Untersuchungen gezogen, in denen sie erstmals belegen konnte, dass der R\u00fcsselspringer, Elephantulus edwardii, den Nektar aus Bl\u00fcten saugt und damit Pagoda Lilien best\u00e4ubt. Ihre Studie wird in der Springer-Fachzeitschrift Naturwissenschaften \u2013 The Science of Nature ver\u00f6ffentlicht.<\/p> <p><!--more-->Dr. Wester untersuchte das Verhalten von Tieren im n\u00f6rdlichen Gebiet von Cederberg in S\u00fcdafrika, wo die Pagoda Lilienart Whiteheadia bifolia (Hyacinthaceae) in schattigen Felsspalten und -h\u00f6hlen w\u00e4chst. Vier N\u00e4chte lang stellte sie Tierfallen in der N\u00e4he der Lilienpflanzen auf, in denen K\u00f6der aus Erdnussbutter und Haferflocken die Tiere anlocken sollten. Tags darauf wurden die Exkremente aus den Tierfallen von Dr. Wester eingesammelt. Zwei R\u00fcsselspringer wurden gefangen und in Glasterrarien mit bl\u00fchenden Lilienpflanzen ausgesetzt, in denen Dr. Wester ihr Essverhalten beobachtete.<\/p> <p>Die gefangenen R\u00fcsselspringer haben innerhalb von vier Tagen die Bl\u00fcten \u00fcber 50 Mal besucht. Sie gingen dabei von einer Bl\u00fctentraube zur anderen. Mit ihren biegsamen Nasen drangen sie in die Staubgef\u00e4\u00dfe vor und leckten den Nektar zwischen den Fruchtknoten und den Staubgef\u00e4\u00dfen mit ihren langen schmalen Zungen ab. Dabei ber\u00fchrten sie die Pollens\u00e4cke und best\u00e4ubten ihre lange Nase mit Bl\u00fctenpollen. Auch die Bl\u00fctennarben wurden von den Tieren ber\u00fchrt.<\/p> <p>Die R\u00fcsselspringer labten sich an dem Nektar, ohne dabei die Pollen direkt zu sich zu nehmen oder die Bl\u00fcten zu essen, zu besch\u00e4digen oder gar zu zerst\u00f6ren. Interessanterweise zogen die Tiere den Nektar anderen Nahrungsmitteln wie Erdnussbutter mit Haferflocken und \u00c4pfeln oder auch Wasser vor. Dr. Wester fand zudem heraus, dass in den Exkrementproben der R\u00fcsselspringer Pollen der Pagoda Lilie enthalten waren. Dies ist m\u00f6glicherweise eher auf die Fellpflege nach den Bl\u00fctenbesuchen als auf eine tats\u00e4chliche Pollenaufnahme zur\u00fcckzuf\u00fchren.<\/p> <p>R\u00fcsselspringer geh\u00f6ren zusammen mit Nagetieren, Primaten und Beuteltieren zu einer eher ungew\u00f6hnlichen Gruppe von Best\u00e4ubertieren, die als &#8217;nichtfliegende S\u00e4ugetiere&#8216; bekannt sind, um sie von den eher verbreiteten Flederm\u00e4usen zu unterscheiden. Abgesehen von ihrer langen Nase \u00e4hneln R\u00fcsselspringer den M\u00e4usen, geh\u00f6ren jedoch nicht zu den Nagetieren. Sie geh\u00f6ren zur Ordnung der Elefantenspitzm\u00e4use (Macroscelidea), zu denen auch Erdferkel, Tenreks, Goldmullen, Schliefer, Seek\u00fche und Elefanten z\u00e4hlen.<\/p> <p>Dr. Wester schlussfolgert: \u201cEs liegen kaum Informationen \u00fcber R\u00fcsselspringer als Best\u00e4ubertiere vor. Mit dieser Studie wird erstmalig nachgewiesen, dass der Elephantulus edwardii Bl\u00fcten wegen des Nektars besucht und sie folglich auch best\u00e4ubt. Es gilt als sehr wahrscheinlich, dass noch weitere Spezies von R\u00fcsselspringern Best\u00e4ubertiere sein k\u00f6nnten.&#8220;<\/p> <p>Quelle<br \/> Wester P (2010). Sticky snack for sengis \u2013 The Cape rock elephant-shrew, Elephantulus edwardii (Macroscelidea) as a pollinator of the Pagoda lily, Whiteheadia bifolia (Hyacinthaceae). Naturwissenschaften; DOI 10.1007\/s00114-010-0723-6<\/p> <p>Der vollst\u00e4ndige Artikel sowie Fotos stehen Journalisten auf Anfrage zur Verf\u00fcgung.<br \/> Kontakt: Joan Robinson, <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.springer.com\/?SGWID=1-102-0-0-0\"  >Springer<\/a>, Te.l +49-6221-487-8130, joan.robinson@springer.com<\/p> <p>Springer-Verlag GmbH, Heidelberg, Zweigniederlassung der Springer-Verlag GmbH, BerlinTiergartenstrasse 17D-69121 Heidelberg<\/p>","protected":false},"excerpt":{"rendered":"<p>Erstmals wird nachgewiesen, dass R\u00fcsselspringer sich am Nektar von Lilien laben und diese best\u00e4uben New York \/ Heidelberg, 16. November 2010 Langschnauzige R\u00fcsselspringer lieben klebrige Leckereien. Dieses Fazit hat Dr. Petra Wester von der University Stellenbosch in S\u00fcdafrika aus ihren Untersuchungen gezogen, in denen sie erstmals belegen konnte, dass der R\u00fcsselspringer, Elephantulus edwardii, den Nektar<\/p>\n","protected":false},"author":291,"featured_media":198616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8808],"tags":[],"class_list":["post-11685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenschaft"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/11685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=11685"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/11685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198616"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=11685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=11685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=11685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}