{"id":12102,"date":"2010-11-25T12:51:01","date_gmt":"2010-11-25T11:51:01","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=12102"},"modified":"2017-10-13T11:08:37","modified_gmt":"2017-10-13T10:08:37","slug":"wellness-deutschland-angebote","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wellness-deutschland-angebote-1012102\/","title":{"rendered":"Wellness genie\u00dfen in Bad Aibling"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12105\" title=\"Wellness- und Sporthotel St. Georg.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/12102\/Wellness- und Sporthotel St. Georg-300x267.jpg\" alt=\"\" width=\"115\" height=\"102\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/12102\/Wellness-%20und%20Sporthotel%20St.%20Georg-300x267.jpg 300w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/12102\/Wellness-%20und%20Sporthotel%20St.%20Georg.jpg 320w\" sizes=\"auto, (max-width: 115px) 100vw, 115px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Wellness ist schon seit Jahren ein absoluter Trend, viele waren schon einmal im Wellnessurlaub, andere m\u00f6chten diese sehr gerne, wissen aber noch nicht so richtig, was dabei alles passiert, und wie so eine Wellnessreise abl\u00e4uft. Daher bieten immer mehr Wellnesshotels sogenannte Kennenlernpakete an, bei denen man auch innerhalb von ein paar Tagen ganz unterschiedliche Wellnessanwendungen kennenlernen kann. Gerade die abwechslungsreiche Wellness in Deutschland bietet den G\u00e4sten eine gro\u00dfe Auswahl.<br \/> Oberbayern beispielsweise verf\u00fcgt \u00fcber eine absolute Bilderbuchlandschaft, sch\u00f6ne Seen und Berge und traditionelle Trachten machen das Ambiente dieser Region aus, das so absolut unverwechselbar ist. <!--more-->Bad Aibling liegt im Wendelsteingebiet, und es ist auch das erste und zugleich \u00e4lteste Moorbad in Bayern.<br \/> In Bad Aibling, und zwar nur wenige Gehminuten vom Ortskern entfernt, befindet sich das Wellness- und Sporthotel St.Georg, und zwar in einer ruhigen Hanglage.<br \/> Das Haus ist ausgestattet mit einem Nichtraucher-Restaurant mit einem Wintergarten, der St. Georg-Stube, der Bauernstube, einem Bistro, der Hotelbase und einem Lift. Das Haus bietet seinen G\u00e4sten 220 Zimmer an, die alle \u00fcber Bad oder Dusche und WC verf\u00fcgen. Es gibt auch einen F\u00f6hn auf den Zimmern, ebenfalls vorhanden ist SAT-TV, ein Radiowecker, eine Minibar, WLAN und ein Durchwahltelefon. In diesem Hause gibt es sowohl die \u00fcblichen Einzel- und Doppelzimmer als auch sch\u00f6ne Familienzimmer. Zus\u00e4tzlich verf\u00fcgt das Haus auch \u00fcber Allergiker-, Nichtraucher- und auch behindertengerechte Zimmer.<br \/> Die Verpflegung erfolgt in diesem Hause mit regionalen und auch internationalen Speisen, auch vegetarische Kost, Reduktionskost und glutenfreie Kost gibt es im Angebot auf Anfrage. Es gibt ein Fr\u00fchst\u00fccksbuffet mit Bio-Ecke, bei Buchung einer Halbpension gibt es abends ein t\u00e4glich wechselndes kalt\/warmes Buffet.<br \/> Das Wellness- und Sporthotel St.Georg bietet f\u00fcr alle, die Wellness erst einmal ausprobieren wollen, die Sonderkennenlernaktion \u201eWellness pur\u201c. In diesem Angebot sind je nach Wahl drei, vier oder auch sieben \u00dcbernachtungen inklusive. Es geh\u00f6rt eine Halbpension dazu, des weiteren gibt es im Paket eine R\u00fccken-\/Nackenmassage, eine Fu\u00dfreflexzonenmassage, eine Moorpackung, ein Wohlf\u00fchlbad und eine Bewegungstherapie und Bewegungsbad in der Gruppe. Zudem kann die Wellnesslandschaft frei genutzt werden, dasselbe gilt auch f\u00fcr die Bogenschie\u00dfanlage. Die Wellnesslandschaft umfasst ein Hallenbad, eine Trocken-, Bio- und auch Dampfsauna, Solarium gegen Geb\u00fchr, einen Fitnessraum mit Personal Trainer und auch einen Kosmetiksalon. W\u00e4hrend der Behandlungen werden Kinder hier betreut.  Je nach Angebot kann man auch am Sportprogramm teilnehmen, hier gibt es beispielsweise Aqua-Aerobic, Morgengymnastik oder auch Jogging im Angebot. F\u00fcr den Eintritt in die Therme Bad Aibling gibt es eine Erm\u00e4\u00dfigung.<br \/> Im Wellnessbereich gibt es Moorpackungen, Massagen, Lymphdrainagen, Fu\u00dfreflexzonentherapien, Ayurveda-Behandlungen und auch Shiatsu-Massagen im Angebot. Wem die Wellnessangebote dann so gut gefallen haben, dass man gerne mehr erleben m\u00f6chte, der kann nat\u00fcrlich auch noch unterschiedliche Wellnessbehandlungen gegen Geb\u00fchr hinzubuchen, sehr beliebt ist hier immer die hawaiianische Ganzk\u00f6rpermassage Lomi Lomi Nui.<br \/> Weitere Informationen zu diesem Reiseangebot gibt es gleich online unter www.kurenundwellness.tv\/ausgewaehltes-angebot\/reisen\/deutschland-wellness-und-sporthotel-st.-georg\/ oder unter der kostenlosen Rufnummer 0800 \u2013 40 40 60 60.<\/p> <p>K&amp;W Reisen GmbH<br \/> Beckumer Str. 34<br \/> 59229 Ahlen<br \/> Tel: 0800 \u2013 40 40 60 60<br \/> web: www.kurenundwellness.tv\/wellnessreisen\/<br \/> email: service@kurenundwellness.tv<\/p>","protected":false},"excerpt":{"rendered":"<p>Wellness ist schon seit Jahren ein absoluter Trend, viele waren schon einmal im Wellnessurlaub, andere m\u00f6chten diese sehr gerne, wissen aber noch nicht so richtig, was dabei alles passiert, und wie so eine Wellnessreise abl\u00e4uft. Daher bieten immer mehr Wellnesshotels sogenannte Kennenlernpakete an, bei denen man auch innerhalb von ein paar Tagen ganz unterschiedliche Wellnessanwendungen<\/p>\n","protected":false},"author":291,"featured_media":198603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8804],"tags":[],"class_list":["post-12102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reisen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/12102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=12102"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/12102\/revisions"}],"predecessor-version":[{"id":269251,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/12102\/revisions\/269251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198603"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=12102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=12102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=12102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}