{"id":128,"date":"2008-03-25T10:48:50","date_gmt":"2008-03-25T09:48:50","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/unternehmerborse-ost-west\/"},"modified":"2010-07-26T14:23:19","modified_gmt":"2010-07-26T13:23:19","slug":"unternehmerborse-ost-west","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/unternehmerborse-ost-west-10128\/","title":{"rendered":"Unternehmerb\u00f6rse OST-WEST"},"content":{"rendered":"<p>Internationales Unternehmertreffen am 17. und 18. April 2008<\/p> <p>Die n\u00e4chste Internationale Unternehmerb\u00f6rse OST-WEST findet am<br \/> 17. und 18. April 2008 in Torgau (Sachsen) im Rathaus (Markt), 1. Etage statt.<\/p> <p>Zielstellung der Unternehmerb\u00f6rse in Torgau:<br \/> &#8211;\u00a0\u00a0\u00a0 osteurop\u00e4ische Unternehmer der neuen EU-L\u00e4nder erhalten die M\u00f6glichkeit, das Potenzial des eigenen Betriebes vorzustellen.<!--more--><br \/> &#8211;\u00a0\u00a0\u00a0 den teilnehmenden Firmen wird ein Forum mit dem Schwerpunkt \u201eindividuelle Gespr\u00e4che \u201c der Firmenvertreter zum Zwecke der Information und Kontaktanbahnung geboten.<br \/> &#8211;\u00a0\u00a0\u00a0 M\u00f6glichkeiten der Gesch\u00e4ftst\u00e4tigkeit deutscher Firmen auf dem Ost-Markt sind \u00fcber Kontaktgespr\u00e4che einzuholen; die Zusammenarbeit ist zu planen.<\/p> <p>23. Internationale Unternehmerb\u00f6rse OST-WEST<\/p> <p>Das Unternehmertreffen findet in Torgau (Sachsen) im Rathaus (Markt), 1. Etage, am 17. und am 18. April 2008 in den B\u00fcror\u00e4umen des OST-WEST Vereins, Schlo\u00dfstra\u00dfe 19 statt.<\/p> <p>Branchen:<br \/> 1.\u00a0\u00a0\u00a0 Metallbearbeitung; Stahlhandel; sowie andere Metalle und Legierungen; Stahlbau und Montage;<br \/> Maschinen- und Anlagenbau und Verfahrenstechnik (besonders Luft- und Wassertechnik); Spedition.<\/p> <p>2.\u00a0\u00a0\u00a0 Elektronik; Automatisierungstechnik und Kontrollsysteme (Messen und Regeln), Programmierung; Umwelttechnik; alternative Energien: Solar-, Wind- und Bioenergie; Apparate und Montage.<\/p> <p>3.\u00a0\u00a0\u00a0 Chemie- und Pharmazie-Industrie und Distribution; Glas-, Kunststoff-, Holz- und Bauindustrie.<\/p> <p>4.\u00a0\u00a0\u00a0 Consulting; Unternehmensberatung; Ingenieurb\u00fcros; Werbung; Bildung; Messe; Banken; Verwaltung; Versicherung; Recht.<\/p> <p>Wir erwarten Teilnehmer aus folgenden L\u00e4ndern: Deutschland, Niederlande, Rum\u00e4nien, Polen, Tschechien, Slowakei, Slowenien, Bulgarien, Baltikum, Ukraine, Ru\u00dfland.<\/p> <p>Kontakt:<br \/> OST &#8211; WEST Verein<br \/> Schlo\u00dfstra\u00dfe 19<br \/> D-04860 Torgau<br \/> Tel.\/Fax: (03421) 71 56 47<br \/> e-mail: ostwest@online.de<\/p> <p>Anmeldeschlu\u00df: 3. April 2008<\/p> <p>Die Teilnahme an der B\u00f6rse ist kostenpflichtig: 100,00 EURO pro Person.<br \/> In der Teilnahmegeb\u00fchr sind Tagungsmaterialien, Getr\u00e4nke und ein Imbiss enthalten. Reise und Aufenthaltskosten tr\u00e4gt jeder selbst.<br \/> Es besteht zus\u00e4tzlich die M\u00f6glichkeit, auf einer separaten Ausstellungsfl\u00e4che die eigene Produktpalette sowie Prospekte vorzustellen.<br \/> Wenn erw\u00fcnscht, kann der Buchungsservice f\u00fcr das Hotel \u00fcbernommen werden, ohne dass Mehrkosten f\u00fcr den Teilnehmer entstehen.<\/p> <p>Sehr geehrte Damen und Herren,<br \/> bei Fragen wenden Sie sich direkt an uns.<\/p> <p>Mit freundlichen Gr\u00fc\u00dfen<\/p> <p>Dr. Uwe Niedersen<\/p>","protected":false},"excerpt":{"rendered":"<p>Internationales Unternehmertreffen am 17. und 18. April 2008 Die n\u00e4chste Internationale Unternehmerb\u00f6rse OST-WEST findet am 17. und 18. April 2008 in Torgau (Sachsen) im Rathaus (Markt), 1. Etage statt. Zielstellung der Unternehmerb\u00f6rse in Torgau: &#8211;\u00a0\u00a0\u00a0 osteurop\u00e4ische Unternehmer der neuen EU-L\u00e4nder erhalten die M\u00f6glichkeit, das Potenzial des eigenen Betriebes vorzustellen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,22],"tags":[],"class_list":["post-128","post","type-post","status-publish","format-standard","hentry","category-business-handel-gewerbe","category-industrie-produktion"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/128\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}