{"id":13027,"date":"2011-01-18T10:38:23","date_gmt":"2011-01-18T09:38:23","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13027"},"modified":"2011-01-18T10:38:23","modified_gmt":"2011-01-18T09:38:23","slug":"pressestelle-outsourcing","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/pressestelle-outsourcing-1013027\/","title":{"rendered":"Kontinuierliche PR-Betreuung mit Full-Service"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13030\" title=\"pr4you_logo_jpg_200.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13027\/pr4you_logo_jpg_200.jpg\" alt=\"\" width=\"149\" height=\"55\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Die PR-Agentur PR4YOU \u00fcbernimmt als externe Presseagentur die Kommunikation und PR f\u00fcr Unternehmen und Marken.<\/p> <p>Die in Berlin ans\u00e4ssige PR-Agentur PR4YOU unterst\u00fctzt Unternehmen und Marken auch als externe Pressestelle und zeichnet f\u00fcr die Pressearbeit, Medienarbeit und \u00d6ffentlichkeitsarbeit sowie Online-PR verantwortlich.<\/p> <p>\u201eWir bieten unseren Kunden die vollst\u00e4ndige Auslagerung ihrer PR-Arbeit zum monatlichen Festpreis an und vertreten sie als externe Pressestelle und Presseagentur gegen\u00fcber Medien und anderen Interessenten. <!--more-->Unsere kontinuierliche PR-Betreuung mit Full-Service reicht dabei von der Erstellung und Versendung aktueller Pressemitteilungen, \u00fcber Online-PR, Aufbau und Pflege der Presseverteiler, regelm\u00e4\u00dfiger Medienkontakte, Vertretung in allen wichtigen \u00f6ffentlichkeitsrelevanten Angelegenheiten, bis hin zur Medienbeobachtung und Erfolgskontrolle zu kalkulierbaren und fairen Preisen. Das spart nicht nur Zeit, sondern auch unn\u00f6tige Kosten\u201c, erl\u00e4utert Holger Ballwanz, Inhaber und Gesch\u00e4ftsf\u00fchrer der PR-Agentur PR4YOU.<\/p> <p>Zu den Dienstleistungen der PR-Agentur PR4YOU als externe Pressestelle z\u00e4hlen:<\/p> <p>&#8211; PR und Kommunikation: PR-Betreuung und PR-Beratung<br \/> &#8211; Klassische Pressearbeit, Medienarbeit und \u00d6ffentlichkeitsarbeit<br \/> &#8211; Online-PR<br \/> &#8211; Themen-Management, Recherchen, Texterstellung und Redaktionsleitung<br \/> &#8211; Erstellung aktueller Pressemitteilungen nach journalistischen Regeln<br \/> &#8211; Erstellung von journalistischen Texten<br \/> &#8211; Erstellung von Hintergrundinformationen<br \/> &#8211; Entwicklung und Produktion von Pressemappen (Online und Print)<br \/> &#8211; Bildredaktion und -beschaffung<br \/> &#8211; \u00dcbersetzungen der Publikationen und Pressetexte in \u00fcber 40 Sprachen<br \/> &#8211; Erstellung effizienter Medienverteiler und Pflege der Medienverteiler<br \/> &#8211; Presseversand der Pressemeldungen via personalisierter E-Mail, Post oder Fax<br \/> &#8211; Kontaktpflege mit relevanten Journalisten<br \/> &#8211; Bearbeitung von Anfragen der Redaktionen (Pressestellenfunktion)<br \/> &#8211; Organisation von Interviews, Unternehmensbesuchen und Pressegespr\u00e4chen<br \/> &#8211; Erfolgskontrolle (Presseclipping, Erstellung des Pressespiegels, Evaluation)<\/p> <p>Weitere Informationen \u00fcber das Leistungsangebot der PR-Agentur PR4YOU sind im Internet unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pr4you.de\"  >http:\/\/www.pr4you.de<\/a> erh\u00e4ltlich.<\/p> <p>Verwendung honorarfrei, Beleghinweis erbeten<br \/> 265 W\u00f6rter, 2.265 Zeichen mit Leerzeichen<\/p> <p>Ansprechpartner f\u00fcr R\u00fcckfragen zu dieser Pressemitteilung:<\/p> <p>PR-Agentur PR4YOU<\/p> <p>Ansprechpartner: Herr Holger Ballwanz, Herr Marko Homann<\/p> <p>PR-Agentur PR4YOU<br \/> Schonensche Stra\u00dfe 43<br \/> D-13189 Berlin<\/p> <p>Telefon: +49 (0) 30 43 73 43 43<br \/> Fax: +49 (0) 30 44 67 73 99<br \/> E-Mail: presse@pr4you.de<br \/> Internet: http:\/\/www.pr4you.de<\/p> <p>\u00dcber die PR-Agentur PR4YOU:<\/p> <p>Die in Berlin ans\u00e4ssige PR-Agentur PR4YOU ist eine Full Service Agentur f\u00fcr Public Relations und Kommunikation. PR4YOU betreut seit 2001 Unternehmen, Institutionen und Personen lokal, regional, national und international in den Bereichen Public Relations, klassische Presse- und \u00d6ffentlichkeitsarbeit, Online-PR, Suchmaschinen-PR (SEO-PR), Social Media Relations, Mediaberatung, Mediaplanung, Werbung und Werbeschaltung, Corporate Communications, Corporate Publishing und Corporate Design.<\/p> <p>Das Angebot reicht vom strategischen PR-Consulting \u00fcber die operative Umsetzung bis hin zur kontinuierlichen PR-Betreuung mit variablen und kundenspezifischen Honorarmodellen. Dazu z\u00e4hlen PR-Beratung und PR-Betreuung, aktive Pressearbeit, Medienarbeit und \u00d6ffentlichkeitsarbeit, Marken-PR und Produkt-PR, Unternehmens-PR, Event-PR, Messe-PR, Personal-PR, Personality-PR, Corporate Social Responsibility PR, Krisen-PR, Online-PR, Suchmaschinen-PR (SEO-PR), Social Media Relations (Social Media PR, PR 2.0), Radio-PR und Radiowerbung, TV-PR und TV-Sponsoring, Mediaplanung, Werbeschaltung sowie Gestaltung und Herstellung von Kommunikationsmitteln.<\/p> <p>PR4YOU verf\u00fcgt \u00fcber eine eigene Pressedatenbank mit redaktionellen Ansprechpartnern zahlreicher Ressorts (f\u00fcr Deutschland sind alleine \u00fcber 30.000 Datens\u00e4tze verf\u00fcgbar) sowie ein eigenes Presseversandtool. Damit ist die PR-Agentur unabh\u00e4ngig von Datenh\u00e4ndlern und E-Mail-Versanddiensten.<\/p> <p>Das Team um den gepr\u00fcften PR-Berater (DAPR) Holger Ballwanz besteht aus Public Relations Experten (PR-Berater und PR-Redakteure, Mediaberater und Mediaplaner, Grafiker und Mediendesigner sowie Fotografen) mit umfassender Berufspraxis in Public Relations, Journalismus, Marketing, Mediaplanung und Werbung. Zu den aktuellen Kunden der Agentur z\u00e4hlen beispielsweise: Mindfactory AG, optivel AG, Blutspendedienst der Landesverb\u00e4nde des DRK Niedersachsen, Sachsen-Anhalt, Th\u00fcringen, Oldenburg und Bremen gGmbH, GEORG JENSEN A\/S, Bundesverband Legasthenie und Dyskalkulie, Yogafestival Berlin, Molaris GmbH (Der Lackdoktor), micropayment\u2122 GmbH, fefa Reisen GmbH, ODS &#8211; Office Data Service GmbH, SPEED-FIT GmbH, Brainworks GmbH, Fitnesshotline GmbH, deutsche medienakademie GmbH, scandtrack touristik GmbH, scake food GmbH, Products-Up GmbH, ps printsolution GmbH, myprinting GmbH, RR Software GmbH, Lieferservice.de und Lieferservice.at des niederl\u00e4ndischen Unternehmens Takeaway.com sowie das 4-Sterne-Superior Upstalsboom Hotel Ostseestrand.<\/p> <p>Weitere Informationen \u00fcber die PR-Agentur PR4YOU sind im Internet unter http:\/\/www.pr4you.de abrufbar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die PR-Agentur PR4YOU \u00fcbernimmt als externe Presseagentur die Kommunikation und PR f\u00fcr Unternehmen und Marken. Die in Berlin ans\u00e4ssige PR-Agentur PR4YOU unterst\u00fctzt Unternehmen und Marken auch als externe Pressestelle und zeichnet f\u00fcr die Pressearbeit, Medienarbeit und \u00d6ffentlichkeitsarbeit sowie Online-PR verantwortlich. \u201eWir bieten unseren Kunden die vollst\u00e4ndige Auslagerung ihrer PR-Arbeit zum monatlichen Festpreis an und vertreten<\/p>\n","protected":false},"author":291,"featured_media":13030,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-13027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13027"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/13030"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}