{"id":13118,"date":"2011-01-21T10:11:46","date_gmt":"2011-01-21T09:11:46","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13118"},"modified":"2011-01-21T10:11:46","modified_gmt":"2011-01-21T09:11:46","slug":"druckmaschine-welt","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/druckmaschine-welt-1013118\/","title":{"rendered":"Gr\u00f6\u00dfte Druckmaschine der Welt in Betrieb genommen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13121\" title=\"print24_logo_200_w.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13118\/print24_logo_200_w.jpg\" alt=\"\" width=\"108\" height=\"108\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13118\/print24_logo_200_w.jpg 200w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13118\/print24_logo_200_w-150x150.jpg 150w\" sizes=\"auto, (max-width: 108px) 100vw, 108px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>&#8211; In Zusammenarbeit mit der Heidelberger Druckmaschinen AG hat print24 als weltweit erstes Unternehmen die gr\u00f6\u00dfte Druckmaschine der Welt in Betrieb genommen.<\/p> <p>&#8211; Die Onlinedruckerei konnte 2010 ein Wachstum von 50% erzielen. Als weltweit operierendes Unternehmen und europ\u00e4ischer Marktf\u00fchrer im Onlinedruck erzielte print24 im Jahr 2010 ein Bestellwachstum von 50%.Mit der global erst- und einmaligen Inbetriebnahme der gr\u00f6\u00dften Druckmaschine der Welt schenkt der Weltmarktf\u00fchrer im Druckmaschinenbau \u2013 Heidelberger Druckmaschinen AG \u2013 print24 nun das Vertrauen, in neue Dimensionen des Druckens vorzusto\u00dfen.<\/p> <p><!--more-->Auch in allen weiteren Bereichen steigert sich print24, um seinen Kunden Flyer, Plakate, Postkarten, Prospekte, Visitenkarten u.v.m. mit h\u00f6chster Qualit\u00e4t, schnellster Lieferzeit und niedrigsten Preisen liefern zu k\u00f6nnen. So stieg der Personalbestand im Vergleich zum Jahr 2009 von 400 auf \u00fcber 500 Mitarbeiter an. Und auch Anfang 2011 sind bereits \u00fcber 100 zus\u00e4tzliche Stellen zu besetzen.<\/p> <p>Weitere Informationen \u00fcber print24 sind unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.print24.com\"  >http:\/\/www.print24.com<\/a> verf\u00fcgbar.<\/p> <p>Verwendung honorarfrei, Beleghinweis erbeten<br \/> 158 W\u00f6rter, 1.164 Zeichen mit Leerzeichen<\/p> <p>Weiteres Pressematerial zu dieser Pressemitteilung:<\/p> <p>Sie k\u00f6nnen im Online-Pressefach schnell und einfach weiteres Bild- und Textmaterial zur kostenfreien Verwendung downloaden:<\/p> <p>http:\/\/www.pr4you.de\/pressefaecher\/print24<\/p> <p>Ansprechpartner f\u00fcr R\u00fcckfragen zu dieser Pressemitteilung:<\/p> <p>(1) print24 GmbH<\/p> <p>Ansprechpartner: David Gornickel<\/p> <p>print24 GmbH<br \/> Friedrich- List- Str. 3<br \/> D-01445 Radebeul<\/p> <p>Telefon: +49 (0) 351 27 22 53 86<br \/> Fax: +49 (0) 351 65 63 35 00<br \/> E-Mail: david.gornickel@unitedprint.com<br \/> Internet: http:\/\/www.print24.com, http:\/\/www.unitedprint.com<\/p> <p>(2) PR-Agentur PR4YOU<\/p> <p>Ansprechpartner: Marko Homann, Holger Ballwanz<\/p> <p>PR-Agentur PR4YOU<br \/> Schonensche Stra\u00dfe 43<br \/> D-13189 Berlin<\/p> <p>Telefon: +49 (0) 30 43 73 43 43<br \/> Fax: +49 (0) 30 44 67 73 99<br \/> E-Mail: presse@pr4you.de<br \/> Internet: http:\/\/www.pr4you.de<\/p> <p>\u00dcber print24<\/p> <p>print24 ist ein Unternehmen der unitedprint.com SE &#8211; Europas Marktf\u00fchrer im Bereich web-to-print. \u00dcber 500 Mitarbeiter arbeiten 24 Stunden rund um die Uhr mit modernster Technologie auf \u00fcber 10.000 m\u00b2 Produktionsfl\u00e4che. Unsere Standorte befinden sich weltweit in 23 L\u00e4ndern &#8211; unter anderem in den asiatischen, nordamerikanischen, lateinamerikanischen und europ\u00e4ischen Metropolen Hong Kong, Seattle, Calgary, S\u00e3o Paulo, Berlin, London, Paris, Mailand, Madrid, Wien, Z\u00fcrich, Amsterdam, Br\u00fcssel, Dublin, Luxemburg, Warschau, Prag, Kopenhagen, Oslo, Stockholm, Helsinki, Lissabon und Athen.<\/p> <p>Weitere Informationen \u00fcber print24 sowie zu den Produkten und Dienstleistungen sind im Internet unter http:\/\/www.print24.com abrufbar.<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; In Zusammenarbeit mit der Heidelberger Druckmaschinen AG hat print24 als weltweit erstes Unternehmen die gr\u00f6\u00dfte Druckmaschine der Welt in Betrieb genommen. &#8211; Die Onlinedruckerei konnte 2010 ein Wachstum von 50% erzielen. Als weltweit operierendes Unternehmen und europ\u00e4ischer Marktf\u00fchrer im Onlinedruck erzielte print24 im Jahr 2010 ein Bestellwachstum von 50%.Mit der global erst- und einmaligen<\/p>\n","protected":false},"author":291,"featured_media":13121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-13118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13118"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/13121"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}