{"id":13155,"date":"2011-01-24T11:45:25","date_gmt":"2011-01-24T10:45:25","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13155"},"modified":"2013-04-08T16:24:17","modified_gmt":"2013-04-08T15:24:17","slug":"global-aktiv-lokal","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/global-aktiv-lokal-1013155\/","title":{"rendered":"Spielerisch den Einstieg ins Arbeitsleben erleichtern"},"content":{"rendered":"<table style=\"float: left; height: 90px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"141\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13158\" title=\"Emma interviewing-web.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13155\/Emma interviewing-web.jpg\" alt=\"\" width=\"141\" height=\"93\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Wolfestone Translation hat Kunden und Mitarbeiter in der ganzen Welt und B\u00fcros in verschiedenen L\u00e4ndern, darunter auch in der Bundeshauptstadt Berlin (http:\/\/www.wolfestonetranslation.de). Seine Wurzeln und seinen Hauptsitz aber hat das \u00dcbersetzungsunternehmen in der zweitgr\u00f6\u00dften walisischen Stadt Swansea. Seit neuestem beteiligt sich Wolfestone Translation an einer lokalen Initiative, mit der das staatlich gef\u00f6rderte Berufsberatungszentrum Careers Wales West Sch\u00fcler und Sch\u00fclerinnen den Einstieg ins Arbeitsleben erleichtert.<br \/> <!--more-->Wolfestone bietet interessierten Jugendlichen schon seit einiger Zeit regelm\u00e4\u00dfig Gelegenheit, im Rahmen von Schnupperwochen den Alltag eines international erfolgreichen Sprachdienstleisters kennen zu lernen. Nun besuchen Wolfestone-Mitarbeiter Schulen in Swansea, wo sie Sch\u00fcler und Sch\u00fclerinnen durch Rollenspiele auf Vorstellungsgespr\u00e4che bei Firmen bzw. Hochschulen und Universit\u00e4ten vorbereiten. Wolfestone-Betriebsleiterin Emma Roome freute sich besonders \u00fcber die Einladung, in ihrer ehemaligen Schule die Rolle der Personalchefin zu \u00fcbernehmen: \u201eDies ist eine wunderbare Chance f\u00fcr Wolfestone, der Stadt f\u00fcr ihre gro\u00dfartige Unterst\u00fctzung w\u00e4hrend der vergangenen vier Jahre zu danken, in denen Wolfestone sich als erfolgreiches Unternehmen etabliert hat. Und auf einer pers\u00f6nlichen Ebene, da ich selber in Swansea aufgewachsen und hier zur Schule gegangen bin, freut es mich riesig, etwas f\u00fcr meine alte Schule tun zu k\u00f6nnen. Denn w\u00e4hrend meiner eigenen Schulzeit h\u00e4tte ich eine solche Aktion ungeheuer hilfreich gefunden.\u201c<br \/> Im neuen Jahr will Wolfestone sein Engagement vor Ort noch verst\u00e4rken und m\u00f6glichst viele Mitarbeiter an Aktionen und Initiativen zum Nutzen der Allgemeinheit beteiligen. Gesch\u00e4ftsf\u00fchrerin Anna Bastek best\u00e4tigte: \u201eWolfestone legt gro\u00dfen Wert darauf, mit der hiesigen Gemeinschaft zusammenzuarbeiten und bei vielen \u00f6rtlichen Initiativen mitzumachen. Wir unterst\u00fctzen Universit\u00e4ten, Studierende, gemeinn\u00fctzige Organisationen und Sportvereine. Au\u00dferdem k\u00fcmmern wir uns um unsere Mitarbeiter und bieten ihnen eine Menge Leistungen, die f\u00fcr kleine und mittelst\u00e4ndische Unternehmen nicht unbedingt \u00fcblich sind. Ich bin stolz auf unser Firmen-Ethos und darauf, dass alle unsere Mitarbeiter dieselben Werte teilen.\u201c<br \/> Januar 2011<\/p> <p>Wolfestone Translation Deutschland<br \/> Anna Bastek<br \/> Glockenblumenweg 131a<br \/> 12357 Berlin<br \/> Tel. 0800 1814873<br \/> E-Mail: sales@wolfestonetranslation.de<br \/> http:\/\/www.wolfestonetranslation.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Wolfestone Translation hat Kunden und Mitarbeiter in der ganzen Welt und B\u00fcros in verschiedenen L\u00e4ndern, darunter auch in der Bundeshauptstadt Berlin (http:\/\/www.wolfestonetranslation.de). Seine Wurzeln und seinen Hauptsitz aber hat das \u00dcbersetzungsunternehmen in der zweitgr\u00f6\u00dften walisischen Stadt Swansea. Seit neuestem beteiligt sich Wolfestone Translation an einer lokalen Initiative, mit der das staatlich gef\u00f6rderte Berufsberatungszentrum Careers Wales<\/p>\n","protected":false},"author":291,"featured_media":13158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13155"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/13158"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}