{"id":13221,"date":"2011-01-25T18:34:54","date_gmt":"2011-01-25T17:34:54","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13221"},"modified":"2017-04-18T16:27:48","modified_gmt":"2017-04-18T15:27:48","slug":"competence-center","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/competence-center-1013221\/","title":{"rendered":"Einsatzgebiete, Nutzen und Weiterentwicklungen des PDF\/A-Formates"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>(Berlin) Besucher der CeBIT haben auch in diesem Jahr Gelegenheit, sich umfassend \u00fcber Einsatzgebiete, Nutzen und Weiterentwicklungen des PDF\/A-Formates zu informieren. Anlaufstelle daf\u00fcr ist der Messestand des PDF\/A Competence Center, der beim Kooperationspartner VOI-Verband Organisations- und Informationssysteme e.V. (Halle 3, Stand D34) zu finden ist. <!--more-->Vertreter der Mitgliedsfirmen actino, callas software, Four Pees, intarsys, LuraTech sowie Z\u00f6ller &amp; Partner zeigen die erweiterten Nutzungsm\u00f6glichkeiten des ISO-Standards f\u00fcr Langzeitarchivierung im PDF-Format, die sich durch den bevorstehenden Normteil PDF\/A-2 ergeben. Dar\u00fcber hinaus stehen sie zu Fragen rund um die wachsende Familie von PDF-Standards im DMS\/ECM-Umfeld zur Verf\u00fcgung. Das PDF\/A Competence Center ist in diesem Jahr bereits zum f\u00fcnften Mal auf der CeBIT vertreten.<\/p> <p>Seit seiner ISO-Zertifizierung 2005 hat sich PDF\/A sukzessiv als bevorzugtes Archivierungsformat etabliert. Immer mehr Unternehmen und Beh\u00f6rden nutzen die Vorteile des von der ISO standardisierten Formates und profitieren damit unter anderem von Layouttreue und Volltextdurchsuchbarkeit ihrer PDF\/A-Dokumente. In diesem Jahr steht die Ver\u00f6ffentlichung des Normteils PDF\/A-2 an. Dieser beinhaltet Funktionen, die erst mit PDF ab der Version 1.5 verf\u00fcgbar wurden. Hierzu z\u00e4hlen die Aufnahme des leistungsf\u00e4higen Kompressionsverfahrens JPEG2000, das Zusammenf\u00fcgen von PDF\/A-Dateien via Collections und die Verwendung von elektronischen Signaturen gem\u00e4\u00df dem PadES-Standard, den das European Telecommunications Standards Institute herausgegeben hat. \u201ePDF\/A existiert als ISO-Standard bereits mehr als f\u00fcnf Jahre. Seitdem hat sich PDF massiv weiterwickelt\u201c, erl\u00e4utert Olaf Dr\u00fcmmer Vorstandsvorsitzender des PDF\/A Competence Center. \u201eBasierte PDF\/A-1 auf der Version 1.4 von PDF, so dient bei PDF\/A-2 die Version 1.7 mit ihren funktionalen Erweiterungen als Grundlage. \u201eEs h\u00e4ngt alleinig von individuellen Anforderungen des Projekts ab, ob PDF\/A-1 oder PDF\/A-2 eingesetzt werden sollte.\u201c<\/p> <p>Dar\u00fcber hinaus haben sich zahlreiche weitere PDF-Standards im DMS\/ECM-Bereich entwickelt, \u00fcber die der internationale Verband ebenfalls auf der CeBIT informiert. Von besonderem Interesse d\u00fcrften hierbei vor allem PDF\/VT und PDF\/UA sein.<\/p> <p>PDF\/VT \u2013 V steht f\u00fcr variablen Datendruck und T f\u00fcr Transaktionsdruck \u2013adressiert insbesondere den Prepress- und Print-Bereich und definiert ein interoperables Datenformat f\u00fcr den hochvolumigen Druck variabler Daten.<br \/> PDF\/UA \u2013 UA steht f\u00fcr Universal Accessibility, also Barrierefreiheit \u2013hingegen soll daf\u00fcr sorgen, dass Inhalte von PDF-Dateien so strukturiert sind, dass sie mittels technischer Hilfsmittel, etwa in Form von Sprachausgabe, zug\u00e4nglich werden. Der barrierefreie Zugang zu Dokumentinhalten gewinnt gerade im amerikanischen und europ\u00e4ischen Beh\u00f6rden- und Verwaltungsbereich zunehmend an Bedeutung.<\/p> <p>Weitere Standards sind PDF\/X, PDF\/E und nicht zuletzt das PDF-Format als solches, das mit der Version 1.7 als ISO-Standard 32000-1 ratifiziert wurde. PDF\/X \u2013 X steht f\u00fcr eXchange \u2013 wurde als erster PDF-Standard bereits 2001 ver\u00f6ffentlicht und sorgt f\u00fcr einen reibungslosen Datenaustausch in der Druckindustrie. PDF\/E \u2013 E steht f\u00fcr Engineering \u2013 ist insbesondere f\u00fcr technische Dokumente relevant. Es gew\u00e4hrleistet die Zusammenf\u00fchrung komplexer Engineering-Daten in einem einzigen PDF-Dokument sowie die Unterst\u00fctzung des sicheren Austauschs von Kommentaren.<br \/> In sogenannten Special Interest Groups (SIGs), die jeweils \u00fcber eine technische und eine Marketing-Arbeitsgruppe verf\u00fcgen, engagieren sich die Mitglieder des PDF\/A Competence Center, um den Informations- und Erfahrungsaustausch rund um diese Standards voranzutreiben.<\/p> <p>Neben der thematischen Erweiterung dehnt das PDF\/A Competence Center auch seine internationalen Aktivit\u00e4ten aus. In BeNeLux, Frankreich, Italien, Gro\u00dfbritannien und den USA bestehen jetzt aktive L\u00e4ndergruppen. Dar\u00fcber hinaus sind seit dem vergangenen Jahr mit Duff Johnson und Stewart Rogers zwei Repr\u00e4sentanten aus den USA und Gro\u00dfbritannien im Vorstand vertreten, was den internationalen Anspruch des Verbandes unterstreicht. Schlie\u00dflich ist die CeBIT als international f\u00fchrende ITK-Messe ein idealer Treffpunkt f\u00fcr PDF\/A-Interessierte aus aller Welt.<\/p> <p>\u00dcber PDF\/A<\/p> <p>PDF\/A ist der ISO Standard 19005 f\u00fcr die Langzeitarchivierung im PDF-Format. Es stellt eine eingegrenzte Variante von PDF dar, ein standardisiertes Profil zur Verwendung von PDF in der Langzeitarchivierung. Der Standard schreibt detailliert vor, welche Inhalte erlaubt sind und welche nicht. Durch diese und andere Vorschriften soll eine langfristige Lesbarkeit der Dokumente garantiert sein \u2013 und zwar unabh\u00e4ngig davon, mit welcher Anwendungssoftware und auf welchem Betriebssystem sie urspr\u00fcnglich erstellt wurden. Die Vorteile von PDF\/A, wie zum Beispiel die F\u00e4higkeit zur Volltextsuche, machen es zu einem bevorzugten Archivierungsformat, das bei zahlreichen internationalen Beh\u00f6rden und Unternehmen das TIFF-Format inzwischen verdr\u00e4ngt hat.<\/p> <p>\u00dcber das PDF\/A Competence Center<\/p> <p>Das PDF\/A Competence Center wurde 2006 als internationaler Verband gegr\u00fcndet. Ziel des Verbandes ist die F\u00f6rderung des Informations- und Erfahrungsaustausches auf dem Gebiet der Langzeitarchivierung gem\u00e4\u00df ISO 19005: PDF\/A. Der Vorstand setzt sich aus F\u00fchrungskr\u00e4ften der Unternehmen Appligent Document Solutions Inc., callas software GmbH, Compart AG, Crawford Technologies Inc., intarsys consulting GmbH und LuraTech Europe GmbH zusammen. Innerhalb von weniger als zwei Jahren traten \u00fcber 100 Unternehmen und diverse Experten aus mehr als 20 L\u00e4ndern dem PDF\/A Competence Center als Mitglieder bei. Vorstandsvorsitzender ist Olaf Dr\u00fcmmer, Gesch\u00e4ftsf\u00fchrer der callas software GmbH. Duff Johnson, CEO der Appligent Document Solutions, ist stellvertretender Vorstandsvorsitzender.<\/p> <p>Ihre Redaktionskontakte:<\/p> <p>PDF\/A Competence Center<br \/> Thomas Zellmann<br \/> Neue Kantstr. 14<br \/> D-14057 Berlin<br \/> Telefon: +49 30 39 40 50 &#8211; 0<br \/> Telefax: +49 30 39 40 50 &#8211; 99<br \/> info@pdfa.org<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pdfa.org \"  >http:\/\/www.pdfa.org <\/a><\/p> <p>PR-Agentur<br \/> good news! GmbH<br \/> Nicole K\u00f6rber<br \/> Kolberger Str. 36<br \/> D-23617 Stockelsdorf<br \/> Telefon: +49 451 881 99 &#8211; 12<br \/> Telefax: +49 451 881 99 &#8211; 29<br \/> pdfa@goodnews.de<br \/> http:\/\/www.goodnews.de<\/p>","protected":false},"excerpt":{"rendered":"<p>(Berlin) Besucher der CeBIT haben auch in diesem Jahr Gelegenheit, sich umfassend \u00fcber Einsatzgebiete, Nutzen und Weiterentwicklungen des PDF\/A-Formates zu informieren. Anlaufstelle daf\u00fcr ist der Messestand des PDF\/A Competence Center, der beim Kooperationspartner VOI-Verband Organisations- und Informationssysteme e.V. (Halle 3, Stand D34) zu finden ist.<\/p>\n","protected":false},"author":291,"featured_media":198531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-13221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-computer-und-videospiele"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13221"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13221\/revisions"}],"predecessor-version":[{"id":268884,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13221\/revisions\/268884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198531"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}