{"id":13449,"date":"2011-02-04T10:17:26","date_gmt":"2011-02-04T09:17:26","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13449"},"modified":"2015-04-17T11:11:48","modified_gmt":"2015-04-17T10:11:48","slug":"agentur-appadvisors","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/agentur-appadvisors-1013449\/","title":{"rendered":"Full-Service im Bereich alternativer Werbung"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13452\" title=\"webguerillas_beteiligen_sich_an_AppAdvisors.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/53fe000017d38c462e574a9d610ded12.jpg\" alt=\"\" width=\"141\" height=\"114\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/b0c9b8b01f51f0d0c3b9469b73a855c1.jpg\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>M\u00fcnchner Werber erweitern ihre Expertise im Bereich App-L\u00f6sungen<\/p> <p>M\u00fcnchen, 03. Februar 2011: Die webguerillas, Deutschlands f\u00fchrende Full-Service-Agentur f\u00fcr Alternative Werbung, beteiligen sich mit 50 Prozent an der AppAdvisors GmbH, den M\u00fcnchner Professionals f\u00fcr App-L\u00f6sungen. \u201cDurch diese strategische Beteiligung festigen wir unser Full-Service-Portfolio im Bereich Alternativer Werbung und erweitern unsere Expertise im Bereich App-Solutions\u201d, so David Eicher, Gesch\u00e4ftsf\u00fchrer der webguerillas.<\/p> <p><!--more-->Unter der Leitung der Deutsch-Amerikanischen Designerin Kira Song (38) und New-Media-Entrepeneur Michael Reuter (41) entwickeln die AppAdvisors seit 2010 Konzepte f\u00fcr die Entwicklung, Vermarktung und Monetarisierung von Apps. Das Leistungsspektrum wird durch Monitoring, Research und Tracking abgerundet und gew\u00e4hrleistet Qualit\u00e4t und Nachhaltigkeit in einem sich schnell entwickelnden Markt. \u201cApps sind kein tempor\u00e4res Thema, sondern eines, welches uns auch in Zukunft begleiten wird. Derzeit werden Apps haupst\u00e4chlich auf mobilen Endger\u00e4ten wie Smartphones sowie Mac und PC eingesetzt. Der n\u00e4chste konsequente Schritt f\u00fchrt uns zu intuitiven und logischen Anwendungen auf Ger\u00e4ten, wie zum Beispiel TV und Fotoapparaten. Alle elektronische Hausger\u00e4te sind theoretisch dazu geeignet, ihre Funktion durch Applications zu erweitern. Apps werden uns auch au\u00dferhalb der Computer- und Telekommunikationswelt begleiten\u201d, erkl\u00e4rt Kira Song, Gesch\u00e4ftsf\u00fchrerin der AppAdvisors.<\/p> <p>Mit diesem deutlichen Einstieg der webguerillas in den App-Markt, werden die Rahmenbedingungen f\u00fcr App-Marketing neu definiert. So ist David Eicher begeistert von den Synergieeffekten, die sich durch die Beteiligung f\u00fcr die webguerillas GmbH ergeben: \u201eMittels AppAdvisors haben wir den R\u00fcckenwind f\u00fcr neue L\u00f6sungsans\u00e4tze rund um unsere Kernthemen, wie beispielsweise Viral Marketing, Word-of-Mouth-Marketing, Social-Media-Marketing. Wir z\u00fcnden quasi die Stufe &#8222;Alternative Werbung 2.0 \u201c.<\/p> <p>Die AppAdvisors sind an der Entwicklung des deutschen App-Marktes ma\u00dfgeblich beteiligt und haben bereits feste Institutionen ins Leben gerufen. \u201cMit eigenen Projekten wie beispielsweise appstory.tv und appstar \u2013 Deutschlands renommiertesten App-Award \u2013 haben wir nachhaltig Position bezogen und deutlich gemacht, dass noch sehr viel Potential in diesem jungen Segment steckt,\u201d so Michael Reuter, Mitbegr\u00fcnder der AppAdvisors und CEO des Social-Newsportals yigg.de. Und weiter: \u201cWir bieten App-L\u00f6sungen von A-Z nicht nur im Kundenauftrag, sondern auch eigeninitiativ. Das bedeutet: Wir sondieren den Markt und setzen selbst Applikation in die Welt,  wenn wir davon \u00fcberzeugt sind, dass ein Markt besteht. Social Gaming, Hybrid TV, Open Innovation, usw. \u2013 wir haben noch viel vor und freuen uns darauf.\u201d<\/p> <p>Die Agentur webguerillas ist ein Full-Service-Dienstleister f\u00fcr Alternative Werbung. Zum Portfolio geh\u00f6ren alle Werbeformen im On- und Offline-Bereich, die das Zielpublikum mit unkonventionellen Ideen \u00fcberraschen und unterhalten. Die M\u00fcnchner Werber wurden vielfach ausgezeichnet und geh\u00f6ren zu den f\u00fchrenden Agenturen in Deutschland f\u00fcr Virale Kampagnen, Social-Media-Aktivit\u00e4ten, Guerilla-, Word-of-Mouth-, Ambient- und Mobile Marketing, sowie f\u00fcr Blog- und Website-Konzepte. Zus\u00e4tzliche Gesch\u00e4ftsfelder wie Alternative PR und Online Monitoring runden das Angebot ab. Zu den Kunden der webguerillas geh\u00f6ren unter anderem die Deutsche Telekom, Bacardi, MINI, Grohe, KRAFT Foods,  Zott und SIEMENS Hausger\u00e4te.<\/p> <p>Die webguerillas GmbH besch\u00e4ftigt derzeit 53 Mitarbeiter. Die Agentur wurde im Jahr 2000 gegr\u00fcndet und gewann bis heute zahlreiche Preise: 2010 wurde die stern.de-Kampagne mit dem LeadAward in der Kategorie \u201eAnzeigenkampagne\u201c ausgezeichnet. Der MINImalism-Spot der webguerillas gewann den Clio Award 2010 in Bronze sowie den silbernen International Advertising Award 2010 beim New York Festival. 2009 holten die webguerillas Gold beim Onlinestar und Bronze beim London International Award f\u00fcr den MINImalism-Spot, sowie vier Mal die OttoCar-Troph\u00e4e.<br \/> Die AppAdvisors GmbH ist ein App-Spezialdienstleister, der App-Konzepte entwickelt und umsetzt sowie L\u00f6sungen f\u00fcr App-Research, App-Vermarktung und App-Monetarisierung anbietet. Neben der Award Plattform \u201eappstar.tv\u201c, die gemeinsam mit dem IDG-Verlag durchgef\u00fchrt wird und j\u00e4hrlich auf der CeBIT Deutschlands beste Apps pr\u00e4miert, wird mit \u201eappstory.tv\u201c ein zweites Eigenprojekt betrieben. Im Rahmen dieses Bewegtbildformates werden Videos \u00fcber neue Apps, App-Entwickler und internationale Player der App-Economy produziert.<\/p> <p>Kontakt:<br \/> webguerillas GmbH<br \/> Daniela Mayer<br \/> Phone: +49 (0) 89 1893 089 &#8211; 23<br \/> E-Mail: dm@webguerillas.de<\/p>","protected":false},"excerpt":{"rendered":"<p>M\u00fcnchner Werber erweitern ihre Expertise im Bereich App-L\u00f6sungen M\u00fcnchen, 03. Februar 2011: Die webguerillas, Deutschlands f\u00fchrende Full-Service-Agentur f\u00fcr Alternative Werbung, beteiligen sich mit 50 Prozent an der AppAdvisors GmbH, den M\u00fcnchner Professionals f\u00fcr App-L\u00f6sungen. \u201cDurch diese strategische Beteiligung festigen wir unser Full-Service-Portfolio im Bereich Alternativer Werbung und erweitern unsere Expertise im Bereich App-Solutions\u201d, so David<\/p>\n","protected":false},"author":291,"featured_media":198520,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-13449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13449"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13449\/revisions"}],"predecessor-version":[{"id":180880,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13449\/revisions\/180880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198520"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}