{"id":13682,"date":"2011-02-14T11:13:35","date_gmt":"2011-02-14T10:13:35","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13682"},"modified":"2025-08-01T11:24:08","modified_gmt":"2025-08-01T10:24:08","slug":"marktforschung-portaltechnologie","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/marktforschung-portaltechnologie-1013682\/","title":{"rendered":"Flexible und personalisierte Portall\u00f6sungen auch in der Marktforschung"},"content":{"rendered":"<table style=\"float: left; height: 107px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"106\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13685\" title=\"WIBA_Puzzle.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13682\/WIBA_Puzzle.jpg\" alt=\"\" width=\"107\" height=\"107\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13682\/WIBA_Puzzle.jpg 174w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13682\/WIBA_Puzzle-150x150.jpg 150w\" sizes=\"auto, (max-width: 107px) 100vw, 107px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Die Fasihi GmbH hat einen neuen Kunden: Das Markforschungsinstitut WIBA Statistik UG (Weisenheim\/Berg) nutzt die Portaltechnologie des Ludwigshafener IT-Unternehmens f\u00fcr empirische Untersuchungen. Der neue Web-Auftritt auf Basis des Fasihi-Produkts fep2b\u00ae wurde jetzt online unter www.wiba-statistik.de gestellt.<br \/> Mit dem Modul \u201eOnline-Befragung&#8220; steht dem neuen Kunden ein m\u00e4chtiges Werkzeug zur Verf\u00fcgung, um alle g\u00e4ngigen Frageb\u00f6gen technisch zu generieren \u2013 <!--more-->beispielsweise Fragen in Form von Single Choice, Multiple Choice, Matrizen der Fragebatterien und vieles mehr. Zus\u00e4tzlich kann die WIBA Statistik UG das in fep2b enthaltene Content Management System (CMS) nutzen, um ihre Dienstleistungen zu pflegen und alle Daten stets aktuell zu halten. Mit Hilfe der Administrations-Werkzeuge k\u00f6nnen die Frageb\u00f6gen mit verschiedenen Rollen und Rechten versehen werden, damit sie nach der Ablage im Dokumentenmanagement-System \u00fcbersichtlich verwaltet und leicht wieder gefunden werden k\u00f6nnen. Kurzum: Die technische Generierung der WIBA-Fragebogen, die Datenerfassung der Stichprobe oder die Zugriffseinrichtung auf die WIBA-Ergebnisse der Gesamtauswertung k\u00f6nnen \u00fcber das Portal durch feb2b erledigt werden.<br \/> Die Umfrage-Teilnehmer erhalten \u00fcber die Web-Adresse einen eigenen Zugang, so dass ein einmaliges Ausf\u00fcllen des Fragebogens gew\u00e4hrleistet ist. Die Online-Befragung kann wie in der Print-Form beliebig unterbrochen und zeitnah wieder aufgenommen werden.<br \/> Bei der Nutzung des Fasihi-Produkts fep2b entf\u00e4llt die aufw\u00e4ndige Papierablage. Alle Daten k\u00f6nnen hierbei im Portal archiviert und verwaltet werden. Gesch\u00e4ftsf\u00fchrer Dr. Peter Willenbacher von der WIBA Statistik UG erl\u00e4utert: \u201eDie Datenerfassung wird durch das Produkt fep2b der Fasihi GmbH erheblich vereinfacht. Eine sonst in der Regel erforderliche Dateneingabe per Scanner oder gar per Hand entf\u00e4llt. Zahlreiche Module sichern im Datenbestand eine 1:1-Abbildung der im Fragebogen erfassten Daten. Im \u00dcbrigen erm\u00f6glicht die zentrale Datenverwaltung \u00fcber das Portal eine Straffung in der bisherigen Organisation.\u201c<br \/> \u00dcber die WIBA Statistik UG:<br \/> Die WIBA Statistik UG ist ein Institut der Marktforschung und richtet sich an Dienstleistungseinrichtungen wie zum Beispiel Beh\u00f6rden oder unterschiedlichste Unternehmen aus Industrie und Wirtschaft. Die empirischen Untersuchungen &#8211; wissenschaftlich fundiert &#8211; beziehen sich sowohl auf aktuelle Ereignisse in Form von Blitzumfragen als auch auf Befragungen etwa im Rahmen der firmenspezifischen Innovationsprozesse. Damit werden Einzelmeinungen, Einzelaussagen statistisch abgesichert in eine \u201eAll-Aussage\u201c \u00fcberf\u00fchrt, deren Aussagekraft repr\u00e4sentativ ist und die zuverl\u00e4ssig die Allgemeinmeinung abbildet. In der Datenanalyse werden dadurch gesicherte Erkenntnisse erschlossen, die zur substanziellen Weiterentwicklung des Untersuchungsgegenstandes beitragen. F\u00fcr die statistische Auswertung wird u.a. auf das Statistikpaket SPSS zur\u00fcckgegriffen.<br \/> \u00dcber die Fasihi GmbH:<br \/> Die Fasihi GmbH bietet flexible und personalisierte Portall\u00f6sungen f\u00fcr Internet, Intranet oder f\u00fcr die exklusive Kommunikation mit Gesch\u00e4ftspartnern (Extranet) an.  Dazu geh\u00f6ren eine vollst\u00e4ndige Web-Infrastruktur und die komplette Rundum-Betreuung.<br \/> Innovative Produkte des 1990 gegr\u00fcndeten Unternehmens aus Ludwigshafen sind das Fasihi Enterprise Portal und fep2b. Mit Fasihi Enterprise Portal lassen sich besonders anspruchsvolle firmenindividuelle Informations- und Kommunikationsanforderungen erf\u00fcllen. Speziell f\u00fcr kleinere und mittlere Unternehmen steht die Gesch\u00e4fts- und Kommunikationsl\u00f6sung fep2b zur Verf\u00fcgung.<br \/> Die Kunden kommen aus vielerlei Branchen. Hauptkunde ist das weltweit gr\u00f6\u00dfte Chemieunternehmen BASF SE. Dort arbeiten t\u00e4glich \u00fcber 40.000 Mitarbeiter mit mehr als 50 Portall\u00f6sungen auf Basis des Fasihi Enterprise Portal.<br \/> Weitere Informationen unter www.fasihi.net<br \/> Hermann Martin<br \/> Pressesprecher Fasihi GmbH<br \/> Sternstra\u00dfe 166<br \/> 67063 Ludwigshafen<br \/> Tel. 0621-5200780<br \/> martin@fasihi.net<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Fasihi GmbH hat einen neuen Kunden: Das Markforschungsinstitut WIBA Statistik UG (Weisenheim\/Berg) nutzt die Portaltechnologie des Ludwigshafener IT-Unternehmens f\u00fcr empirische Untersuchungen. Der neue Web-Auftritt auf Basis des Fasihi-Produkts fep2b\u00ae wurde jetzt online unter www.wiba-statistik.de gestellt. Mit dem Modul \u201eOnline-Befragung&#8220; steht dem neuen Kunden ein m\u00e4chtiges Werkzeug zur Verf\u00fcgung, um alle g\u00e4ngigen Frageb\u00f6gen technisch zu<\/p>\n","protected":false},"author":291,"featured_media":13685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-13682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet-portale-foren-communities"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13682"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13682\/revisions"}],"predecessor-version":[{"id":277683,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13682\/revisions\/277683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/13685"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}