{"id":13687,"date":"2011-02-14T11:19:00","date_gmt":"2011-02-14T10:19:00","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13687"},"modified":"2011-02-14T11:19:32","modified_gmt":"2011-02-14T10:19:32","slug":"forschungsliteratur-china","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/forschungsliteratur-china-1013687\/","title":{"rendered":"Beitr\u00e4ge auf h\u00f6chstem wissenschaftlichen Niveau"},"content":{"rendered":"<table style=\"float: left; height: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"82\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/images.springer.com\/cda\/content\/image\/cda_displayimage.jpg?SGWID=0-0-16-704715-0\" alt=\"\" width=\"87\" height=\"116\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Zwei Springer-Journale seit Januar neu in der weltweit wichtigsten Datenbank f\u00fcr Medizinliteratur<br \/> Die beiden Springer-Fachzeitschriften Frontiers of Medicine und Protein &amp; Cell wurden im Januar in MEDLINE, der weltweit bedeutendsten Literaturdatenbank f\u00fcr medizinische und biomedizinische Fachartikel, aufgenommen. Die beiden Fachjournale sind Ko-Publikationen, die Springer mit dem chinesischen Verlagspartner Higher Education herausbringt. Beide Fachbl\u00e4tter geh\u00f6ren zur Chinese Library of Science, einer Sammlung von \u00fcber 90 Springer-Fachzeitschriften.<br \/> Frontiers in Medicine verfolgt einen breiten Ansatz von der medizinischen Grundlagen- bis zur klinischen Forschung. <!--more-->Das Themenspektrum umfasst neben der Medizin, die Epidemiologie, die traditionelle chinesische Medizin, die translationale Forschung sowie die Gesundheitspolitik und das Gesundheits-wesen in China. Die Zeitschrift gibt den Forschungsstand der Medizin in China nach dem aktuellen Kenntnisstand in Diagnostik und Therapie wieder.<br \/> Protein &amp; Cell ver\u00f6ffentlicht Original- und \u00dcbersichtsartikel sowie Kommentare zu den neuesten Entwicklungen in der interdisziplin\u00e4ren Forschung in Biologie und Biomedizin mit besonderer Fokus-sierung auf die Zell- und Proteinforschung. Die Zeitschrift zeigt die Forschungsschwerpunkte in China auf diesem Gebiet und sie informiert aktuell \u00fcber den jeweiligen Forschungsstand, die Forschungspolitik und die Drittmitteleinwerbung in dem Land.<br \/> Beide Fachzeitschriften wurden seit ihrer Gr\u00fcndung von einem internationalen Herausgebergremium gef\u00fchrt und organisiert. Die Mitglieder des Editorial Boards sind renommierte Forscher und Experten in der Medizin und den Life Sciences. Dadurch wird sichergestellt, dass Beitr\u00e4ge auf h\u00f6chstem wissenschaftlichen Niveau publiziert werden und die Manuskripte effizient den Peer-Review-Prozess durchlaufen. Durch verschiedene Alertservices, wie beispielsweise den ToC-Alert, der interessierte Leser \u00fcber die Inhalte der kommenden Ausgabe informiert oder durch Presseinformationen sorgt Springer daf\u00fcr, dass die Zeitschriften international einen hohen Bekanntheitsgrad erlangen. Dies hat eine sehr gute Sichtbarkeit der Fachmagazine zur Folge sowie eine vermehrte Anfrage nach Artikel-Downloads. Durch die Publikation von Online-First-Beitr\u00e4gen, die lange vor der gedruckten Ausgabe erscheinen, kann Springer sicherstellen, dass die Zeitschriftenbeitr\u00e4ge m\u00f6glichst rasch \u00fcber die Plattform SpringerLink zu lesen sind.<br \/> Seit 2006 bietet Springer Forschungsliteratur aus China in englischer Sprache an und arbeitet mit weite-ren renommierten chinesischen Verlagen, Fachgesellschaften sowie mit der Chinesischen Akademie der Wissenschaften zusammen. Unter dem Namen Chinese Library of Science b\u00fcndelt  der Wissen-schaftsverlag inzwischen \u00fcber 90 wissenschaftliche Zeitschriften, die auf www.springerlink.com zu lesen sind.<br \/> Die chinesische Verlagsgruppe Higher Education Press (HEP) wurde 1954 gegr\u00fcndet und ist in China der f\u00fchrende Anbieter f\u00fcr Lehrb\u00fccher, Bildungs- und Forschungsliteratur. Der Verlag sorgt dar\u00fcber hi-naus f\u00fcr  jegliche Art von Bildungs- und Weiterbildungsm\u00f6glichkeiten in Universit\u00e4ten und Ausbildungs-st\u00e4tten.<\/p> <p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.springer.com\"  >www.springer.com<\/a><\/p> <p>Springer-Verlag GmbH, Heidelberg, Zweigniederlassung der Springer-Verlag GmbH, BerlinTiergartenstrasse 17D-69121 Heidelberg<\/p>","protected":false},"excerpt":{"rendered":"<p>Zwei Springer-Journale seit Januar neu in der weltweit wichtigsten Datenbank f\u00fcr Medizinliteratur Die beiden Springer-Fachzeitschriften Frontiers of Medicine und Protein &amp; Cell wurden im Januar in MEDLINE, der weltweit bedeutendsten Literaturdatenbank f\u00fcr medizinische und biomedizinische Fachartikel, aufgenommen. Die beiden Fachjournale sind Ko-Publikationen, die Springer mit dem chinesischen Verlagspartner Higher Education herausbringt. Beide Fachbl\u00e4tter geh\u00f6ren zur<\/p>\n","protected":false},"author":291,"featured_media":198502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[361],"tags":[],"class_list":["post-13687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verlagsnachrichten"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13687"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198502"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}