{"id":13879,"date":"2011-02-21T11:45:15","date_gmt":"2011-02-21T10:45:15","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13879"},"modified":"2011-02-21T11:45:15","modified_gmt":"2011-02-21T10:45:15","slug":"gestalt-reichtum-planeten","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/gestalt-reichtum-planeten-1013879\/","title":{"rendered":"Vielf\u00e4ltige Gestalt und Reichtum unseres Planeten in atemberaubenden Bildern"},"content":{"rendered":"<table style=\"float: left; height: 91px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"67\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13880\" title=\"nationalgeographic\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2011\/02\/nationalgeographic-206x300.jpg\" alt=\"\" width=\"75\" height=\"108\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2011\/02\/nationalgeographic-206x300.jpg 206w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2011\/02\/nationalgeographic-648x941.jpg 648w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2011\/02\/nationalgeographic-88x127.jpg 88w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2011\/02\/nationalgeographic.jpg 935w\" sizes=\"auto, (max-width: 75px) 100vw, 75px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Zur Ausgabe 3\/2011 (EVT: 25. Februar) \u00fcbernimmt die IPS Pressevertrieb GmbH die vertriebliche Betreuung der englischsprachigen Originalausgabe von <strong>National Geographic<\/strong>. Das Monatsmagazin wird seit 1888 von der <em>National Geographic Society <\/em>\u2013 Amerikas legend\u00e4rer Gesellschaft zur Erforschung der Erde \u2013 herausgegeben; es war die erste und gilt bis heute als f\u00fchrende Zeitschrift seines Genres. <strong>National Graphic<\/strong> zeigt die vielf\u00e4ltige Gestalt und den Reichtum unseres Planeten in hervorragend geschriebenen und atemberaubend bebilderten Artikeln. <!--more-->Das Magazin hat seit seiner Gr\u00fcndung nicht nur zahlreiche Nachahmer auf den Plan gerufen, sondern den westlichen Blick auf die Welt entscheidend gepr\u00e4gt: Disneys Comics, die Indiana-Jones-Filme s\u00e4hen ohne den Einfluss von <strong>National Geographic<\/strong> wohl anders aus. Heute ist das Magazin eine der weltweit bekanntesten Printmarken, sofort erkennbar am charakteristischen gelben Rahmen um das Cover. <strong>National Geographic<\/strong> erscheint weltweit in 33 Sprachausgaben in einer Gesamtauflage von knapp neun Millionen Exemplaren.<\/p> <p>Die IPS Pressevertrieb GmbH betreut den deutschen Einzelverkauf und das Point-of-Sale-Marketing des US-amerikanischen Originals. Das Magazin ist f\u00fcr 6,95 Euro bundesweit im Handel erh\u00e4ltlich. Online ist <strong>National Geographic<\/strong> unter der Adresse <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/ngm.nationalgeographic.com\/\"  >http:\/\/ngm.nationalgeographic.com<\/a> erreichbar. Die kommende Ausgabe 3\/2011 schildert in der Titelgeschichte die lange und erfolgreiche Geschichte der Domestizierung von Tierarten \u2013 und blickt voraus in die nahe Zukunft, in der Tiere mit Hilfe der Gentechnik gez\u00e4hmt werden k\u00f6nnen.<\/p> <p>IPS Pressevertrieb GmbH<br \/> Carl-Zeiss-Str. 5<br \/> 53340 Meckenheim<\/p> <p>Postanschrift:<br \/> Postfach 12 11<br \/> 53334 Meckenheim<br \/> Deutschland\/Germany<\/p>","protected":false},"excerpt":{"rendered":"<p>Zur Ausgabe 3\/2011 (EVT: 25. Februar) \u00fcbernimmt die IPS Pressevertrieb GmbH die vertriebliche Betreuung der englischsprachigen Originalausgabe von National Geographic. Das Monatsmagazin wird seit 1888 von der National Geographic Society \u2013 Amerikas legend\u00e4rer Gesellschaft zur Erforschung der Erde \u2013 herausgegeben; es war die erste und gilt bis heute als f\u00fchrende Zeitschrift seines Genres. National Graphic<\/p>\n","protected":false},"author":291,"featured_media":198490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13879"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198490"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}