{"id":13894,"date":"2011-02-22T16:06:55","date_gmt":"2011-02-22T15:06:55","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13894"},"modified":"2014-07-23T09:19:42","modified_gmt":"2014-07-23T08:19:42","slug":"loesung-content-erstellung","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/loesung-content-erstellung-1013894\/","title":{"rendered":"Mehrsprachige und medien\u00fcbergreifende Publikation komplexer Inhalte"},"content":{"rendered":"<table style=\"float: left; height: 94px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"72\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Anbindung des Noxum Publishing Studio an den Across Language Server beschleunigt \u00dcbersetzungsprozesse<\/p> <p>KARLSBAD \u2013 21. Februar 2011. Die Across Systems GmbH zeigt auf der CeBIT am Stand ihres Partners Noxum GmbH (Halle 6, Stand H24) die nahtlose Anbindung des Noxum Publishing Studio an den Across Language Server. Der Across Language Server ist die zentrale Plattform f\u00fcr alle Sprachressourcen und \u00dcbersetzungsprozesse im Unternehmen. Er unterst\u00fctzt die Steuerung und Bearbeitung interner und externer \u00dcbersetzungsaufgaben. <!--more-->Das Noxum Publishing Studio ist ein XML-basiertes Redaktionssystem f\u00fcr die mehrsprachige und medien\u00fcbergreifende Publikation komplexer Inhalte in Form von Katalogen, Handb\u00fcchern, Webseiten und anderen Ausgabeformaten.<\/p> <p>Dank der integrierten L\u00f6sung kann der Anwender direkt im Noxum Publishing Studio auf crossTerm und crossTank zugreifen sowie die \u00dcbersetzungsauftr\u00e4ge automatisch oder manuell ausl\u00f6sen und die relevanten Angaben festlegen, wie beispielsweise die ben\u00f6tigten Zielsprachen oder das Fertigstellungsdatum der \u00dcbersetzungen. Dies beschleunigt die Erstellung mehrsprachiger Produktinformationen und technischer Beschreibungen bei gleichzeitig geringeren Kosten.<\/p> <p>Dar\u00fcber hinaus zeigt Across am Noxum-Stand die integrierten L\u00f6sungen der Congree Language Technologies GmbH. Deren Produkte unterst\u00fctzen Autoren bei der Formulierung konsistenter Texte unter Ber\u00fccksichtigung von definierten Stilregeln und einem einheitlichen Wording. Dies schafft die Voraussetzungen f\u00fcr eine sogenannte Controlled Language, welche die Wiederverwendbarkeit von \u00dcbersetzungen maximiert und dabei gleichzeitig die hohe Qualit\u00e4t der Inhalte sicherstellt.<\/p> <p>Leserkontakt Across:<br \/> Phone: +49 7248 925-425<br \/> info@across.net<\/p> <p>\u00dcber Across Systems<\/p> <p>Across Systems (www.across.net) mit Sitz in Karlsbad bei Karlsruhe und Glendale, Kalifornien, ist Hersteller des Across Language Server \u2013 der weltweit f\u00fchrenden unabh\u00e4ngigen Technologie f\u00fcr die \u201eLinguistic Supply Chain\u201c.<\/p> <p>Der Across Language Server ist eine zentrale Software-Plattform f\u00fcr alle Sprach-Ressourcen und \u00dcbersetzungsprozesse im Unternehmen. Er vereinfacht, beschleunigt und verbessert die Steuerung, Koordinierung und Durchf\u00fchrung von \u00dcbersetzungen. Die Software beinhaltet unter anderem ein Translation-Memory- und Terminologiesystem sowie leistungsf\u00e4hige Werkzeuge zu Projekt-Management und Workflow-Steuerung von \u00dcbersetzungen. Insbesondere erlaubt der Across Language Server durchg\u00e4ngige Prozesse, bei denen Auftraggeber, Agenturen und \u00dcbersetzer nahtlos und auf Basis der gleichen Daten zusammenarbeiten. Offene Schnittstellen erm\u00f6glichen die direkte Integration korrespondierender Systeme, zum Beispiel von CMS-, Katalog- oder ERP-L\u00f6sungen.<\/p> <p>Zielgruppe sind alle, die professionell \u00fcbersetzen oder \u00fcbersetzen lassen \u2013 vom exportorientierten Mittelst\u00e4ndler \u00fcber die Sprachendienste weltweit t\u00e4tiger Konzerne bis hin zu professionellen \u00dcbersetzungsdienstleistern. Durch den Einsatz von Across k\u00f6nnen \u00dcbersetzungskosten deutlich reduziert werden, die Investition in Across amortisiert sich \u00fcblicherweise innerhalb k\u00fcrzester Zeit.<br \/> Der Across Language Server wird von hunderten f\u00fchrender Firmen als zentrale Plattform f\u00fcr Sprachressourcen und \u00dcbersetzungsprozesse eingesetzt, beispielsweise vom Volkswagen Konzern, der HypoVereinsbank und der SMA Solar Technology AG.<\/p> <p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.across.net\"  >www.across.net<\/a><\/p> <p>Pressekontakte Across:<\/p> <p>Across Systems GmbH<br \/> J\u00fcrgen Jungermann<br \/> Marketing Director<br \/> Im Stockmaedle 13 &#8211; 15<br \/> 76307 Karlsbad<br \/> Phone: +49 7248 925-477<br \/> Fax: +49 7248 925-444<br \/> press@across.net<br \/> http:\/\/www.across.net<\/p> <p>PR-Agentur<br \/> good news! GmbH<br \/> Nicole K\u00f6rber<br \/> Kolberger Str. 36<br \/> 23617 Stockelsdorf<br \/> Phone: +49 451 88199-12<br \/> Fax: +49 451 88199-29<br \/> across@goodnews.de<br \/> http:\/\/www.goodnews.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Anbindung des Noxum Publishing Studio an den Across Language Server beschleunigt \u00dcbersetzungsprozesse KARLSBAD \u2013 21. Februar 2011. Die Across Systems GmbH zeigt auf der CeBIT am Stand ihres Partners Noxum GmbH (Halle 6, Stand H24) die nahtlose Anbindung des Noxum Publishing Studio an den Across Language Server. Der Across Language Server ist die zentrale Plattform<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-13894","post","type-post","status-publish","format-standard","hentry","category-computer-und-videospiele"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13894"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13894\/revisions"}],"predecessor-version":[{"id":167481,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13894\/revisions\/167481"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}