{"id":13935,"date":"2011-02-23T11:09:02","date_gmt":"2011-02-23T10:09:02","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=13935"},"modified":"2011-02-23T11:09:51","modified_gmt":"2011-02-23T10:09:51","slug":"magnetische-etiketten","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/magnetische-etiketten-1013935\/","title":{"rendered":"Flexible Kennzeichnung durch magnetische Etiketten"},"content":{"rendered":"<table style=\"float: left; height: 78px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"71\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13938\" title=\"_MG_9510.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/13935\/_MG_9510-199x300.jpg\" alt=\"\" width=\"66\" height=\"101\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Endlich ist es soweit: Magnetische Etiketten zur Lagerkennzeichnung kann man nun effizient selbst bedrucken. M\u00f6glich wird dies durch die magnetischen Etiketten f\u00fcr Thermotransferdrucker: COROSTOC TT.<br \/> Diese Neuheit ist dem Unternehmen M\u00fcnchner Magnet Service zu verdanken, der ja schon lange als Spezialist f\u00fcr magnetische Kennzeichnungssysteme bekannt ist.<br \/> <!--more-->COROSTOC TT werden  angestanzt auf Rollen geliefert. Durch eine spezielle Steuerstanzung wird eine Erkennung durch die meisten Thermotransferdrucker erm\u00f6glicht und somit sichergestellt, da\u00df der Druck immer an der richtigen Stelle erfolgt.<br \/> Derzeit werden die Etiketten in folgenden Standardformaten angeboten:<br \/> 50 x 20 mm, 60 x 30 mm, 80 x 40 mm und 100 x 50 mm.<br \/> Das Besondere der magnetischen Kennzeichnung ist, da\u00df sie schnell angebracht ist, ohne R\u00fcckst\u00e4nde wieder entfernt und bei Bedarf sogar wieder verwendet werden kann.<br \/> Mit den COROSTOC TT Etiketten steht einer flexiblen Kennzeichnung also nichts mehr im Wege.<br \/> Und da die MMS Standardprodukte innerhalb von 24 Stunden verschickt hat sie auch schon so manch rettende L\u00f6sung f\u00fcr z.B. bevorstehende ISO Pr\u00fcfungen gebracht.<br \/> _____________________________________________________________________<br \/> MMS M\u00fcnchner Magnet Service Betriebs-GmbH<br \/> Die MMS, Baierbrunn wurde Ende der sechziger Jahre gegr\u00fcndet und entwickelte sich rasch zum Spezialisten f\u00fcr magnetische Kennzeichnungssysteme. Mit Niederlassungen in Frankreich und den Niederlanden haben es sich alle 3 Firmen zur Aufgabe gemacht mit den besten Magnetmaterial, der geeigneten Magnetisierung und der vorteilhaftesten Verarbeitung optimale und innovative L\u00f6sungen f\u00fcr Ihre Kunden zu finden. Das Firmenbestehen seit 40 Jahren macht den Erfolg der MMS messbar.<br \/> MMS \u2013 M\u00fcnchner Magnet Service Betriebs-GmbH, Isarstra\u00dfe 6, 82065 Baierbrunn<br \/> Tel.: +49 (0)89 \u2013 2885256-0, Fax: +49 (0)89 \u2013 2885256-99, mail@mms-magnet.de, <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.mms-magnet.de\"  >http:\/\/www.mms-magnet.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Endlich ist es soweit: Magnetische Etiketten zur Lagerkennzeichnung kann man nun effizient selbst bedrucken. M\u00f6glich wird dies durch die magnetischen Etiketten f\u00fcr Thermotransferdrucker: COROSTOC TT. Diese Neuheit ist dem Unternehmen M\u00fcnchner Magnet Service zu verdanken, der ja schon lange als Spezialist f\u00fcr magnetische Kennzeichnungssysteme bekannt ist.<\/p>\n","protected":false},"author":291,"featured_media":198484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-13935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industrie-produktion"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=13935"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/13935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198484"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=13935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=13935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=13935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}