{"id":14016,"date":"2011-02-28T11:29:03","date_gmt":"2011-02-28T10:29:03","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=14016"},"modified":"2020-09-22T11:49:16","modified_gmt":"2020-09-22T10:49:16","slug":"hochleistungs-faserverbundtechnologien","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/hochleistungs-faserverbundtechnologien-1014016\/","title":{"rendered":"Marktf\u00e4hige Hochleistungs-Faserverbundstrukturen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" width=\"89\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Der Carbon Composites e. V. (CCeV) wird auch in diesem Jahr wieder auf der weltweit gr\u00f6\u00dften und wichtigsten Fachmesse f\u00fcr Faserverbundtechnologien, der JEC (Joint Exhibition in Composites), mit einem Gemeinschaftsstand in Halle 1, Stand 46, vertreten sein. Die Messe findet vom 29. bis 31. M\u00e4rz 2011 in Paris statt. Mit 274 Quadratmetern Standfl\u00e4che geh\u00f6rt der CCeV zu den gr\u00f6\u00dften Ausstellern der Fachmesse. <!--more-->Unter dem Dach des Verbandes sind 17 Unternehmen vertreten, wie beispielsweise EADS und Premium Aerotec aus der Flugzeugindustrie, BMW aus der Wachstumsbranche Automobilbau, ebenso etliche Werkzeugbauer und ein Forschungsinstitut. Der CCeV ist seit 2008 auf der JEC vertreten, in dieser Zeit hat sich seine Ausstellungsfl\u00e4che nahezu versiebenfacht.<br \/> \u00dcber CCeV:<br \/> Carbon Composites e.V. (CCeV) ist ein Verband von Unternehmen und Forschungseinrichtungen. CCeV vernetzt Forschung und Wirtschaft im S\u00fcden des deutschsprachigen Raums (S\u00fcddeutschland, \u00d6sterreich, Schweiz). Sitz des Vereins ist Augsburg.<br \/> CCeV versteht sich als Kompetenznetzwerk zur F\u00f6rderung der Anwendung von Faserverbundtechnologien. Die Aktivit\u00e4ten von CCeV sind auf die Produktgruppe \u201eMarktf\u00e4hige Hochleistungs-Faserverbundstrukturen\u201c ausgerichtet. Der Fokus liegt auf Faserverbundstrukturen mit Kunststoffmatrices, wie sie aus vielen Anwendungen auch einer breiteren \u00d6ffentlichkeit bekannt sind, sowie auf Faserverbundstrukturen mit Keramikmatrices mit ihren h\u00f6heren Temperatur- und Verschlei\u00dfbest\u00e4ndigkeiten.<br \/> Belegexemplar erbeten an Pressekontakt:<br \/> Doris Karl, Medienb\u00fcro MehrText, Kirchberg 10, 86853 Langerringen,<br \/> Tel.: 08248 901190, mehrtext@online.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Carbon Composites e. V. (CCeV) wird auch in diesem Jahr wieder auf der weltweit gr\u00f6\u00dften und wichtigsten Fachmesse f\u00fcr Faserverbundtechnologien, der JEC (Joint Exhibition in Composites), mit einem Gemeinschaftsstand in Halle 1, Stand 46, vertreten sein. Die Messe findet vom 29. bis 31. M\u00e4rz 2011 in Paris statt. Mit 274 Quadratmetern Standfl\u00e4che geh\u00f6rt der<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14016","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/14016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=14016"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/14016\/revisions"}],"predecessor-version":[{"id":271935,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/14016\/revisions\/271935"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=14016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=14016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=14016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}