{"id":144666,"date":"2014-04-11T12:43:04","date_gmt":"2014-04-11T11:43:04","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=144666"},"modified":"2014-07-29T06:25:03","modified_gmt":"2014-07-29T05:25:03","slug":"der-mut-der-fische","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/der-mut-der-fische-10144666\/","title":{"rendered":"Der Mut der Fische"},"content":{"rendered":"<p>Der Mut der Fische &#8211; So k\u00f6nnte man eine neue Studie betiteln, die die australischen Wissenschaftler Culum Brown und Anne-Laurence Bibost von der Universit\u00e4t von Macquarie in Sydney durchgef\u00fchrt haben. Sie wollten wissen, worin sich in Freiheit geborene Regenbogenfische von in gefangenschaft lebenden unterscheiden. Die Ursache fanden sie in der zerebralen Lateralisierung, also der F\u00e4higkeit, Informationen mit den verschiedenen Gehirnh\u00e4lften zu verarbeiten.<\/p> <p><!--more-->Regenbogenfische in Freiheit sind intelligent und mutig<\/p> <p>Studie zeigt, dass wild aufgewachsene Regenbogenfische mutiger sind als Zuchtfische<\/p> <p>In Freiheit geborene Schwarzband-Regenbogenfische sind die mutigsten unter ihren Artgenossen. Die australischen Wissenschaftler Culum Brown und Anne-Laurence Bibost von der Universit\u00e4t von Macquarie in Sydney haben dazu eine Studie durchgef\u00fchrt und festgestellt, dass die Fische generell weniger Angst haben, die Informationen \u00fcber beide Gehirnh\u00e4lften verarbeiten. Die Studie erscheint in der Springer-Fachzeitschrift Behavioral Ecology and Sociobiology.<\/p> <p>Die F\u00e4higkeit, Informationen entweder mit der linken oder der rechten Hemisph\u00e4re des Gehirns auszuwerten und darauf zu reagieren, wird als zerebrale Lateralisierung bezeichnet und ist bei Wirbeltieren weit verbreitet. Bei Menschen oder Papageien wird die Lateralisierung dadurch ersichtlich, dass sie eine Hand oder Kralle bevorzugt benutzen oder sich immer f\u00fcr die gleiche Seite entscheiden, wenn sie sich um Objekte herumbewegen.<\/p> <p>Zun\u00e4chst verglichen die Wissenschaftler wilde Regenbogenfische mit in Gefangenschaft aufgewachsenen Regenbogenfischen. Anschlie\u00dfend verwendeten sie eine abge\u00e4nderte Version des Spiegeltests, um zu pr\u00fcfen, ob ein Fisch eine laterale Pr\u00e4ferenz zeigte, sich selbst entweder mit dem linken oder rechten Auge zu betrachten. Den Mut der Fische testeten die Wissenschaftler, indem sie die Zeit ma\u00dfen, die verstrich, bis sie ein sicheres Versteck wieder verlie\u00dfen.<\/p> <p>Es zeigte sich, dass Fische ohne Lateralisierung \u2013 die also Informationen nicht in einer bestimmten Hemisph\u00e4re des Gehirns analysierten \u2013 deutlich mutiger waren als Fische mit linker oder rechter Lateralisierung. Diese Ergebnisse legen nahe, dass Angst verst\u00e4rkt wird, wenn sie in erster Linie nur von einer Hemisph\u00e4re verarbeitet wurde; daher ist ein Fisch mit Lateralisierung weniger mutig. Vorangegangene Studien zeigten, dass komplexe Aufgabenstellungen schwieriger zu bew\u00e4ltigen sind, wenn die Informationsverarbeitung zwischen beiden Hemisph\u00e4ren des Gehirns aufgeteilt wird. Entscheidend ist also die Verarbeitungsgeschwindigkeit. Fische ohne Lateralisierung m\u00fcssen in einer potenziell lebensbedrohlichen Situation erst Informationen von beiden Hemisph\u00e4ren abrufen, vergleichen und diese integrieren, bevor sie eine Entscheidung treffen k\u00f6nnen. Fische mit einer stark ausgepr\u00e4gten Lateralisierung k\u00f6nnen dagegen schneller reagieren, da sie Information nur von einer Hemisph\u00e4re abrufen.<\/p> <p>Fische ohne Lateralisierung verarbeiten angstbesetzte Reize vergleichsweise langsam oder ineffizient. Daraus lie\u00dfe sich ableiten, dass die d\u00e4mpfende Wirkung von Angst bei ihnen weniger ausgepr\u00e4gt ist als bei Fischen mit starker Lateralisierung. Die Wissenschaftler gehen davon aus, dass dies generell das Ausma\u00df an Furcht verringert, oder dass die Entscheidung, die Umgebung zu erkunden, bereits getroffen wurde, bevor der d\u00e4mpfende Effekt der Angst eintritt. Beide Szenarien w\u00e4ren eine angemessene Erkl\u00e4rung f\u00fcr ihre Beobachtung, dass Fische ohne Lateralisierung mutiger sind als Fische mit Lateralisierung.<\/p> <p>Die Wissenschaftler waren nicht \u00fcberrascht, dass wild aufgewachsene Fische deutlich mutiger waren als ihre Artgenossen, die in Gefangenschaft aufgezogen wurden. Auch da ihre bisherigen Arbeiten gezeigt haben, dass Fischbest\u00e4nde, die von R\u00e4ubern gejagt werden, furchtloser sind als die aus Gebieten, die wenig bejagt werden.<\/p> <p>\u201eDie \u00dcbereinstimmungen zwischen Pers\u00f6nlichkeit und Lateralisierung sind nat\u00fcrlich faszinierend und deuten auf eine einzelne zugrunde liegende Funktion bzw. Mechanismus hin\u201c, sagt Brown. \u201eUnsere Ergebnisse lassen darauf schlie\u00dfen, dass diese Aspekte der Pers\u00f6nlichkeitseigenschaften tats\u00e4chlich auf Unterschiede bez\u00fcglich der Lateralisierung zur\u00fcckzuf\u00fchren sind.\u201c<\/p> <p>Quelle: Brown, C. &amp; Bibost, A-L. (2014). Laterality is linked to personality in the black-lined rainbowfish, Melanotaenia nigrans, Behavioral Ecology and Sociobiology, DOI 10.1007\/s00265-014-1712-0<\/p> <p>Journalisten erhalten auf Anfrage den vollst\u00e4ndigen Artikel sowie Bildmaterial.<\/p> <p>Kontak: Renate Bayaz | Springer | Corporate Communications tel +49 6221 487 8531 | renate.bayaz@springer.com<\/p> <p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.springer.com\/?SGWID=1-102-0-0-0\" title=\"Der Wissenschaftsverlag\" >http:\/\/www.springer.com\/?SGWID=1-102-0-0-0<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Der Mut der Fische &#8211; So k\u00f6nnte man eine neue Studie betiteln, die die australischen Wissenschaftler Culum Brown und Anne-Laurence Bibost von der Universit\u00e4t von Macquarie in Sydney durchgef\u00fchrt haben. Sie wollten wissen, worin sich in Freiheit geborene Regenbogenfische von in gefangenschaft lebenden unterscheiden. Die Ursache fanden sie in der zerebralen Lateralisierung, also der F\u00e4higkeit,<\/p>\n","protected":false},"author":3,"featured_media":144667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8807],"tags":[],"class_list":["post-144666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiere"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/144666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=144666"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/144666\/revisions"}],"predecessor-version":[{"id":168603,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/144666\/revisions\/168603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/144667"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=144666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=144666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=144666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}