{"id":145247,"date":"2014-04-13T14:05:46","date_gmt":"2014-04-13T14:05:46","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=145247"},"modified":"2014-04-15T12:19:20","modified_gmt":"2014-04-15T11:19:20","slug":"preis-pro-quadratmeter-bananen-aepfel-und-ein-brot","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/preis-pro-quadratmeter-bananen-aepfel-und-ein-brot-10145247\/","title":{"rendered":"Preis pro Quadratmeter: Bananen, \u00c4pfel und ein Brot"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Gemeinsam wohnen, den Alltag erleichtern, sparen und vielleicht sogar eine Kleinigkeit verdienen\" alt=\"Gemeinsam wohnen, den Alltag erleichtern, sparen und vielleicht sogar eine Kleinigkeit verdienen\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/aff56183675bd1105bcc0d211a37bd52.jpg\" width=\"119\" height=\"119\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/aff56183675bd1105bcc0d211a37bd52.jpg\" \/>Eine neue Idee erobert das Netz: Warum nicht Wohnraum anbieten gegen Dienstleistungen, ganz ohne oder mit sehr geringem finanziellen Aufwand?Der Rentner sucht jemanden, der die Eink\u00e4ufe erledigt, die Familie m\u00f6chte Ihren Nachwuchs betreuen lassen, wieder andere brauchen Hausmeisterdienste &#8211; Und sie alle haben Wohnraum. Was liegt da n\u00e4her, als das eine gegen das andere zu tauschen? Und eventuell noch tolle neue Orte zu entdecken? Ein neues Portal macht&#8217;s m\u00f6glich:<\/p> <p><!--more-->Deutschland und Ausland: Mietfrei oder Kosteng\u00fcnstig Wohnen &#8211; gibt es das?<\/p> <p>Wohnen gegen Hilfe &#8211; die L\u00f6sung auf Gegenseitigkeit f\u00fcr Vermieter und Mieter &#8211; Deutschland, \u00d6sterreich, Schweiz, Frankreich, Spanien und mehr &#8230;<br \/> Eine neue Webseite macht es m\u00f6glich &#8211; das Zusammenbringen von Vermietern, die irgendwelche kleineren Dienstleistungen rund um Haus, Garten und Hof ben\u00f6tigen und Mieter, die sie anbieten k\u00f6nnen. Dies in Deutschland, \u00d6sterreich und der Schweiz, aber es gibt auch Angebote im Ausland. Die ersten, die von Vermieterseite Bedarf haben, sind die Familien, denn der Nachwuchs muss bewacht werden. Ferner die Senioren, die zwar r\u00fcstig sind, aber oft viel zu gro\u00dfe Immobilien bewohnen, denn die Kinder sind ausgeflogen.<\/p> <p>Hier einige Leckerbissen, aktuell oder aus der letzten Zeit:<br \/> &#8211; Gro\u00dfes, mietfreies Zimmer in M\u00fcnchen, in wundersch\u00f6nem Altbau. Aufgaben: 10 Stunden pro Woche Betreuung eines M\u00e4dchens mit Down-Syndrom.<br \/> &#8211; Oder wie w\u00e4r\u00b4s mit naturnahem Wohnen gegen Kinderbetreuung auf dem Land f\u00fcr eine Alleinerziehende und gegen eine Miete von 100 EUR? Hier ist ein Kind von 5 Monaten stundenweise zu betreuen. Dies in einem 4-H\u00f6fe-Weiler in Mittelbayern.<br \/> &#8211; In Bonn ist es dann kein Kind, aber ein Hund, der zu versorgen ist: 10 Stunden w\u00f6chentlich und eine Miete f\u00fcrs Zimmer von 50 Euro. Da h\u00fcpft das Herz des Azubis oder der Rentnerin.<br \/> &#8211; Im Harzvorland sind 118 qm2 in einem historischen Gutshaus zu bekommen, gegen Hilfe im Haushalt, bei Haustieren sowie gegen kleine Instandsetzungen und Gartenarbeit. N\u00f6tige monatliche Arbeitsstunden 20.<\/p> <p>Zahllos sind solche Mietangebote in den deutschsprachigen L\u00e4ndern, denn der Bedarf ist gro\u00df. H\u00e4ufig im Leben kann man Unterst\u00fctzung gebrauchen, ob im Zusammenhang mit Kindern, Senioren, der Versorgung des heimischen Zoos bis hin zum Ross.<\/p> <p>Auch aus den Ausland gibt es Angebote:<br \/> &#8211; So sucht jemand eine Schweizerin ein auf Korsika ein r\u00fcstige Rentnerin gegen die Betreuung ihrer kleinen Tochter und des Hundes. Arbeitsstunden: 40, Miete f\u00fcr ein kleines abgeschlossenes Studio: 100-300 EUR.<\/p> <p>&#8211; Ebenfalls auf Korsika ein Angebot f\u00fcr ein Aussteiger- oder jung gebliebenes Rentnerpaar ab Herbst f\u00fcr dauernd, &#8222;gratis&#8220; und ganzj\u00e4hrig. Winterfestes. Ferienhaus, 3 Zimmer, 600 Meter vom Meer, Alleinlage in Naturschutzgebiet. Wahrscheinlich die sch\u00f6nste und urt\u00fcmlichste Lage am Meer in Korsika. Vollm\u00f6bliert, TV, Schwimmbad und Sauna. Ohne Miete, gegen Mithilfe in Garten und Wohnung &#8211; Distanz zw. beiden H\u00e4usern ca. 60 Meter.<br \/> Fast zu sch\u00f6n, um wahr zu sein. Das m\u00f6chte sicher so mancher zum Aussteiger werden.<\/p> <p>Wer eine Unterkunft sucht, kann sein Dienste auf der Webseite anbieten ebenso nat\u00fcrlichQuadtra Vermieter. Es gibt keine Vermittlungsgeb\u00fchr, denn beide Parteien machen alle Bedingungen untereinander aus. Eintrag und Suche sind kostenlos, wer andere kontaktieren will, zahlt einen Minibeitrag f\u00fcr drei Monate. Kein Abo, keine versteckten Kosten.<\/p> <p>Hier die Webseite: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.mitwohnen.org\" title=\"Wohnen gegen Hilfe oder Minijob\" >http:\/\/www.mitwohnen.org<\/a><\/p> <p>Verlag und Betreiber diverser Reiseseiten und Jugendportale. Gr\u00fcndung 1984 mit dem Schwerpunkt des Buchprogramms auf Sachthemen wie Jobs, Praktika, Aupair, Freiwilligendiensten.<br \/> Ferner gibt es auch Reisef\u00fchrer und Reiseberichte, darunter den einzigen aktuellen Interrailf\u00fchrer auf dem deutschsprachigen Markt. In letzter Zeit wurde das Programm auch um Autobiographien erweitert.<\/p> <p>interconnections medien &amp; reise e.K.<br \/> Georg Beckmann<br \/> Schillerstr. 44<br \/> 79102 Freiburg<br \/> 0761 700 650<br \/> info@interconnections.de<br \/> http:\/\/interconnections.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Eine neue Idee erobert das Netz: Warum nicht Wohnraum anbieten gegen Dienstleistungen, ganz ohne oder mit sehr geringem finanziellen Aufwand?Der Rentner sucht jemanden, der die Eink\u00e4ufe erledigt, die Familie m\u00f6chte Ihren Nachwuchs betreuen lassen, wieder andere brauchen Hausmeisterdienste &#8211; Und sie alle haben Wohnraum. Was liegt da n\u00e4her, als das eine gegen das andere zu<\/p>\n","protected":false},"author":3,"featured_media":196613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[1734],"class_list":["post-145247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik-gesellschaft","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/145247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=145247"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/145247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/196613"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=145247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=145247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=145247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}