{"id":147175,"date":"2014-04-25T12:29:31","date_gmt":"2014-04-25T11:29:31","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=147175"},"modified":"2025-03-28T14:59:06","modified_gmt":"2025-03-28T13:59:06","slug":"das-umfeld-der-sucht","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/das-umfeld-der-sucht-10147175\/","title":{"rendered":"Das  Umfeld der Sucht"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-147790\" title=\"Sucht 3.0 - L\u00f6sungen f\u00fcr Co-Betroffene\" alt=\"Sucht 3.0 - L\u00f6sungen f\u00fcr Co-Betroffene\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/a62b3cd3d0d6e1bfd2a9a578afbca30f.jpg\" width=\"173\" height=\"129\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/a62b3cd3d0d6e1bfd2a9a578afbca30f.jpg\" \/>8.5 % aller Menschen sind s\u00fcchtig &#8211; Und diese Zahl ber\u00fccksichtigt nicht die immense Dunkelziffer, die zumindest mit den weicheren Drogen diese Zahl massiv erh\u00f6hen d\u00fcrfte. Angeh\u00f6rige und das n\u00e4here Umfeld wissen mit der Erkrankung oftmals nicht umzugehen. Eine neue Seminarreihe nimmt sich dieser Thematik an. &#8222;Sucht 3.0 &#8211; L\u00f6sungen f\u00fcr Co-Betroffene&#8220; bietet in verschiedensten Seminaren L\u00f6sungsstrategien mit individuellem Zuschnitt.<\/p> <p><!--more-->&#8211; Alkohol- und Nikotinkonsum in Berlin r\u00fcckl\u00e4ufig *<br \/> &#8211; Konsum illegaler Drogen steigt in der Hauptstadt *<br \/> &#8211; neues Seminar in Berlin zu L\u00f6sungen f\u00fcr Co-Betroffene von Suchtmittelabh\u00e4ngigen<\/p> <p>Sucht ist kein Ph\u00e4nomen, sondern eine jedem t\u00e4glich begegnende Krankheit. Rund 8,5 % aller Menschen sind s\u00fcchtig **, nicht gerechnet die Dunkelziffer riskant Konsumierender. Sucht verursacht immense wirtschaftliche Sch\u00e4den, von den zwischenmenschlichen ganz zu schweigen.<\/p> <p>Die Berliner Seminaranbieterin beredsam GmbH nimmt deshalb eine neue Seminarreihe ins Programm. Unter dem Namen \u201eSucht 3.0 &#8211; L\u00f6sungen f\u00fcr Co-Betroffene\u201c stehen f\u00fcr verschiedene Zielgruppen die Erarbeitung individueller L\u00f6sungsstrategien bereit.<\/p> <p>\u201eDie wenigsten erkennen, dass sie sich in einem Co-Betroffenen-Umfeld befinden\u201c, so Matthias Fink, Suchtberater und Verhaltenstherapeut, der eines der Seminare leitet. \u201eHat man erkannt, dass beispielsweise der Kollege am Nebentisch tablettenabh\u00e4ngig ist, gibt es auch Wege, damit umzugehen. Da Co-Betroffenheit in allen Lebenslagen anzutreffen ist, bietet die Dienstleisterin beredsam eine gute Plattform, auch unterschiedlich Interessierte anzusprechen.\u201c<\/p> <p>Das Thema in seiner kompletten und komplexen Breite steht so erstmalig allen interessierten Co-Betroffenen offen. Das Seminar zeigt Co-Betroffenen Wege und L\u00f6sungen, sich selbst besser zu sch\u00fctzen, Sucht \u00fcberhaupt zu erkennen und Handlungswege richtig zu bewerten. Das ist ein wichtiger Schritt zu einer Vorsorge, Sch\u00e4den von Familie oder Unternehmen abzuwehren.<\/p> <p>Was: Seminar \u201eSucht 3.0 &#8211; L\u00f6sungen f\u00fcr Co-Betroffene\u201c<br \/> Wann: Samstag, den 03.05.2014, 10:00 &#8211; 17:00 Uhr<br \/> Wo: beredsam GmbH, Bessemerstra\u00dfe 82, 10. OG Ostturm, 12103 Berlin<\/p> <p>Weitere Informationen: http:\/\/suchtberater.eu\/<br \/> Anmeldung unter: http:\/\/buchung.beredsam.de\/<\/p> <p>* Pressemitteilung der Berliner Senatsverwaltung f\u00fcr Gesundheit und Soziales vom 27.03.2014<br \/> ** Jahrbuch Sucht 2013<\/p> <p>&nbsp;<\/p> <p>Weiteres Pressematerial zu dieser Pressemitteilung:<\/p> <p>Sie k\u00f6nnen im Online-Pressefach schnell und einfach weiteres Bild- und<br \/> Textmaterial zur kostenfreien Verwendung downloaden:<\/p> <p>http:\/\/www.pr4you.de\/pressefaecher\/beredsam\/<\/p> <p>(1) beredsam GmbH<\/p> <p>Ansprechpartner: Robert Erler<\/p> <p>beredsam GmbH<br \/> Bessemerstra\u00dfe 82<br \/> D-12103 Berlin<\/p> <p>Telefon: +49 (0) 30 609 88 58 10<br \/> E-Mail: erler@beredsam.de<br \/> Internet: http:\/\/www.beredsam.de<\/p> <p>(2) PR-Agentur PR4YOU<\/p> <p>Ansprechpartner: Lukas Hecht, Marko Homann, Holger Ballwanz<\/p> <p>PR-Agentur PR4YOU<br \/> Schonensche Stra\u00dfe 43<br \/> D-13189 Berlin<\/p> <p>Telefon: +49 (0) 30 43 73 43 43<br \/> Fax: +49 (0) 30 44 67 73 99<br \/> E-Mail: presse@pr4you.de<br \/> Internet: http:\/\/www.pr4you.de<\/p> <p>\u00dcber die beredsam GmbH<\/p> <p>Die beredsam GmbH ist ein seit 2004 in Berlin ans\u00e4ssiges Dienstleistungsunternehmen, das heute in f\u00fcnf top ausgestatteten Seminarr\u00e4umen ein hauseigenes Workshop-Programm zu den Themen Kommunikation und Gesundheit anbietet. Die Seminarthemen sind ausgesucht und werden von ausgezeichneten Spezialisten l\u00f6sungsorientiert und dabei popul\u00e4r vorgetragen.<\/p> <p>Die Seminarr\u00e4ume der beredsam GmbH kann man f\u00fcr Trainings und Pr\u00e4sentationen mieten.<\/p> <p>Weitere Informationen: http:\/\/www.beredsam.de<\/p>","protected":false},"excerpt":{"rendered":"<p>8.5 % aller Menschen sind s\u00fcchtig &#8211; Und diese Zahl ber\u00fccksichtigt nicht die immense Dunkelziffer, die zumindest mit den weicheren Drogen diese Zahl massiv erh\u00f6hen d\u00fcrfte. Angeh\u00f6rige und das n\u00e4here Umfeld wissen mit der Erkrankung oftmals nicht umzugehen. Eine neue Seminarreihe nimmt sich dieser Thematik an. &#8222;Sucht 3.0 &#8211; L\u00f6sungen f\u00fcr Co-Betroffene&#8220; bietet in verschiedensten<\/p>\n","protected":false},"author":3,"featured_media":196603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-147175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/147175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=147175"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/147175\/revisions"}],"predecessor-version":[{"id":277251,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/147175\/revisions\/277251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/196603"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=147175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=147175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=147175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}