{"id":14778,"date":"2011-03-09T14:51:55","date_gmt":"2011-03-09T13:51:55","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=14778"},"modified":"2011-03-09T14:51:55","modified_gmt":"2011-03-09T13:51:55","slug":"emsland-zeigt-grunen-daumen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/emsland-zeigt-grunen-daumen-1014778\/","title":{"rendered":"Kontrastreiche Pflanzenwelt inspiriert Gartenfreunde"},"content":{"rendered":"<p>Meppen, 09.03.2011 &#8211; Im Emsland finden Hobbyg\u00e4rtner im Urlaub Anregungen f\u00fcr die Gestaltung des eigenen Gartens oder den Balkon. In der Region zwischen M\u00fcnster und Nordsee baut Europas gr\u00f6\u00dfter Pflanzenproduzent Emsflower jedes Jahr eine halbe Milliarde Schnittblumen, Balkon- und Gartenpflanzen sowie exotische Gew\u00e4chse an. Nur in die Meyer Werft in Papenburg str\u00f6men noch mehr Besucher als in das Besucherzentrum von Emsflower, wo sich jedes Jahr 300.000 Besucher \u00fcber neue Pflanzensorten informieren. <!--more-->Im Kontrast dazu stehen kleine und liebevoll angelegte Kr\u00e4uterh\u00f6fe und Bibelg\u00e4rten in der Region, die von engagierten Gartenexperten wie Ingrid Rosen in Geeste-Bramhar betrieben werden. In ihrem Caf\u00e9 h\u00e4lt sie Vortr\u00e4ge \u00fcber die Kr\u00e4uterkunde in Medizin und K\u00fcche und zeigt, wie die Urlauber Kr\u00e4utertee selbst herstellen k\u00f6nnen. Eine ganz andere Facette der Gartenbaukunst zeigt das Schloss Clemenswerth in S\u00f6gel, mit der weltweit einzigen noch erhaltenen sternf\u00f6rmig angelegten Schlossanlage aus dem Barock. Die Anlage lockt mit \u00fcppigen Buchsbaumhecken und weitl\u00e4ufigen Blumenrabatten. Weitere Informationen zu den G\u00e4rten im Emsland unter 05931\/442266 oder www.emsland.com.<\/p> <p>Emsflower &#8211; Erlebnisg\u00e4rtnerei zu jeder Jahreszeit<br \/> Im s\u00fcdlichen Emsland sorgt der Gartenbaugigant Emsflower daf\u00fcr, dass der heimische Balkon und Garten immer bunt ist. Die G\u00e4rtnerei beliefert Discounter wie Lidl und Aldi ebenso wie Obi und Hornbach und Superm\u00e4rkte von Portugal bis Finnland. Im Besucherzentrum werden neue Orchideensorten vorgestellt und getestet, wie gut sie bei den Gartenfreunden ankommen. Im exotischen Tropengarten flattern Papageien und Koi-Karpfen schwimmen in den Teichen. Im gro\u00dfen Stil produzieren auch die Gro\u00dfg\u00e4rtnereien in Papenburg, von hier stammen 90 Prozent der K\u00fcchenkr\u00e4uter und jede zweite Salatgurke, die man im Supermarkt findet. In Papenburg lohnt sich auch ein Abstecher zur Orchideenfarm Kasten, denn hier k\u00f6nnen Besucher eine gro\u00dfe Vielfalt an Orchideen bewundern und Feng-Shui-Atmosph\u00e4re genie\u00dfen, nach der ein Teil der Anlagen aufgebaut ist.<\/p> <p>Inspirierende Muster- und Bibelg\u00e4rten zum Innehalten<br \/> In Twist k\u00f6nnen Hobbyg\u00e4rtner im Garten des Nazareners verweilen und dessen Architektur bestaunen. Nach dem Vorbild mittelalterlicher Klosterg\u00e4rten sind die Pflanzen entlang eines kreuzf\u00f6rmig angeordneten Weges in vier &#8222;Quartieren&#8220; angeordnet. Im vorderen Teil des Gartens finden sich symbolische Pflanzen der Bibel, im hinteren Teil Beete der Klostermedizin. Im kleinen Bibelgarten Werlte k\u00f6nnen Gartenfreunde \u00fcber 80 verschiedene Pflanzenarten die vier angelegten Landschaften wie den Sch\u00f6pfungsgarten, den Garten der Verhei\u00dfung, den Ackergarten und die W\u00fcste bestaunen und in verschiedenen Ruhezonen innehalten. Pfiffige Ideen f\u00fcr die Gartendekoration finden Gartenfreunde au\u00dferdem in Borchers Idylle. Die Landschaftsg\u00e4rtnerei und Gastronomie in Surwold hat sich spezialisiert hat auf Ahorn sowie Funkien und bietet Hobbyg\u00e4rtnern ein sch\u00f6nes Ambiente aus Musterg\u00e4rten, Kunsthandwerk und kulinarischen K\u00f6stlichkeiten.<br \/> Das Emsland erstreckt sich von der nordrhein-westf\u00e4lischen Landesgrenze bei Rheine bis zur Grenze Ostfrieslands bei Papenburg und ist damit fl\u00e4chenm\u00e4\u00dfig der zweitgr\u00f6\u00dfte Landkreis der Bundesrepublik Deutschland, gr\u00f6\u00dfer als das Bundesland Saarland.<br \/> Emsland Touristik<br \/> Petra Rosenbach<br \/> Ordeniederung 1<br \/> 49716 Meppen<br \/> 05931\/442266<\/p> <p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.emsland.com\"  >www.emsland.com<\/a><\/p> <p>Pressekontakt:<br \/> ReCom PR GmbH<br \/> Thomas Rentschler<br \/> Herderplatz 5<br \/> 55124<br \/> Mainz<br \/> emsland@recompr.de<br \/> 06131-21632-11<br \/> http:\/\/www.recompr.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Meppen, 09.03.2011 &#8211; Im Emsland finden Hobbyg\u00e4rtner im Urlaub Anregungen f\u00fcr die Gestaltung des eigenen Gartens oder den Balkon. In der Region zwischen M\u00fcnster und Nordsee baut Europas gr\u00f6\u00dfter Pflanzenproduzent Emsflower jedes Jahr eine halbe Milliarde Schnittblumen, Balkon- und Gartenpflanzen sowie exotische Gew\u00e4chse an. Nur in die Meyer Werft in Papenburg str\u00f6men noch mehr Besucher<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8804],"tags":[],"class_list":["post-14778","post","type-post","status-publish","format-standard","hentry","category-reisen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/14778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=14778"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/14778\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=14778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=14778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=14778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}