{"id":1486,"date":"2009-07-12T09:02:58","date_gmt":"2009-07-12T08:02:58","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=1486"},"modified":"2010-11-26T12:00:57","modified_gmt":"2010-11-26T11:00:57","slug":"abtreibung-contra-vorgeburtlichen-vaterschaftstest","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/abtreibung-contra-vorgeburtlichen-vaterschaftstest-101486\/","title":{"rendered":"Abtreibung contra vorgeburtlichen Vaterschaftstest"},"content":{"rendered":"<p>Aus ethischen Gruenden lautet eine der Standardbegruendungen. Statt dessen kann es <img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1489\" title=\"vaterschaftstest.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/1486\/vaterschaftstest-150x150.jpg\" alt=\"vaterschaftstest.jpg\" width=\"150\" height=\"150\" \/>passieren, das der werdenden Mutter empfohlen wird eine Abtreibung vornehmen zu lassen, wenn sie sich nicht sicher sei, wer der biologische Vater ist. <!--more-->Das ist skandalverdaechtig aber was sind die Hintergruende?   Der Frauenarzt ist meist die erste Person, die von der werdenden Mutter kontaktiert wird, wenn es waehrend der Empfaengniszeit Verkehr mit mehr als einem Mann gab. Gemeinsam mit der Patientin versucht der Arzt dann den genauen Zeugungszeitpunkt zu berechnen, um den biologischen Vater zu ermitteln. Jedoch ist diese Methode sehr ungenau und das wissen die Beteiligten nur zu gut.  Wie sollte dies auch gehen, wenn es z.B. an einem Tag Verkehr mit zwei Maennern gab? Lebenslange Zweifel an der Vaterschaft sind dann nicht ausgeschlossen. Allzu oft endet das Arztgespraech mit der aerztlichen Empfehlung das Kind abtreiben zu lassen. Statt ein Leben lang die Ungewi\u00dfheit der Frage der Vaterschaft zu ertragen, empfiehlt der Arzt eine Abtreibung. Das ist moeglicherweise der Weg des geringsten Widerstands aber ist das die Art Ethik, die man in Deutschland, einem Hochmoralland, vertritt? Wird nicht auf allen Plattformen zum Erhalt von Leben aufgerufen und hier soll es auf aerztlichen Rat vernichtet werden?   Immer mehr Frauen aber wissen um die Moeglichkeit eines praenatalen Vaterschaftstests und befragen den Arzt danach. Wenn man einen solchen Vaterschaftstest vor der Geburt ausfuehren lae\u00dft, kann man ganz sicher herausfinden, welcher Mann der wahre biologische Vater ist. Das 100 prozentige Risiko, so wie es der Arzt durch eine Abtreibung beschwoert, sinkt dann statistisch betrachtet auf eine Risiko von nur 20 %. In allen Abstammungstestlaboratorien scheint es naemlich ein konstantes Verhaeltnis von Vaterschaftsbestaetigungen zu Vaterschaftsausschluessen zu geben, so werden von 10 getesteten Maenner nur zwei von der Vaterschaft ausgeschlossen. Fuer acht der 10 getesteten Maennern wird die Vaterschaft dann bestaetigt. Die Zahlen sprechen also ganz klar fuer den Erhalt des ungeborenen Lebens durch einen praenatalen Abstammungstest.   Warum also empfehlen \u00c4rzte eine Abtreibung, wenn man mit einem vorgeburtlichen Test Leben retten kann? Eine rationale Erklaerung scheint es dazu nicht zu geben. Schon alleine dann nicht, wenn man sich ansieht, wie die \u00c4rzteschaft in anderen Laendern mit diesem Problem umgeht. In \u00d6sterreich, Holland oder den ueberwiegend katholischen Laendern Polen und Italien raten die \u00c4rzte zu einem praenatalen Vaterschaftstest, wenn sich die Mutter unsicher ist, welcher Mann der Vater ist. Handelt es sich bei den Ursachen um ein falsch verstandenes Moralempfinden, um ueberkommene Riten der \u00c4rzteschaft oder ist es so, wie man in Deutschland immer glauben machen moechte: alle anderen machen es falsch und nur in Deutschland beschreitet man den richtigen Pfad? Eine Antwort auf diese Frage kann hier leider nicht gegeben werden. Die Fakten aber sprechen gegen eine Abtreibung. Wenn das vorgeschobene Argument der Ethik bei der Patientin nicht greift, schwenkt der Arzt oft auf das Argument um, dass man eine Probe (Fruchtwasser oder Chorionzotten) nur entnehmen koenne, wenn es eine medizinische Indikation gaebe. Eine medizinische Indikation laege vor, wenn es ein hoeheres Risiko fuer eine genetische Erkrankung des Ungeborenen gaebe, z.B. wenn die Summe des Alters von Mutter und Vater groe\u00dfer als 70 Jahre sei, in diesem Fall koenne man dann neben der genetischen Untersuchung auf Krankheiten auch eine DNA-Abstammungsanalyse mit der entnommenen Probe ausfuehren. Weitere Informationen finden Sie auf unserer Website unter: http:\/\/www.bj-diagnostik.de\/news.php?id=46<\/p> <p>bj diagnostik GmbH<br \/> Kerkrader Stra\u00dfe 11<br \/> D-35394 Gie\u00dfen                           vertreten durch den Gesch\u00e4ftsf\u00fchrer:<br \/> Dr. Michael Jung<\/p>","protected":false},"excerpt":{"rendered":"<p>Aus ethischen Gruenden lautet eine der Standardbegruendungen. Statt dessen kann es passieren, das der werdenden Mutter empfohlen wird eine Abtreibung vornehmen zu lassen, wenn sie sich nicht sicher sei, wer der biologische Vater ist.<\/p>\n","protected":false},"author":291,"featured_media":199035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familie-jugend-familie"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/1486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/199035"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=1486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=1486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}