{"id":14883,"date":"2011-03-10T10:06:36","date_gmt":"2011-03-10T09:06:36","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=14883"},"modified":"2011-03-10T10:07:04","modified_gmt":"2011-03-10T09:07:04","slug":"platin-award-punktzahl","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/platin-award-punktzahl-1014883\/","title":{"rendered":"Das Jahr der Preise"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"94\" height=\"120\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14886\" title=\"Kuenssberg_Iv_cmy_zug_web.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/14883\/Kuenssberg_Iv_cmy_zug_web-233x300.jpg\" alt=\"\" width=\"96\" height=\"120\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Bester Spezial-Distributor Deutschlands zeigt auf der CeBIT 2011 Remote-Management- und Online-Backup-L\u00f6sung sowie Antivirus<br \/> Hannover, 09. M\u00e4rz 2011.- acmeo cloud-distribution aus Hannover wurde zum besten Spezial-Distributor Deutschlands gew\u00e4hlt. Damit hat acmeo 2010 mehr Preise eingeheimst, als der Newcomer Jahre z\u00e4hlt. Auf der CeBIT 2011 pr\u00e4sentiert acmeo die Produkte GFI MAX Remote Management, GFI MAX Mail, acmeo Online Backup und acmeo Antivirus in der Planet Reseller Area.<br \/> <!--more-->Mehr als 1400 Leser der Fachzeitschrift IT-BUSINESS w\u00e4hlten acmeo cloud-distribution aus Hannover zum besten Spezial-Distributor, der die Auszeichnung &#8222;Most Preferred Platin Award&#8220; erhielt. Fachhandels- und Systemhauspartner hatten acmeo die meisten Punkte gegeben und honorierten damit den Service, das Preis-Leistungsverh\u00e4ltnis und die Beratungskompetenz, die der Distributor seinen Partnern bietet. Kategorie\u00fcbergreifend erreichte acmeo mit der Note 1,55 die beste Bewertung von allen.<br \/> \u201e2010 war f\u00fcr uns das Jahr der Preise\u201c, strahlt Isabelle von K\u00fcn\u00dfberg, Vertriebsleiterin bei acmeo. \u201eNachdem wir den Wettbewerb um den Titel \u201aaktivster GFI MAX Remote-Management Distributor 2010\u2018 gegen zahlreiche Mitbewerber klar f\u00fcr uns entscheiden konnten, war der erste Preis als Spezial-Distributor eine Best\u00e4tigung unserer Leitlinie, die Partner nach Kr\u00e4ften mit Beratungskompetenz und Service zu unterst\u00fctzen.\u201c Das Ziel, die Kunden stark und erfolgreich zu machen, erreicht acmeo durch Seminare und effektive Akquise-Unterst\u00fctzung.<br \/> Reseller, Systemh\u00e4user und Integratoren, Fachh\u00e4ndler und Online-Anbieter w\u00e4hlen jedes Jahr in der gemeinsamen Leserumfrage von IT BUSINESS und dem Marktforschungsinstitut IDC die besten Distributoren des Landes. Bewertet werden die Leistungen in den f\u00fcnf Kategorien Broadliner, Peripherie- und Komponenten-Distributor, Spezial-Distributor, TK Distributor und Value Added Distributor.<\/p> <p>Als Newcomer in einem von etablierten Distributoren dominierten Markt hat acmeo seit der Gr\u00fcndung 2009 konsequent auf den Zukunftsmarkt der Cloud-Produkte gesetzt und inzwischen \u00fcber 600 Systemh\u00e4user in Deutschland, \u00d6sterreich und der Schweiz \u00fcberzeugt. \u201eWir liefern n\u00e4mlich nicht nur erstklassige Marketing- und Vertriebsunterst\u00fctzung\u201c, erkl\u00e4rt Isabelle von K\u00fcn\u00dfberg den Erfolg, \u201esondern wir verstehen das Business unserer Partner, da das Kern-Team der acmeo einen Systemhaus-Hintergrund hat!\u201c Zur CeBIT 2011 hat acmeo cloud-distribution den Partnern VIP-Parkpl\u00e4tze, Eintrittskarten und Einladungen zum Fr\u00fchst\u00fcck geschenkt.<br \/> acmeo ist Spezial-Distributor f\u00fcr die besten White-Label-SaaS\/Cloud-L\u00f6sungen f\u00fcr IT-Systemh\u00e4user und gr\u00f6\u00dfter GFI MAX Distributor im deutschsprachigen Raum. acmeo unterst\u00fctzt IT-Systemh\u00e4user bei der Integration der IT-Monitoring &amp; -Managementl\u00f6sungen, Email-Schutz und -archivierung, managed AntiVirus, CRM, Centrex, Webfilter und OnlineBackup in das Portfolio von Service- und Wartungsvertr\u00e4gen und Managed Services. www.acmeo.eu<br \/> &#8212;&#8212;&#8211;<br \/> Kurzprofil<br \/> Der Spezial-Distributor acmeo cloud-distribution vertreibt innovative White-Label-SaaS-L\u00f6sungen an mittelst\u00e4ndische IT-Systemh\u00e4user in D-A-CH (Deutschland, \u00d6sterreich und Schweiz). Als Newcomer in einem von etablierten Distributoren dominierten Markt hat acmeo konsequent auf den Zukunftsmarkt Cloud-Produkte gesetzt. Der Distributor unterst\u00fctzt seine Partner bei der Vermarktung mit Seminaren zu Themen wie \u201eErfolgreicher Vertrieb von Managed Services\u201c, \u201eErfolgsfaktoren im Systemhaus\u201c und \u201eNeukundenakquisition\u201c. Au\u00dferdem stellt acmeo ihnen Marketing- und Vertragsunterlagen und ein CallCenter f\u00fcr die Akquise zur Verf\u00fcgung.<br \/> Im Oktober 2009 gegr\u00fcndet, w\u00e4chst das junge Unternehmen stetig. Ende 2010 w\u00e4hlten die Leser der Fachzeitung &#8222;IT-Business&#8220; acmeo zum besten &#8222;Spezial-Distributor&#8220;. Den Wettbewerb um den Titel \u201eaktivster GFI MAX Remote-Management Distributor 2010\u201c hatte acmeo mit Beratungskompetenz und Service gegen Mitbewerber aus EMEA (Europa, Mittlerer Osten, Afrika) ebenfalls klar f\u00fcr sich entschieden. Ein gro\u00dfer Erfolg war der erste Platz in der Kategorie &#8222;Beste Software&#8220;, verliehen von der CRN im November 2010 in London f\u00fcr den von acmeo vermarkteten GFI MAX (der vor Oracle und Microsoft siegte). www.acmeo.de<br \/> &#8212;&#8212;-<br \/> Kontakt:<br \/> acmeo cloud-distribution GmbH &amp; Co. KG<br \/> Expo Plaza 3<br \/> D-30539 Hannover<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.acmeo.eu\"  >www.acmeo.eu<\/a><br \/> Telefon +49 (511) 515151-0<br \/> Pressekontakt:<br \/> Sabine Faltmann<br \/> faltmann PR | \u00d6ffentlichkeitsarbeit f\u00fcr IT-Unternehmen<br \/> Theaterstra\u00dfe 15<br \/> 52062 Aachen<br \/> Telefon +49.241.43537484<\/p>","protected":false},"excerpt":{"rendered":"<p>Bester Spezial-Distributor Deutschlands zeigt auf der CeBIT 2011 Remote-Management- und Online-Backup-L\u00f6sung sowie Antivirus Hannover, 09. M\u00e4rz 2011.- acmeo cloud-distribution aus Hannover wurde zum besten Spezial-Distributor Deutschlands gew\u00e4hlt. Damit hat acmeo 2010 mehr Preise eingeheimst, als der Newcomer Jahre z\u00e4hlt. Auf der CeBIT 2011 pr\u00e4sentiert acmeo die Produkte GFI MAX Remote Management, GFI MAX Mail, acmeo<\/p>\n","protected":false},"author":291,"featured_media":198458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-14883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-handel-gewerbe"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/14883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=14883"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/14883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198458"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=14883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=14883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=14883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}