{"id":1581,"date":"2009-07-27T08:18:52","date_gmt":"2009-07-27T07:18:52","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=1581"},"modified":"2010-07-26T14:20:18","modified_gmt":"2010-07-26T13:20:18","slug":"wanderatlas-fur-den-westerwald-routen-konnen-direkt-auf-gps-gerate-geladen-werden","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wanderatlas-fur-den-westerwald-routen-konnen-direkt-auf-gps-gerate-geladen-werden-101581\/","title":{"rendered":"Wanderatlas f\u00fcr den Westerwald: Routen k\u00f6nnen direkt auf GPS-Ger\u00e4te geladen werden"},"content":{"rendered":"<p>Jeder vierte Deutsche ist gerne und regelm\u00e4\u00dfig zu Fu\u00df unterwegs in der Natur.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1584\" title=\"wanderatlas-logo_farbe_220x99.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/1581\/wanderatlas-logo_farbe_220x99-150x101.jpg\" alt=\"wanderatlas-logo_farbe_220x99.jpg\" width=\"150\" height=\"101\" \/> Ob als Nordic Walker, Wanderer oder Tagesausfl\u00fcgler: Wandern liegt im Trend. Dennoch findet man bislang im Internet nur sp\u00e4rlich zuverl\u00e4ssige Informationen, um eine Wanderung zu planen. Das soll sich jetzt \u00e4ndern. Mit dem Wanderatlas Deutschland, der im Internet unter der Adresse www.ich-geh-wandern.de ab sofort kostenfrei zur Verf\u00fcgung steht.<!--more--><\/p> <p>Der Wanderatlas Deutschland ist eine offene Internet-Plattform, auf der Wanderer ihre Erfahrungen ver\u00f6ffentlichen k\u00f6nnen und somit anderen Wanderern helfen, sich besser vorzubereiten. Das Grundprinzip des Wanderatlas Deutschland erinnert an das Internet-Lexikon Wikipedia: Jeder kann Informationen bereitstellen, die sofort f\u00fcr alle anderen verf\u00fcgbar sind.<\/p> <p>Um eine Wanderung im Wanderatlas Deutschland zu ver\u00f6ffentlichen, braucht man eine elektronische Wegbeschreibung, einen so genannten GPS-Track. GPS-Tracks k\u00f6nnen mit speziellen Ger\u00e4ten (ab 40 Euro) oder auch schon mit vielen Mobiltelefonen aufgezeichnet werden. Diese GPS-Technologie ist vor allem bei J\u00fcngeren beliebt, die damit z.B. die moderne Schnitzeljagd Geocaching betreiben.<\/p> <p>Hat man einen entsprechenden GPS-Track, l\u00e4dt man diesen auf der Internetseite www.ich-geh-wandern.de und sieht dann eine Karte mit der fertig eingezeichneten Wanderung am Bildschirm. Man kann jetzt die Wanderung aus seiner pers\u00f6nlichen Sicht beschreiben, sie kategorisieren und Bilder hinzuf\u00fcgen. Fertig. Jetzt ist die Wanderung online im Internet verf\u00fcgbar.<\/p> <p>Andere Wanderer, die z.B. nicht direkt aus dem Umland kommen, k\u00f6nnen aus erster Quelle lesen, ob sich der Weg lohnt, auf was man achten sollte und wie der Weg beschaffen ist. Sie erhalten au\u00dferdem ein H\u00f6henprofil und die exakte Wegstreckenl\u00e4nge \u2013 diese Daten ermittelt der Wanderatlas Deutschland automatisch auf Basis des GPS-Tracks. Und schlie\u00dflich kann man jetzt mit einem Klick die gesamte Wanderung aus dem Internet auf sein Navigationsger\u00e4t laden. So hat man die Wegbeschreibung am Mann, wenn man zu einer Tour aufbricht.<\/p> <p>Die Wanderstrecken werden im Wanderatlas Deutschland erg\u00e4nzt durch touristische Informationen zu Ausflugszielen und Sehensw\u00fcrdigkeiten, die die Wanderatlas-Redaktion beisteuert.<\/p> <p>Der Wanderatlas Deutschland ist derzeit in der Pilotphase. Die erste Zielregion, die innerhalb dieser Pilotphase bearbeitet wird, ist der Westerwald, der in sieben unterschiedliche Wanderregionen eingeteilt worden ist. Der Hessische Westerwald von Haiger bis Hadamar, der Hohe Westerwald um Rennerod, Bad Marienberg und Westerburg und der Obere Westerwald mit der Kroppacher Schweiz, der Westerw\u00e4lder Seenplatte und dem Sayntal sind bereits ver\u00f6ffentlicht.<\/p> <p>In den n\u00e4chsten Wochen erscheinen noch das Kannenb\u00e4ckerland (ab Anfang August), der Lahn-Westerwald mit dem Naturpark Nassau (ab Ende August), der Rhein-Westerwald (ab Mitte September) und der Sieg-Westerwald (ab Anfang Oktober).<\/p> <p>Der Wanderatlas Deutschland l\u00e4dt alle Wanderer, Spazierg\u00e4nger und Nordic Walker im Westerwald ein, ab sofort Wegempfehlungen im Internet unter www.ich-geh-wandern.de zu ver\u00f6ffentlichen. Auch Kommentare und Anregungen zu den Informationstexten sind herzlich willkommen.<\/p> <p>(Beselich, 27. Juli 2009)<\/p> <p>Heiko Rutenbeck, Steinbacher Stra\u00dfe 24, 65614 Beselich.<br \/> ViSdP: Dr. Thomas Becker (Chefredakteur), Albrechtstra\u00dfe 51, 12103 Berlin<\/p> <p><a href=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/1581\/wanderatlas-logo_farbe_220x99.jpg\"><br \/> <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Jeder vierte Deutsche ist gerne und regelm\u00e4\u00dfig zu Fu\u00df unterwegs in der Natur. Ob als Nordic Walker, Wanderer oder Tagesausfl\u00fcgler: Wandern liegt im Trend. Dennoch findet man bislang im Internet nur sp\u00e4rlich zuverl\u00e4ssige Informationen, um eine Wanderung zu planen. Das soll sich jetzt \u00e4ndern. Mit dem Wanderatlas Deutschland, der im Internet unter der Adresse www.ich-geh-wandern.de<\/p>\n","protected":false},"author":291,"featured_media":199028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8804],"tags":[],"class_list":["post-1581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reisen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/1581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=1581"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/1581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/199028"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=1581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=1581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=1581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}