{"id":15983,"date":"2011-03-24T12:37:43","date_gmt":"2011-03-24T11:37:43","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=15983"},"modified":"2012-07-02T14:21:08","modified_gmt":"2012-07-02T13:21:08","slug":"meisterschaft-haushalts-fuenfkampf","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/meisterschaft-haushalts-fuenfkampf-1015983\/","title":{"rendered":"Deutsche Meisterschaft im Modernen Haushalts-F\u00fcnfkampf"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"73\" height=\"120\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15986\" title=\"leifheit.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/15983\/leifheit-201x300.jpg\" alt=\"\" width=\"98\" height=\"141\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Daniel Peetz will die deutsche Meisterschaft im Haushalts-F\u00fcnfkampf gewinnen<\/p> <p>Daniel Peetz aus Rheinberg will das Double: Der 29-j\u00e4hrige Bundeswehroffizier, der im vergangenen Jahr mit \u00fcber 58 Stunden einen neuen Weltrekord im Dauerb\u00fcgeln aufstellte, peilt jetzt einen weiteren Titel an. Gemeinsam mit seiner Lebensgef\u00e4hrtin, der Rechtsanwaltsgehilfin Yvonne Closta (25), will Peetz die deutsche Meisterschaft im Modernen Haushalts-F\u00fcnfkampf von Leifheit gewinnen. Die beiden sind eines von acht Paaren, die am 11. April in K\u00f6ln im Finale des Wettbewerbs gegeneinander antreten.<\/p> <p><!--more-->food-pressedienst, Hamburg. \u201eAls B\u00fcgelweltrekordhalter war es f\u00fcr mich selbstverst\u00e4ndlich, an diesem Wettbewerb teilzunehmen\u201c, erkl\u00e4rt Peetz seine Motivation. Da fiel es auch nicht schwer, Partnerin Yvonne zu \u00fcberzeugen. Den ersten Schritt zum Titelgewinn hat das Paar bereits absolviert. Unter mehr als 1.500 Bewerbern konnten sie sich f\u00fcr den Finalwettkampf qualifizieren. Dort m\u00fcssen die beiden nun ihre Vielseitigkeit unter Beweis stellen. Denn B\u00fcgeln ist nur eine der f\u00fcnf Disziplinen: Auch beim Bodenwischen, Fensterputzen, W\u00e4scheaufh\u00e4ngen sowie bei der Zubereitung von Sushi-R\u00f6llchen f\u00fcr das kalte B\u00fcffet werden sich die Paare untereinander messen. Dabei kommt es vor allem aufs Teamwork an. Organisiert wird der Wettbewerb von Leifheit, dem Spezialisten f\u00fcr clevere Haushaltsprodukte.<\/p> <p>\u201eWir beide geben unser Bestes, um m\u00f6glichst weit vorne zu landen\u201c, so Peetz. F\u00fcr Motivation sorgt nicht nur der Titel, sondern auch attraktive Preise, die vom Reiseanbieter ITS bereitgestellt werden.<br \/> www.leifheit.de<\/p> <p>Unternehmenskontakt:<\/p> <p>Leifheit AG<\/p> <p>Katrin Lauer<\/p> <p>Leifheitstra\u00dfe 1, 56377 Nassau,<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Daniel Peetz will die deutsche Meisterschaft im Haushalts-F\u00fcnfkampf gewinnen Daniel Peetz aus Rheinberg will das Double: Der 29-j\u00e4hrige Bundeswehroffizier, der im vergangenen Jahr mit \u00fcber 58 Stunden einen neuen Weltrekord im Dauerb\u00fcgeln aufstellte, peilt jetzt einen weiteren Titel an. Gemeinsam mit seiner Lebensgef\u00e4hrtin, der Rechtsanwaltsgehilfin Yvonne Closta (25), will Peetz die deutsche Meisterschaft im Modernen<\/p>\n","protected":false},"author":291,"featured_media":198400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,16],"tags":[],"class_list":["post-15983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-sonstiges","category-event-entertainment-lifestyle"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/15983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=15983"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/15983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198400"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=15983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=15983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=15983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}