{"id":163,"date":"2008-04-07T08:45:15","date_gmt":"2008-04-07T07:45:15","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/professionelle-blogger-leiden-unter-permanentem-stress\/"},"modified":"2010-07-26T14:23:11","modified_gmt":"2010-07-26T13:23:11","slug":"professionelle-blogger-leiden-unter-permanentem-stress","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/professionelle-blogger-leiden-unter-permanentem-stress-10163\/","title":{"rendered":"Professionelle Blogger leiden unter permanentem Stress"},"content":{"rendered":"<p><strong>Erfolgsabh\u00e4ngige Bezahlung steigert den Druck<br \/> <\/strong><br \/> #Flexible Arbeitszeiten bedeuten f\u00fcr viele eine gro\u00dfe Belastung (Foto: pixelio.de, K. Gerhardt)<br \/> New York (pte\/07.04.2008\/06:15) &#8211; Eine beachtliche Zahl an Weblogs wird inzwischen von bezahlten Autoren verfasst. Sie befassen sich in ihren Onlinepublikationen mit aktuellen Neuigkeiten aus diversen Themenbereichen. Die so genannten Blogger stehen jedoch unter andauerndem Druck, der sich auch auf ihre Gesundheit und Lebensqualit\u00e4t niederschl\u00e4gt, berichtet die New York Times. <!--more-->Wie viele Blogger gegen Bezahlung arbeiten, ist unklar. Sch\u00e4tzungen reichen von einigen Tausend bis hin zu Zehntausenden. Aktuell gibt auch das fr\u00fche Ableben der beiden US-Blogger Marc Orchant und Russel Shaw im Alter von 50 und 60 Jahren Grund zur Annahme, dass beruflicher Stress mit ihrem Tod zu tun haben k\u00f6nnte.<\/p> <p>Ein Problem, unter dem viele Blogger leiden, ist die Verschmelzung von Arbeitsplatz und Wohnung. Die meisten Weblog-Autoren erledigen ihre Arbeit nicht in einem B\u00fcro, sondern zu Hause. Die daraus entstehenden ungeregelten Arbeitszeiten f\u00fchren oft zu dem Gef\u00fchl, keine Freizeit zu haben. Au\u00dferdem ist es essenziell, Neuigkeiten m\u00f6glichst schnell zu ver\u00f6ffentlichen. Wer zuerst interessante Berichte liefert, kann auch mit einer h\u00f6heren Anzahl an Klicks und damit auch mit einem gr\u00f6\u00dferen Interesse von Werbekunden rechnen. Dieser Druck, sich in einem niemals enden wollenden Informationsfluss zu befinden, \u00fcber den es zu berichten gilt, f\u00fchrt bei vielen zu gesundheitlichen Problemen. Viele klagen \u00fcber Gewichtszu- oder -abnahme, Schlafst\u00f6rungen oder Ersch\u00f6pfung.<\/p> <p>Ein Faktor, der den Druck auf professionelle Blogger noch erh\u00f6ht, ist die Bezahlung. F\u00fcr einige kann ihr Weblog zu einer lukrativen Einnahmequelle werden, andere bekommen lediglich zehn Dollar pro Beitrag, was sie zu einem gro\u00dfen Output an Artikeln zwingt. Wer Blogs f\u00fcr gr\u00f6\u00dfere Seiten schreibt, verdient zu Beginn ungef\u00e4hr 30.000 Dollar pro Jahr und kann sich zu einem Einkommen von 70.000 Dollar hocharbeiten. Einige Unternehmer haben sich auch selbst kleine Blog-Imperien aufgebaut, mit denen sie sogar mehrere tausend Dollar im Monat verdienen. Viele andere k\u00f6nnen froh sein, wenn sie die 1.000-Dollar-Grenze nicht unterschreiten. (Ende)<\/p> <p>Aussender: pressetext.austria<br \/> Redakteur: Kristina Sam<br \/> email: sam@pressetext.com<br \/> Tel. +43-1-81140-319<\/p>","protected":false},"excerpt":{"rendered":"<p>Erfolgsabh\u00e4ngige Bezahlung steigert den Druck #Flexible Arbeitszeiten bedeuten f\u00fcr viele eine gro\u00dfe Belastung (Foto: pixelio.de, K. Gerhardt) New York (pte\/07.04.2008\/06:15) &#8211; Eine beachtliche Zahl an Weblogs wird inzwischen von bezahlten Autoren verfasst. Sie befassen sich in ihren Onlinepublikationen mit aktuellen Neuigkeiten aus diversen Themenbereichen. Die so genannten Blogger stehen jedoch unter andauerndem Druck, der sich<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-163","post","type-post","status-publish","format-standard","hentry","category-computer-und-videospiele"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/163\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}