{"id":16896,"date":"2011-04-06T08:47:26","date_gmt":"2011-04-06T07:47:26","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=16896"},"modified":"2011-04-06T08:47:26","modified_gmt":"2011-04-06T07:47:26","slug":"psp-user","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/psp-user-1016896\/","title":{"rendered":"Neuer Zauberkasten f\u00fcr die PSP"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16899\" title=\"SU320-PSP_FR_2.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/16896\/SU320-PSP_FR_2.jpg\" alt=\"\" width=\"135\" height=\"114\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Der neue Zauberkasten von ViTecco bringt das Bild der PSP* formatf\u00fcllend auf einen Flach-TV.<br \/> Das macht so richtig Spa\u00df!<\/p> <p>Der SU 320-PSP, so hei\u00dft das ViTecco-Ger\u00e4t, wird ganz einfach zwischen die PSP und den Flach-Fernseher gesteckt, fertig. Das Spezial-Kabel wird mitgeliefert, die Stromversorgung erfolgt \u00fcber ein eingebautes 230 V-Netzteil.<\/p> <p><!--more-->* PSP 2000, PSP 3000 und PSP-GO<\/p> <p>ViTecco ist ein inhabergef\u00fchrtes, mittelst\u00e4ndisches Unternehmen, welches bereits 1968 als Eicke &amp; Bemmerer von den Namensgebern gegr\u00fcndet wurde und seither in den Bereichen Entwicklung, Herstellung, Vertrieb und Service von Video-Elektronik-Produkten f\u00fcr die Unterhaltungselektronik, f\u00fcr die Video-Pr\u00e4sentation und f\u00fcr technisches Fernsehen spezialisiert hat.<\/p> <p>Wir von ViTecco liefern die Probleml\u00f6ser in den Bereichen Heim-Video \/ Heim-Kino \/ Hobby-Film, Videoanlagen in Industrie, Handel und Gewerbe sowie bei Schulen und Beh\u00f6rden und in der Medizintechnik, Video-\u00dcberwachung, Pr\u00e4sentationstechnik (als Unterhaltung oder Info) bei Veranstaltungen, in Verkaufsr\u00e4umen, Wettb\u00fcros, sky-sportsbars oder in der Kneipe nebenan &#8230; \u00fcberall dort, wo Videosignale verteilt und \/ oder geschaltet werden sollen:<br \/> Schalter, Verteiler, Trennstufe, Konverter, HDMI Verteiler, HDMI Schalter, Signalwandler, Kreuzschiene, Kopierverst\u00e4rker usw.<\/p> <p>Aufgrund der eigenen Entwicklung und Fertigung sind wir in der Lage marktgerechte Produkte sowie absolut hochwertige Qualit\u00e4t zu liefern und durch unseren End-Of-Life-Support auch \u00fcber Jahrzehnte (!) zu sichern.<\/p> <p>&nbsp;<\/p> <p>Impressum:<br \/> ViTecco GmbH<br \/> B\u00fcntefeldstra\u00dfe 25<br \/> D-30952 Ronnenberg<\/p> <p>Tel.: 0511 &#8211; 2200 705-0<br \/> Fax 0511 &#8211; 2200 705-99<\/p> <p>E-Mail: info@ViTecco.de<br \/> Internet: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.ViTecco.de\"  >www.ViTecco.de<\/a><\/p> <p>Abdruck honorarfrei<\/p>","protected":false},"excerpt":{"rendered":"<p>Der neue Zauberkasten von ViTecco bringt das Bild der PSP* formatf\u00fcllend auf einen Flach-TV. Das macht so richtig Spa\u00df! Der SU 320-PSP, so hei\u00dft das ViTecco-Ger\u00e4t, wird ganz einfach zwischen die PSP und den Flach-Fernseher gesteckt, fertig. Das Spezial-Kabel wird mitgeliefert, die Stromversorgung erfolgt \u00fcber ein eingebautes 230 V-Netzteil.<\/p>\n","protected":false},"author":291,"featured_media":16899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-16896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handy-elektronik-telekommunikation"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/16896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=16896"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/16896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/16899"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=16896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=16896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=16896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}