{"id":173400,"date":"2015-01-13T18:28:26","date_gmt":"2015-01-13T17:28:26","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=173400"},"modified":"2025-09-12T10:04:18","modified_gmt":"2025-09-12T09:04:18","slug":"pegida-no-pegida","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/pegida-no-pegida-10173400\/","title":{"rendered":"Pegida &#8211; No Pegida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-173403\" title=\"alte Streotype in neuem Gewand?\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/e8b675768f25b2c884bac8c4122b0fcd.jpg\" alt=\"islamophobie-im-netz\" width=\"129\" height=\"129\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/e8b675768f25b2c884bac8c4122b0fcd.jpg\" \/>Pegida, No Pegida, das Attentat auf die Redaktion des Satiremagazins Charlie Hebdo und zahlreiche weitere Ausschreitungen rund um den Globus haben eines gemein: &#8222;Gruppenbezogene Menschenfeindlichkeit&#8220;<\/p> <p>Unruhen, Demonstrationen und Gegendemonstrationen bewegen derzeit nicht nur Deutschland. Seit dem Anschlag auf die Redaktion des franz\u00f6sischen Satiremagazins Charlie Hebdo wechseln hitzige Diskussionen mit pathetischen Parolen und verunsicherten Fragen in der Presselandschaft und den sozialen Netzwerken. Nicht selten polarisieren die Meinungen, werden Vorurteile angefacht oder alles \u00fcber einen Kamm geschoren. <!--more-->So manch einer kommt nicht umhin, an den Geschichtsunterricht oder die Erz\u00e4hlungen der Eltern und Gro\u00dfeltern zu denken. Schon 2008 wurde &#8222;Was unseren V\u00e4tern der Jud ist f\u00fcr uns die Moslembrut seid auf der Hut!&#8220; auf die Au\u00dfenmauern einer Gedenkst\u00e4tte in Mauthausen geschmiert, die Zuspitzung der Ereignisse beunruhigt nicht nur die Menschen auf der Stra\u00dfe.<\/p> <p>Dies ist das Thema, mit dem sich der P\u00e4dagogik-Professor Wilhelm Heitmeyer im Rahmen einer Langzeitforschung besch\u00e4ftigt hat. Um den aktuellen Geschehnissen zu zollen und f\u00fcr alle, die sich mit den Mechanismen, die hinter Fremdenfeindlichkeit und der sogenannten Islamophobie stecken, besch\u00e4ftigen um so Wege aus der feindseligen Haltung zu finden, m\u00f6chten wir Ihnen diese Lekt\u00fcre ans Herz legen:<\/p> <p>www.fachzeitungen.de\/ebook-islamophobie-im-netz<\/p> <p>www.fachzeitungen.de\/ebook-islamophobie-oesterreich<\/p> <p>Nat\u00fcrlich finden Sie auch noch viele weitere Publikationen in unserem Shop, die die Thematik von allen Seiten beleuchten.<\/p> <p>Durch das Attentat auf das Satiremagazin Charlie Hebdo ist eine Diskussion um rechtliche und moralische Aspekte der satirischen Darstellung entbrannt. Dieses eBook beleuchtet die Frage nach der Freiheit und den Grenzen der Macher von Satire:\u00a0https:\/\/www.fachzeitungen.de\/ebook-persoenlichkeitsrechtliche-grenzen-der-satirischen-bildbearbeitung <\/p> <p>Lehnert &#8211; Mainstr. 85 &#8211; 41469 Neuss<\/p> <p>&nbsp;<\/p> <p>&nbsp;<\/p> <p>&nbsp;<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Pegida, No Pegida, das Attentat auf die Redaktion des Satiremagazins Charlie Hebdo und zahlreiche weitere Ausschreitungen rund um den Globus haben eines gemein: &#8222;Gruppenbezogene Menschenfeindlichkeit&#8220; Unruhen, Demonstrationen und Gegendemonstrationen bewegen derzeit nicht nur Deutschland. Seit dem Anschlag auf die Redaktion des franz\u00f6sischen Satiremagazins Charlie Hebdo wechseln hitzige Diskussionen mit pathetischen Parolen und verunsicherten Fragen in<\/p>\n","protected":false},"author":1,"featured_media":196506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7472],"tags":[],"class_list":["post-173400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ebooks-und-fachzeitschriften-zum-aktuellen-zeitgeschehen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/173400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=173400"}],"version-history":[{"count":6,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/173400\/revisions"}],"predecessor-version":[{"id":277840,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/173400\/revisions\/277840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/196506"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=173400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=173400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=173400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}