{"id":17673,"date":"2011-04-18T09:35:18","date_gmt":"2011-04-18T08:35:18","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=17673"},"modified":"2013-06-04T11:06:22","modified_gmt":"2013-06-04T10:06:22","slug":"gmbh-osterfest","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/gmbh-osterfest-1017673\/","title":{"rendered":"Mit Hilfe der Funkmesstechnik Energie sparen"},"content":{"rendered":"<p>Am 20. April wird in Bitterfeld bei der Neubi (Neue Bitterfelder Wohnungs- und Baugesellschaft mbh) gefeiert. Das diesj\u00e4hrige Fr\u00fchlings- und Osterfest wird von der Neubi als Kommunikationsplattform genutzt, um mit den Mietern und mit Interessierten ins Gespr\u00e4ch zu kommen. Abgeschlossene Projekte sowie zuk\u00fcnftige Pl\u00e4ne werden vorgestellt, allgemeine Mieterfragen beantwortet \u2013 und das alles in entspannter und freundlicher Atmosph\u00e4re.<\/p> <p>Bei solcher Gelegenheit darf die LAS GmbH aus Leipzig nat\u00fcrlich nicht fehlen. Der Abrechner mit Einsparkompetenz ber\u00e4t die Gesch\u00e4ftsf\u00fchrung der Neubi seit circa drei Jahren in Sachen Energiemanagement, stattet die einzelnen Wohnungen und Heizanlagen mit neuester Technik aus und liefert die Energieverbrauchsdaten f\u00fcr die Heizkostenabrechnungen.<\/p> <p>Die Zusammenarbeit tr\u00e4gt bereits Fr\u00fcchte. <!--more-->Im Abrechnungsjahr 2010 konnte die Neubi circa 600.000 Euro Energiekosten gegen\u00fcber 2009 einsparen. In erster Linie wurde diese Einsparung durch erfolgreiche Vertragsverhandlungen mit den Energielieferanten und durch die Umsetzung des Energiemanagementsystems der LAS GmbH bei der verbrauchsorientierten Anlagensteuerung realisiert.<\/p> <p>Das Fr\u00fchlings- und Osterfest wird die LAS GmbH dazu nutzen, den Neubi-Mietern zu zeigen, wie jeder Mieter jetzt \u00fcber das LAS-Kundenportal seinen Energieverbrauch f\u00fcr Heizung und Warmwasser online einsehen und gezielt anpassen kann. Mit Hilfe der Funkmesstechnik an Heizk\u00f6rpern und Warm- und Kaltwasserz\u00e4hler wird der Verbrauch gemessen und sichtbar gemacht. \u00c4hnlich wie beim Drehzahlmesser im Auto wird durch die grafische Darstellung des jeweiligen Energieverbrauchs aufgezeigt, ob man Energie wirtschaftlich nutzt oder sie verschwendet und dann mit steigenden Kosten bei der n\u00e4chsten Nebenkostenabrechnung rechnen muss. Studien zeigen, dass Einsparungen von bis zu 25 % des individuellen Energieverbrauchs durch den Mieter selbst erzielt werden k\u00f6nnen. Vern\u00fcnftig, das hei\u00dft im gr\u00fcnen Drehzahlbereich, unterwegs zu sein, zahlt sich also nicht nur beim Autofahren aus.<\/p> <p>Damit \u00e4ltere Mieter oder Mieter mit begrenzten finanziellen Mitteln ohne eigenen Computer teilhaben k\u00f6nnen, unterst\u00fctzt die LAS GmbH in diesem Jahr wieder das Projekt \u201eFamilienbegegnungszentrum\u201c des Vereins MitN\u00e4he e.V. in Bitterfeld-Wolfen mit einer Spende in H\u00f6he von 1.500 Euro. Der Verein hat sich zum Ziel gesetzt, Chancengleichheit herzustellen und es Mietern zu erm\u00f6glichen, in Zukunft in den eigenen vier W\u00e4nden Energie zu sparen. Die Computer, mit denen man das erlernte Wissen zum eigenen Vorteil umsetzen kann, stehen den Mietern der Neubi sowohl im \u201eFamilienbegegnungszentrum\u201c des Vereins als auch in der Internet-Lounge in den Gesch\u00e4ftsr\u00e4umen der Neubi zur Verf\u00fcgung.<\/p> <p>Solches Engagement, aber auch die Unterst\u00fctzung der Neubi bei den Bestrebungen, die Energiekosten nachhaltig zu senken, sind f\u00fcr die LAS GmbH selbstverst\u00e4ndlich, zumal \u201esoziale Verantwortung zu \u00fcbernehmen\u201c zu den integralen Bestandteilen ihres Leitbildes geh\u00f6rt. Ziel ist es, die Mieter zu sensibilisieren und zu bef\u00e4higen, verantwortungsvoll mit Energie umzugehen. Die Auswirkung bei der n\u00e4chsten Nebenkostenabrechnung kann sich dann sehen lassen \u2013 und die globale CO2-Verminderung ohnehin.<br \/> Die LAS GmbH ist ein bundesweit t\u00e4tiges Dienstleistungsunternehmen der Versorgungs- und Immobilienwirtschaft. Das Produktportfolio der LAS GmbH umfasst f\u00fcr beide Branchen gleicherma\u00dfen Abrechnungs- und Inkassodienstleistungen sowie Beratung und L\u00f6sungsentwicklung. Durch unsere Markterfahrung und unsere hohe Innovationskraft arbeiten wir schnell, sicher und effizient f\u00fcr den Erfolg unserer Kunden.<br \/> LAS GmbH I L\u00f6sungen aus Sympathie<\/p> <p>Pressekontakt<br \/> LAS GmbH<br \/> Alexandra Wilmsmann<br \/> Marketingreferentin<br \/> Karl-Liebknecht-Stra\u00dfe 143<br \/> 04277 Leipzig<br \/> Telefon: 0341 35597-774<br \/> Telefax: 0341 35597-999<br \/> E-Mail: alexandra.wilmsmann@las-online.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 20. April wird in Bitterfeld bei der Neubi (Neue Bitterfelder Wohnungs- und Baugesellschaft mbh) gefeiert. Das diesj\u00e4hrige Fr\u00fchlings- und Osterfest wird von der Neubi als Kommunikationsplattform genutzt, um mit den Mietern und mit Interessierten ins Gespr\u00e4ch zu kommen. Abgeschlossene Projekte sowie zuk\u00fcnftige Pl\u00e4ne werden vorgestellt, allgemeine Mieterfragen beantwortet \u2013 und das alles in entspannter<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-17673","post","type-post","status-publish","format-standard","hentry","category-energie-verbraucher"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/17673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=17673"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/17673\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=17673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=17673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=17673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}