{"id":18000,"date":"2011-04-20T09:32:07","date_gmt":"2011-04-20T08:32:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=18000"},"modified":"2016-07-22T14:15:18","modified_gmt":"2016-07-22T13:15:18","slug":"preisauszeichner-einsparpotenzial","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/preisauszeichner-einsparpotenzial-1018000\/","title":{"rendered":"Signifikante Verk\u00fcrzung der R\u00fcstzeiten"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"innovative Etikettierer\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/6c3d337b08c2a9f8d40ea979e8728019.gif\" alt=\"\" width=\"200\" height=\"54\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/e08dbc2ab87f07e0307c4dc841093494.gif\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Balingen, 19. April 2011 &#8211; Die Etikettendrucker der GLP-Serie von Bizerba zur Warenkennzeichnung sind sowohl in der lebensmittelverarbeitenden Industrie wie im produzierenden Gewerbe und in der Logistik einsetzbar. Zur internationalen Verpackungsmesse Interpack vom 12. bis 18. Mai 2011 in D\u00fcsseldorf (Halle 14, Stand C 14) pr\u00e4sentiert der schw\u00e4bische L\u00f6sungsanbieter mit dem GLP-I ein neues Modell mit Einsparpotenzial f\u00fcr den Anwender.<\/p> <p>Der GLP-I bietet als Nachfolger des manuellen Preisauszeichners GH zus\u00e4tzliche Benefits. <!--more-->Das neue Ger\u00e4t mit Kunststoffgeh\u00e4use eignet sich f\u00fcr den Einsatz in Handel, Handwerk und der Industrie. Der GLP-I kann sowohl f\u00fcr die gewichtsbezogene wie auch f\u00fcr die Festgewicht- und Festwertauszeichnung in der Herstellung von Fleisch-, Wurst-, Gefl\u00fcgel- und K\u00e4sewaren eingesetzt werden, ebenso in der Obst- und Gem\u00fcseindustrie, der Herstellung von Convenience-Produkten und im Handel.<\/p> <p>&#8222;Der gro\u00dfe Vorteil des GLP-I liegt in der signifikanten Verk\u00fcrzung der R\u00fcstzeiten. Weil hier Etikettenrollen von 300 Millimeter Durchmesser eingesetzt werden k\u00f6nnen, spart der Kunde Zeit und mithin bares Geld&#8220;, erl\u00e4utert Dieter Conzelmann, Director Industry Solutions bei Bizerba. Der Vergleich mit Preisauszeichnern, bei denen Etikettenrollen mit geringerem Durchmesser und entsprechend weniger Etiketten je Rolle zum Einsatz kommen, spricht eine klare Sprache: Gegen\u00fcber einem Ger\u00e4t mit einem Etikettenrollendurchmesser von 160 Millimetern liegt die Zeitersparnis bei etwa 40 Stunden pro Jahr, gegen\u00fcber einem Etikettenrollendurchmesser von 210 Millimetern immerhin noch bei 20 Stunden.<\/p> <p>In bew\u00e4hrter Bizerba Tradition zeichnet sich auch der GLP-I durch vielf\u00e4ltige Kombinations- und Einsatzm\u00f6glichkeiten aus. So kann der Drucker als Summendrucker an einer vollautomatischen Auszeichnungslinie angeschlossen werden, aber ebenso als manueller Gewichts- und Preisauszeichner eingesetzt werden. Nat\u00fcrlich ist auch der Betrieb in einem Netzverbund von Bizerba Preisauszeichner und Checkweigher eine Option.<\/p> <p>Wie alle Bizerba Drucker bietet der GLP-I sowohl den Thermodirektdruck wie den Thermotransferdruck an. &#8222;Bei einer Druckbreite von bis zu 104 Millimeter erreicht der Anwender eine Druckgeschwindigkeit von bis zu 250 Millimeter pro Sekunde&#8220;, so Conzelmann. Je nach Druckgeschwindigkeit wird das Druckbild dabei mit einer Aufl\u00f6sung von 8 bis 12 dot (203 bis 300 dpi) dargestellt. Neben Standard-Etiketten k\u00f6nnen die Layouts auch individuell nach Kundenanforderungen gestaltet werden, beispielsweise mit Hilfe des Bizerba Label Designers BLD.<\/p> <p>Sollten einmal St\u00f6rungen auftreten, garantiert Bizerba mit seinem e-Service daf\u00fcr, dass die Ausfallzeiten sich denkbar gering darstellen. &#8222;Per E-Service k\u00f6nnen unsere Techniker rasch eine Ferndiagnose stellen und den Fehler entweder sofort per Remote oder in k\u00fcrzester Zeit vor Ort beheben&#8220;, versichert Dieter Conzelmann.<\/p> <p>Firmenkontakt<br \/> Bizerba GmbH &amp; Co. KG<br \/> Claudia Gross<br \/> Wilhelm-Kraut-Stra\u00dfe 65<\/p> <p>72336 Balingen<br \/> Deutschland<\/p> <p>E-Mail: claudia.gross@bizerba.com<br \/> Homepage: http:\/\/www.bizerba.com<br \/> Telefon: +49 7433 12-33 00<\/p> <p>Pressekontakt<br \/> nic.pr<br \/> Patrick Schr\u00f6der<br \/> Coburger Str. 3<\/p> <p>53113 Bonn<br \/> Deutschland<\/p> <p>E-Mail: info@nic-pr.de<br \/> Homepage: http:\/\/www.nic-pr.de<br \/> Telefon: 0228 620 43 84<\/p>","protected":false},"excerpt":{"rendered":"<p>Balingen, 19. April 2011 &#8211; Die Etikettendrucker der GLP-Serie von Bizerba zur Warenkennzeichnung sind sowohl in der lebensmittelverarbeitenden Industrie wie im produzierenden Gewerbe und in der Logistik einsetzbar. Zur internationalen Verpackungsmesse Interpack vom 12. bis 18. Mai 2011 in D\u00fcsseldorf (Halle 14, Stand C 14) pr\u00e4sentiert der schw\u00e4bische L\u00f6sungsanbieter mit dem GLP-I ein neues Modell<\/p>\n","protected":false},"author":291,"featured_media":198328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-18000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaft-management-versicherung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=18000"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18000\/revisions"}],"predecessor-version":[{"id":251587,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18000\/revisions\/251587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198328"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=18000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=18000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=18000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}