{"id":183,"date":"2008-04-11T12:02:11","date_gmt":"2008-04-11T11:02:11","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/kreatives-schreiben-ist-keine-gluckssache\/"},"modified":"2022-05-24T11:50:16","modified_gmt":"2022-05-24T10:50:16","slug":"kreatives-schreiben-ist-keine-gluckssache","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/kreatives-schreiben-ist-keine-gluckssache-10183\/","title":{"rendered":"Kreatives Schreiben ist keine Gl\u00fcckssache"},"content":{"rendered":"<p><font size=\"-1\"><strong>CAS Texter\/CAS Texterin &#8211; Erfolgreicher Pilotlehrgang<\/strong><\/font><\/p> <table style=\"float: right; width: 168px\" border=\"0\" cellpadding=\"5\" cellspacing=\"0\"> <tr> <td align=\"center\" bgcolor=\"#ededed\"> <table border=\"0\" cellpadding=\"3\" cellspacing=\"0\" width=\"168\"> <tr> <td align=\"center\"><\/td> <\/tr> <tr> <td class=\"txtklein\" align=\"center\"><nobr>[3 Pressefotos anzeigen]<\/nobr><\/td> <\/tr> <tr> <td colspan=\"2\" class=\"txtklein\" align=\"center\"><!-- copyrighttext --><!-- end copyrighttext --><\/td> <\/tr> <\/table> <\/td> <\/tr> <\/table> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"> <span class=\"txt\"> <!--PTE:ORT-->Z\u00fcrich (pts\/10.04.2008\/13:45) -# <strong>Der erste CAS* Texter steht vor dem Abschluss. Es ist dies die erste Ausbildung der Schweiz in Creative Writing, die zu einem Fachhochschul-Abschluss f\u00fchrt. Das berufsbegleitende Studium hat einen Umfang von 300 Lektionen (10 ECTS*) und kostet Fr. 4&#8217;950.-. Der n\u00e4chste Lehrgang startet im Juni.<\/strong><\/span><\/font><!--more--><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">&#8222;Die Ausbildung war spannend, sie hat sich f\u00fcr mich gelohnt. Vor einem Jahr habe ich mein Lizenziat in Germanistik gemacht und bin noch nicht so lange berufst\u00e4tig. Ich habe aber enorm von den kompetenten Dozenten und den Erfahrungen aus der Klasse profitiert. Dass der Lehrgang &#8218;erst&#8216; ein Pilot war, habe ich nicht gesp\u00fcrt. Ivo Hajnal und Franco Item sind sehr erfahrene Dozenten. Unsicherheiten in Bezug auf Inhalte und Organisation sp\u00fcrten wir nicht&#8220;, so fasst Mona Blum ihre Erfahrungen zusammen.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"><strong>Meister(n) des Kurztextes<\/strong><br \/> Texter gehen sparsam mit Worten um, sie schreiben meist kurz. Keinesfalls jedoch sparen sie mit Wortbildern, Wortwitz und Wortspielen. Sie inszenieren Botschaften und suchen zielstrebig nach dem treffenden Wort. Daf\u00fcr m\u00fcssen sie ihr kreatives Potential wecken und das ist lernbar. &#8222;Was bei mir bisher reines Bauchgef\u00fchl war, fand ich in der Theorie und durch Fachdozenten best\u00e4tigt. Mein Knopf hat sich gel\u00f6st. Wenn ich heute zum kreativen Sprung ansetze, dann schaffe ich die Latte spielend&#8220;, so Stefan Scherrer. Und weiter: &#8222;Die Meisten von uns konnten schon schreiben. Wir haben uns neue Kreativtechniken erschlossen und eine Denkweise entwickelt, die uns im professionellen, kreativen Texten weiterbringt&#8220;.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"><strong>Mit drei Modulen zum Ziel<\/strong><br \/> Modul 1 des Lehrgangs befasst sich mit der Sprache in Marketing und Werbung. Es beleuchtet den Werbe- und Marketingtext als Resultat unseres Schreibens. Dazu vermittelt es Grundtechniken und beantwortet die Frage &#8222;Was muss unser Text leisten?&#8220;. Modul 2 f\u00fchrt in die wesentlichen Methoden des Creative Writings ein. Ferner vermittelt es ein Verst\u00e4ndnis f\u00fcr audiovisuelle und &#8222;Neue&#8220; Medien, die ein besonderes Mass an Kreativit\u00e4t erfordern. Modul 3 bilden die m\u00fcndlichen und schriftlichen Zertifikatspr\u00fcfungen.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">Die Teilnehmer treffen sich im Verlauf der Ausbildung zu sieben Pr\u00e4senztagen und absolvieren sechs praktische \u00dcbungen unter Zeitdruck im E-Classroom. Das Gelernte wenden sie zudem in zwei Studienarbeiten an. R\u00fcckblickend auf den Studiengang meint Teilnehmerin Barbara M\u00f6gli: &#8222;Meine ohnehin schon hohen Erwartungen wurden bei Weitem \u00fcbertroffen. Ivo Hajnal und Franco Item haben es geschafft, anspruchsvolle Inhalte anschaulich und lebendig zu vermitteln. Da kam nie Langeweile auf.&#8220;<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"><strong>Vom CAS Texter zum &#8222;dipl. Texter \/ PR-Redaktor&#8220;<\/strong><br \/> Der Titel wird von der staatlich anerkannten Hochschule f\u00fcr Technik und Wirtschaft HTW Chur verliehen und mit 10 ECTS honoriert. Der CAS Texter \/ CAS Texterin kann mit dem CAS PR-Redaktor zum DAS* in Professional Writing &#8211; &#8222;dipl. Texter \/ PR-Redaktor&#8220; &#8211; kombiniert werden. Den Abschluss bildet eine DAS-Thesis der HTW Chur mit 8 ECTS. Die Reihenfolge, in welcher die beiden CAS-Lehrg\u00e4nge absolviert werden, spielt keine Rolle.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"><strong>* Erkl\u00e4rung der Abk\u00fcrzungen<\/strong><\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">CAS &#8211; Certificate of Advanced Studies &#8211; mindestens 10 Kreditpunkte (ECTS)<br \/> DAS &#8211; Diploma of Advanced Studies &#8211; mindestens 30 Kreditpunkte (ECTS)<br \/> MAS &#8211; Master of Advanced Studies &#8211; mindestens 60 Kreditpunkte (ECTS)<br \/> ECTS &#8211; Credits: Kreditpunkte, die nach dem \u00abEuropean Credit Transfer System\u00bb (ECTS) f\u00fcr Studienleistungen vergeben werden.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"><strong>Die Schweizerische Text Akademie<\/strong><br \/> Zum Stiftungszweck der Schweizerischen Text Akademie geh\u00f6rt &#8222;die F\u00f6rderung der deutschen Sprache in Medien und Wirtschaft&#8220;. Dieses Ziel will die Akademie neben ihrem Angebot an Aus- und Weiterbildungen durch regelm\u00e4ssige wissenschaftliche Forschung erreichen: in der Deutschschweiz und im deutschsprachigen Ausland. Zu diesem Zweck unterh\u00e4lt die Akademie an der Hochschule f\u00fcr Technik und Wirtschaft HTW in Chur eine Forschungstelle f\u00fcr &#8222;Sprache in Medien, Wirtschaft und Corporate Publishing&#8220;.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"><strong>Weitere Ausk\u00fcnfte<\/strong><br \/> Schweizerische Text Akademie<br \/> Technopark Z\u00fcrich<br \/> Technoparkstrasse 1<br \/> 8005 Z\u00fcrich<br \/> Tel: 044 445 19 35<br \/> Web: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.textakademie.ch\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/www.textakademie.ch<\/a><br \/> Mail: <a href=\"mailto:info@textakademie.ch\">info@textakademie.ch<\/a><\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">Kontaktpersonen:<br \/> &#8211; Marie-Christine Schindler, Organisation und Beratung, <a href=\"mailto:info@textakademie.ch\">info@textakademie.ch<\/a><br \/> &#8211; Prof. Dr. Ivo Hajnal, <a href=\"mailto:hajnal@textakademie.ch\">hajnal@textakademie.ch<\/a><br \/> &#8211; Franco Item, <a href=\"mailto:item@textakademie.ch\">item@textakademie.ch<\/a>  (Ende)<br \/> <br clear=\"all\" \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.textakademie.ch\/\"  target=\"_new\" rel=\"noopener\"><\/a><br \/> Aussender: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.textakademie.ch\/\"  target=\"_new\" rel=\"noopener\">Schweizerische Text Akademie<\/a><br \/> Ansprechpartner:                        Marie-Christine Schindler<br \/> email: <a href=\"mailto:info%40textakademie.ch\">info@textakademie.ch<\/a><br \/> Tel. +41 44 445 19 35   <\/font><\/p>","protected":false},"excerpt":{"rendered":"<p>CAS Texter\/CAS Texterin &#8211; Erfolgreicher Pilotlehrgang [3 Pressefotos anzeigen] Z\u00fcrich (pts\/10.04.2008\/13:45) -# Der erste CAS* Texter steht vor dem Abschluss. Es ist dies die erste Ausbildung der Schweiz in Creative Writing, die zu einem Fachhochschul-Abschluss f\u00fchrt. Das berufsbegleitende Studium hat einen Umfang von 300 Lektionen (10 ECTS*) und kostet Fr. 4&#8217;950.-. Der n\u00e4chste Lehrgang startet<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-183","post","type-post","status-publish","format-standard","hentry","category-journalismus-medien-publizistik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":3,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/183\/revisions"}],"predecessor-version":[{"id":274461,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/183\/revisions\/274461"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}