{"id":18471,"date":"2011-04-28T14:28:17","date_gmt":"2011-04-28T13:28:17","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=18471"},"modified":"2011-04-28T14:28:17","modified_gmt":"2011-04-28T13:28:17","slug":"dyskalkulie-handeln","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/dyskalkulie-handeln-1018471\/","title":{"rendered":"Bei den ersten Auff\u00e4lligkeiten auf eine Dyskalkulie testen lassen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18474\" title=\"Interessenvertretung von Betroffenen und deren Eltern\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/18471\/logo_bvl_200.jpg\" alt=\"\" width=\"170\" height=\"113\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Der Bundesverband Legasthenie und Dyskalkulie (BVL) r\u00e4t Lehrern und Eltern, bei Kindern mit massiven Schwierigkeiten beim Rechnen nicht abzuwarten, sondern umgehend qualifiziert f\u00f6rdern zu lassen, um dem Kind die Teilhabe am Unterricht zu erm\u00f6glichen.<\/p> <p>In Deutschland sind ca. 5-6% aller Kinder von einer Dyskalkulie (Rechenst\u00f6rung) betroffen. Sie haben keine Vorstellung, was sich hinter einer Menge oder einer Zahl verbirgt. In der 1. Klasse schaffen sie es, noch \u201eabz\u00e4hlend\u201c zu rechnen. Wird der Zahlenraum der Zehner verlassen, dann scheitern sie oftmals im Mathematikunterricht. Da sie sich auch m\u00fcndlich nicht angemessen beteiligen k\u00f6nnen, sind sie vom Unterricht ausgegrenzt.<\/p> <p><!--more-->Kinder mit einer Dyskalkulie haben es in der Schule besonders schwer, weil sie dem Unterricht trotz guter allgemeiner Begabung nicht folgen k\u00f6nnen und so schnell die Freude am Mathematikunterricht verlieren. Je gr\u00f6\u00dfer der Zahlenraum und je komplexer die Aufgaben werden, umso fataler wird die Situation f\u00fcr die Betroffenen. Und zwar nicht nur f\u00fcr die Sch\u00fcler, sondern auch f\u00fcr Lehrer und Eltern, die nicht wissen, wie sie dem Kind den Zugang zu Zahlen und Mengen vermitteln sollen. Bis heute sind Lehrerinnen und Lehrer noch nicht ausreichend qualifiziert, um den betroffenen Kindern nachhaltig zu helfen. \u201eVor allem ist bei Sch\u00fclerinnen und Sch\u00fclern eine Einzelf\u00f6rderung notwendig, die in der Schule meist nicht geleistet werden kann. Eltern wenden sich dann hilfesuchend an den BVL. Aber wir k\u00f6nnen aktuell auch nur auf qualifizierte externe Dyskalkulietherapeuten verweisen, weil die Schulen mit der Situation \u00fcberfordert sind\u201c, sagt Inge Palme, Referentin f\u00fcr Beratung und Fortbildung vom BVL.<\/p> <p>\u201eWir raten den Eltern, ihr Kind bei den ersten Auff\u00e4lligkeiten auf eine Dyskalkulie testen zu lassen und nach der Diagnose sofort mit einer Dyskalkulietherapie zu beginnen\u201c, so Palme weiter. \u201eMit einer anforderungsgerechten Dyskalkulietherapie gelingt es meist recht gut, dem Kind ein Zahlen- und Mengenverst\u00e4ndnis zu vermitteln und die Teilnahme am Unterricht wieder herzustellen. Wird mit der Therapie nicht fr\u00fchzeitig begonnen, dann hat das Kind meist schon den Mut verloren und es wird immer schwerer, den Anschluss in der Klasse zu finden. Eltern k\u00f6nnen sich beim BVL oder den Landesverb\u00e4nden beraten lassen, wo sie qualifizierte Hilfe finden.\u201c<\/p> <p>Weitere Informationen zum Thema und zum Bundesverband Legasthenie und Dyskalkulie e.V. sind im Internet unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.bvl-legasthenie.de\" title=\"Bundesverband Legasthenie und Dyskalkulie\" >www.bvl-legasthenie.de<\/a> abrufbar.<\/p> <p>Ansprechpartner f\u00fcr R\u00fcckfragen zu dieser Pressemitteilung:<\/p> <p>(1) Bundesverband Legasthenie und Dyskalkulie e. V.<\/p> <p>Frau Annette H\u00f6inghaus<\/p> <p>BVL (Bundesverband Legasthenie und Dyskalkulie e. V.)<br \/> c\/o EZB<br \/> Postfach 201338<br \/> D-53143 Bonn<\/p> <p>Telefon: +49 (0) 4193 96 56 02<br \/> Fax: +49 (0) 4193 96 93 04<br \/> E-Mail: presse@bvl-legasthenie.de<br \/> Internet: http:\/\/www.bvl-legasthenie.de<\/p> <p>(2) PR-Agentur PR4YOU<\/p> <p>Herr Holger Ballwanz, Herr Marko Homann<\/p> <p>PR-Agentur PR4YOU<br \/> Schonensche Stra\u00dfe 43<br \/> D-13189 Berlin<\/p> <p>Telefon: +49 (0) 30 43 73 43 43<br \/> Fax: +49 (0) 30 44 67 73 99<br \/> E-Mail: presse@pr4you.de<br \/> Internet: http:\/\/www.pr4you.de<\/p> <p>\u00dcber den Bundesverband Legasthenie und Dyskalkulie e.V.:<\/p> <p>Der Bundesverband Legasthenie und Dyskalkulie e.V. besteht seit \u00fcber 30 Jahren und ist eine Interessenvertretung von Betroffenen und deren Eltern sowie von Fachleuten (P\u00e4dagogen, Psychologen, \u00c4rzten, Wissenschaftlern und im sozialen Bereich T\u00e4tigen), die sich in Theorie und Praxis mit der Legasthenie und Dyskalkulie auseinandersetzen. Er tr\u00e4gt dazu bei, dass gesetzliche Grundlagen und wissenschaftliche sowie praktische M\u00f6glichkeiten der Hilfe in allen Bundesl\u00e4ndern geschaffen und verbessert werden. Durch pers\u00f6nliche Beratung, Informationsschriften und Hinweise auf geeignete Literatur sollen die Eltern die Schwierigkeiten ihrer betroffenen Kinder besser verstehen lernen.<\/p> <p>Der BVL f\u00f6rdert durch wissenschaftliche Kongresse und Ver\u00f6ffentlichungen die Forschung und den wissenschaftlichen Dialog unter Fachleuten aller beteiligten Disziplinen. Durch Informationen und Zusammenarbeit mit den Medien macht der BVL die Probleme der Legastheniker und Dyskalkuliker bekannt.<\/p> <p>Weitere Informationen zum Thema Legasthenie und \u00fcber den Bundesverband Legasthenie und Dyskalkulie e.V. sind im Internet unter http:\/\/www.bvl-legasthenie.de abrufbar.<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Bundesverband Legasthenie und Dyskalkulie (BVL) r\u00e4t Lehrern und Eltern, bei Kindern mit massiven Schwierigkeiten beim Rechnen nicht abzuwarten, sondern umgehend qualifiziert f\u00f6rdern zu lassen, um dem Kind die Teilhabe am Unterricht zu erm\u00f6glichen. In Deutschland sind ca. 5-6% aller Kinder von einer Dyskalkulie (Rechenst\u00f6rung) betroffen. Sie haben keine Vorstellung, was sich hinter einer Menge<\/p>\n","protected":false},"author":291,"featured_media":18474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-18471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=18471"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/18474"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=18471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=18471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=18471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}