{"id":18618,"date":"2011-05-03T09:46:37","date_gmt":"2011-05-03T08:46:37","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=18618"},"modified":"2017-07-07T15:58:24","modified_gmt":"2017-07-07T14:58:24","slug":"deutsche-manufakturen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/deutsche-manufakturen-1018618\/","title":{"rendered":"Neue Manufakturen und weitere Ma\u00dfnahmen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Am 13. Mai 2011 kommt die Initiative Deutsche Manufakturen im Berlin Capital Club am Gendarmenmarkt zu ihrem ersten Jahrestreffen 2011 zusammen. Unter dem Motto &#8222;Handmade in Germany&#8220; wurde sie im November 2010 von acht Deutschen Manufakturen gegr\u00fcndet. Ziel ist es, die gemeinsamen Interessen der Mitglieder zu vertreten sowie die Bedeutung der Manufakturen sichtbarer und deren Einfluss auf den Wirtschaftsstandort Deutschland im Ausland deutlicher zu machen. Heute sind bereits 14 Manufakturen Mitglied in der Initiative Deutsche Manufakturen.<\/p> <p><!--more-->Um weitere Ma\u00dfnahmen zu besprechen und neue Manufakturen vorzustellen, treffen sich die Mitglieder der Initiative am Freitag, den 13. Mai im Berlin Capital Club am Gendarmenmarkt. Im Anschluss an das Mitgliedertreffen sind die Pressevertreter herzlich eingeladen. Mit dabei sind die Gr\u00fcndungsmitglieder Burmester Audiosysteme, KPM K\u00f6nigliche Porzellan-Manufaktur Berlin, Kay Gundlack Schuhmanufaktur, Johannes Klais Orgelbau, St\u00fcbben, Poggenpohl M\u00f6belwerke, Peter Bock und WELTER Wandunikate sowie die neuen Mitglieder Waldkircher Orgelbau J\u00e4ger &amp; Brommer, die ACCENTE Einrichtungsgesellschaft, die Bildgie\u00dferei Hermann Noack, Sudhaus, Strunkmann &amp; Meister und die FITZ LEUCHTENMANUFAKTUR.<\/p> <p>Die Bildgie\u00dferei Hermann Noack hat die Geschichte Berlins f\u00f6rmlich mit ins Bild gegossen: Prominente Denkm\u00e4ler der Kaiserzeit und Weimarer Republik sowie Rekonstruktionsarbeiten historischer Denkm\u00e4ler wie die der Quadriga auf dem Brandenburger Tor stammen aus dem Handwerksbetrieb. Das Familienunternehmen fertigt Gro\u00dfplastiken und Designobjekte renommierter internationaler K\u00fcnstler wie K\u00e4the Kollwitz, Joseph Beuys oder Jonathan Meese. Auf 10.000qm Werksfl\u00e4che ergibt sich eine eindrucksvolle Kulisse f\u00fcr deutsche Handarbeit.<\/p> <p>Nicht minder bemerkenswert ist die zweite zu besichtigende Manufaktur WELTER Wandunikate: Gr\u00fcnder Ulrich Welter &#8222;inszeniert&#8220; W\u00e4nde mit dem besonderen Blick f\u00fcr edle Materialien, langlebige Farben und Lichtverh\u00e4ltnisse, die das Gesamtwerk sp\u00e4ter untermalen. Auch jenseits Deutschlands ist die Manufaktur bekannt: Bei der diesj\u00e4hrigen Oscar-Verleihung veredelte die Manufaktur mit einer ihrer glamour\u00f6sen Tapeten das B\u00fchnenbild.<\/p> <p>Im ersten internen Teil der Veranstaltung, die um 11 Uhr beginnt, definieren und diskutieren die Mitglieder der Initiative aktuelle Projekte, u.a. das geplante Buch &#8222;Deutsche Manufakturen&#8220; im Verlag Deutsche Standards, welches von Dr. Florian Langenscheidt in Kooperation mit der Initiative Deutsche Manufakturen herausgegeben werden soll.<\/p> <p>Ab 14 Uhr besteht f\u00fcr interessierte Pressevertreter die M\u00f6glichkeit, Interviews mit den Mitgliedern zu f\u00fchren und sich vor Ort ein Bild der Initiative zu machen.<\/p> <p>Um 15 Uhr beginnt die Besichtigung der Bildgie\u00dferei Hermann Noack und der WELTER Manufaktur f\u00fcr Wandunikate f\u00fcr Pressevertreter und die Mitglieder der Initiative. Der Transport erfolgt via Busshuttle.<\/p> <p>Nat\u00fcrlich k\u00f6nnen Sie auch gerne beide M\u00f6glichkeiten wahrnehmen. Treffpunkt ist bei beiden Terminen der Empfang im Berlin Capital Club.<\/p> <p>Datum:        Freitag, 13. Mai 2011<\/p> <p>Uhrzeit:       14 Uhr oder 15 Uhr<\/p> <p>Treffpunkt:    Berlin Capital Club am Gendarmenmarkt, Mohrenstr. 30, 10117  Berlin, am Empfang<\/p> <p>Zeitraum:     Der Besichtigungszeitraum der Manufakturen  wird ca. 2 Stunden  betragen.<\/p> <p>Firmenkontakt<br \/> Initiative Deutsche Manufakturen c\/o wbpr Public Relations GmbH<br \/> Laura Vetter<br \/> Schumannstra\u00dfe 5<\/p> <p>10117 Berlin<br \/> Deutschland<\/p> <p>E-Mail: laura.vetter@wbpr.de<br \/> Homepage: http:\/\/www.handmade-in-germany. org<br \/> Telefon: 030 288 76 133<\/p> <p>Pressekontakt<br \/> Initiative Deutsche Manufakturen c\/o wbpr Public Relations GmbH<br \/> Laura Vetter<br \/> Schumannstra\u00dfe 5<\/p> <p>10117 Berlin<br \/> Deutschland<\/p> <p>E-Mail: laura.vetter@wbpr.de<br \/> Homepage: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.handmade-in-germany.org\/\" title=\"Initiative deutsche Manufakturen\" >http:\/\/www.handmade-in-germany.org\/<\/a><br \/> Telefon: 030 288 76 133<\/p> <p>Informieren Sie sich weiter in unserer Rubrik <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.fachzeitungen.de\/seite\/p\/kat\/katid\/22\" title=\"Fachzeitschriften zum Thema Handel-Gewerbe\" >Handel-Gewerbe<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Am 13. Mai 2011 kommt die Initiative Deutsche Manufakturen im Berlin Capital Club am Gendarmenmarkt zu ihrem ersten Jahrestreffen 2011 zusammen. Unter dem Motto &#8222;Handmade in Germany&#8220; wurde sie im November 2010 von acht Deutschen Manufakturen gegr\u00fcndet. Ziel ist es, die gemeinsamen Interessen der Mitglieder zu vertreten sowie die Bedeutung der Manufakturen sichtbarer und deren<\/p>\n","protected":false},"author":291,"featured_media":198310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-18618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaft-management-versicherung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=18618"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18618\/revisions"}],"predecessor-version":[{"id":269051,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18618\/revisions\/269051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198310"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=18618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=18618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=18618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}