{"id":18651,"date":"2011-05-04T10:41:39","date_gmt":"2011-05-04T09:41:39","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=18651"},"modified":"2025-03-21T12:11:25","modified_gmt":"2025-03-21T11:11:25","slug":"schoepfung-tagen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/schoepfung-tagen-1018651\/","title":{"rendered":"Business in Klosterambiente"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Kreativit\u00e4t braucht Inspiration. Etwa durch die reiche Kulturlandschaft am Untersee. Oder befl\u00fcgelt vom Geist gro\u00dfer Dichter und Denker, Maler und Ordensleute, die hier ihre Spuren hinterlassen haben.<\/p> <p>Seit mehr als 150 Jahren wirken die Barmherzigen Schwestern vom heiligen Kreuz am westlichen Bodensee. Der Orden stellte sich den N\u00f6ten jeder Epoche. Im Jahr 2006 erkannte er das wachsende Bed\u00fcrfnis nach R\u00fcckzugsorten und baute auf einer Anh\u00f6he zwischen Konstanz und Allensbach ein modernes Tagungs- und Urlaubshotel.<\/p> <p><!--more-->Business in Klosterambiente<br \/> Eine Auszeit nehmen ist auch Teil der heutigen Unternehmenskultur. Nur in Klausur gehen war gestern. Nun ist es der Workshop, das Kick off Meeting oder Incentive, \u00fcber das Unternehmen neu ausgerichtet, Mitarbeiter geschult und auf den Teamgeist eingeschworen werden. Werte und Gemeinschaftsgedanken sind fest in Ordenskulturen verankert. Es liegt also nah, in kl\u00f6sterlicher Nachbarschaft und dennoch in modernem Ambiente zu tagen. Die Gastfreundschaft der Hegner Schwestern darf von den Hotelg\u00e4sten w\u00f6rtlich genommen werden. Nicht nur Auszeitsuchende auch Tagungsteilnehmer sind eingeladen, an ihrem spirituellen Leben teilzuhaben.<\/p> <p>Innenschau mit Aussicht<br \/> Abseits der Tagung nutzen viele G\u00e4ste die Hotelangebote. Bei Atemmeditationen, Hatha Yoga oder dem morgendlichen Impuls in der Hauskapelle kehren sie bei sich selbst ein. Andere werden sch\u00f6pferisch beim direkten Blick auf den Untersee mit Blick auf die Weltkulturerbe-Insel Reichenau. Dieser ist von allen acht Tagungsr\u00e4umen mit Platz von 4 bis 150 Teilnehmern und von den meisten der 68 komfortablen Zimmer aus m\u00f6glich. Manche Gruppen nutzen das Seegrundst\u00fcck, die weitl\u00e4ufigen Park- und Gr\u00fcnanlagen als Teil der Tagung und buchen Angebote zur Team-Entwicklung dazu. Sie reichen vom gemeinsamen Flo\u00dfbau und anschlie\u00dfend zur Reichenau \u00fcbersetzen bis zum Geo-Caching, bei dem sich die Teilnehmer mit GPS ausger\u00fcstet durch das Ried schlagen und den &#8222;Schatz vom Bodensee&#8220; aufsp\u00fcren.<\/p> <p>Kneippkur f\u00fcr den Kopf<br \/> K\u00f6rper und Geist arbeiten im Gleichklang am besten. Eine ausgewogene Ern\u00e4hrung hilft, sich zu konzentrieren. Die Hotelk\u00fcche sorgt f\u00fcr gesunde St\u00e4rkung und verarbeitet vom proteinreichen Felchen bis zum knackfrischen Reichenaugem\u00fcse und Bodenseeobst viel Gutes vom See aus eigenem oder regionalem Anbau. Und im hoteleigenen Caf\u00e9 vis \u00e0 vis sorgen hausgemachte Kuchen f\u00fcr s\u00fc\u00dfe Momente.<\/p> <p>Informationen: VCH-Hotel Haus St. Elisabeth, Konradistr. 1, D-78476 Allensbach-Hegne, Tel. +49 (0)7533 9366-2000, info@st-elisabeth-hegne.de, <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.st-elisabeth-hegne.de\" title=\"Gastlichkeit f\u00fcr Leib und Seele\" >www.st-elisabeth-hegne.de<\/a>.<\/p> <p>Tagungspauschalen im VCH-Hotel Haus St. Elisabeth:<br \/> Das Preisspektrum im Haus St. Elisabeth, das dem Verband Christlicher Hoteliers (kurz VCH) angeh\u00f6rt, bel\u00e4uft sich von der klassischen Variante f\u00fcr 30,90 Euro bis zu 45,90 Euro pro Teilnehmer bei Buchung der Pauschale Komfort &amp; Mehr. Pausenvariationen sind frei w\u00e4hlbar, die Pauschalen modular buchbar. Die Team-Entwicklung im Freien verantwortet die Partnerfirma Trekking Tours aus \u00dcberlingen. Meditationskurse wie Hatha Yoga bietet das Referat Bildung im Hotel an. Eine Anreise per Bahn ist bequem und \u00f6kologisch mit dem RIT-Ticket m\u00f6glich. Der Regionalzug \u201aseehas&#8216; h\u00e4lt mehrmals t\u00e4glich an der Station Hegne. Eine Tageskarte kann mit Tagungsraum und Unterkunft gebucht werden, wie auch Tickets zu Veranstaltungen im neun Kilometer entfernten Konstanz oder in die Bodensee Therme.<\/p> <p>Firmenkontakt<br \/> PR2 Petra Reinm\u00f6ller Public Relations<br \/> Petra Reinm\u00f6ller<br \/> Businesspark \/ Max-Stromeyer-Str. 116<\/p> <p>78467 Konstanz<br \/> Deutschland<\/p> <p>E-Mail: redaktion@pr2.de<br \/> Homepage: http:\/\/www.pr2.de<br \/> Telefon: +49-7531-369 37-10<\/p> <p>Pressekontakt<br \/> PR2 Petra Reinm\u00f6ller Public Relations<br \/> Petra Reinm\u00f6ller<br \/> Businesspark \/ Max-Stromeyer-Str. 116<\/p> <p>78467 Konstanz<br \/> Deutschland<\/p> <p>E-Mail: redaktion@pr2.de<br \/> Homepage: http:\/\/www.pr2.de<br \/> Telefon: +49-7531-369 37-10<\/p>","protected":false},"excerpt":{"rendered":"<p>Kreativit\u00e4t braucht Inspiration. Etwa durch die reiche Kulturlandschaft am Untersee. Oder befl\u00fcgelt vom Geist gro\u00dfer Dichter und Denker, Maler und Ordensleute, die hier ihre Spuren hinterlassen haben. Seit mehr als 150 Jahren wirken die Barmherzigen Schwestern vom heiligen Kreuz am westlichen Bodensee. Der Orden stellte sich den N\u00f6ten jeder Epoche. Im Jahr 2006 erkannte er<\/p>\n","protected":false},"author":291,"featured_media":198307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8804],"tags":[],"class_list":["post-18651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reisen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=18651"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18651\/revisions"}],"predecessor-version":[{"id":276910,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18651\/revisions\/276910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198307"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=18651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=18651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=18651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}