{"id":187,"date":"2008-04-14T18:35:36","date_gmt":"2008-04-14T17:35:36","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/deutscher-borsenbrief-award-2008-verliehen\/"},"modified":"2025-03-21T11:59:07","modified_gmt":"2025-03-21T10:59:07","slug":"deutscher-borsenbrief-award-2008-verliehen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/deutscher-borsenbrief-award-2008-verliehen-10187\/","title":{"rendered":"Deutscher B\u00f6rsenbrief-Award 2008 verliehen"},"content":{"rendered":"<p> <strong><span style=\"font-size: 12pt\">Fachinformationsdienst AKTIEN-MONITOR zeichnet Platow B\u00f6rse, Hanseatischen B\u00f6rsendienst und Euro am Sonntag aus<o:p><\/o:p><\/span><\/strong><\/p> <p><span style=\"font-size: 10pt\">Stuttgart, 11. April 2008. #Auf der Anlegermesse Invest in Stuttgart wurde vom Fachinformationsdienst AKTIEN-MONITOR zum zweiten Mal der Deutsche B\u00f6rsenbrief-Award verliehen. Der Preis orientiert sich am Fonds-Rating bekannter Agenturen und wird in drei Kategorien vergeben. \u201eDer B\u00f6rsenbrief-Award ist f\u00fcr Anleger ein Indikator, um seri\u00f6se von unseri\u00f6sen B\u00f6rsendiensten zu unterscheiden\u201c, sagt Raimund Brichta, Wirtschaftsjournalist und Jurymitglied.<\/span><!--more--><\/p> <p style=\"margin-right: 93.6pt\"> <p><span style=\"font-size: 10pt\">Als bester allgemeiner B\u00f6rsenbrief wurde die \u201ePlatow B\u00f6rse\u201c von Chefredakteur Frank Mahlmeister ausgezeichnet. Die Jury attestierte dem Dienst \u201eeine ruhige Hand in schwierigen B\u00f6rsenmonaten.\u201c Der B\u00f6rsenbrief biete erstklassige Hintergrund-Analysen, berichte stets kritisch, objektiv und fundiert \u00fcber das deutsche und internationale B\u00f6rsengeschehen.<o:p><\/o:p><\/span><\/p> <p><span style=\"font-size: 10pt\">In der Kategorie Spezialbriefe gewann zum zweiten Mal der \u201eHanseatische B\u00f6rsendienst\u201c. Der auf deutsche Nebenwerte spezialisierte Dienst<span>  <\/span>beeindruckte die Jury durch die Performance des Musterdepots mit einem Zugewinn von rund 23 Prozent. Das Team um Chefredakteur Matthias Rieger folge einer Value-Strategie, mit der es g\u00fcnstig bewertete Unternehmen ausw\u00e4hlt.<o:p><\/o:p><\/span><\/p> <p><span style=\"font-size: 10pt\">Auch \u201eEuro am Sonntag\u201c von Chefredakteur Dr. Frank-B. Werner verteidigte seinen Titel in der Kategorie Anlegermagazin \/ B\u00f6rsenjournal. Es \u00fcberzeugte durch einen \u201ebunten, informativen und auch gewinnbringenden Mix aus Hintergrundberichten, Sonderthemen und konkreten Anlage-Empfehlungen, der vorbildlich f\u00fcr die gesamte Branche ist\u201c, so die Jury.<span>  <\/span><o:p><\/o:p><\/span><\/p> <p><span style=\"font-size: 10pt\">Die Hauptkriterien der Preisvergabe sind nachhaltiger Erfolg der Anlageempfehlungen, Erfahrung und Unabh\u00e4ngigkeit der Redaktion, Entwicklung der Leserzahlen sowie Informationsgehalt und \u00dcbersichtlichkeit.<o:p><\/o:p><\/span><\/p> <p><span style=\"font-size: 10pt\">Das Buch \u201eDeutscher B\u00f6rsenbrief-Award 2008\u201c (DIN A5, 80 Seiten) kann kostenfrei beim Investor-Verlag, dem Herausgeber von AKTIEN-MONITOR, angefordert werden: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.aktienmonitor.net\/\"  >www.aktienmonitor.net<\/a> oder Tel: 0228\/8205-7718. <\/span><span style=\"font-size: 14pt\"><o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\"><span style=\"font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 14pt; font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 14pt; font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 14pt; font-family: Arial\">Hintergrundinformationen zum<o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><strong><span style=\"font-size: 14pt; font-family: Arial\"><o:p> <\/o:p><\/span><\/strong><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><strong><span style=\"font-size: 14pt; font-family: Arial\">Deutschen B\u00f6rsenbrief-Award 2008<o:p><\/o:p><\/span><\/strong><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\">F\u00fcr das Rating und den B\u00f6rsenbrief-Award wurden drei Kategorien gebildet, da beispielsweise ein Biotech-Spezialbrief nur in Teilbereichen mit einem Anlegermagazin \/ B\u00f6rsenjournal zu vergleichen ist. Richtschnur f\u00fcr die Bewertung war die Frage, was ein Anleger in der jeweiligen Kategorie erwartet. <o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\"><span> <\/span><o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\">Die Jury bestand aus Raimund Brichta, Wirtschaftsjournalist und Moderator der Teleb\u00f6rse bei n-tv, J\u00fcrgen Schmitt, Cliff Michel, Marcus Neugebauer und Cindy Bach, alle vom Fachinformationsdienst AKTIEN-MONITOR.<o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\">Mit dem seit 2002 bestehenden B\u00f6rsenbrief Rating vermittelt der AKTIEN-MONITOR Anlegern eine Orientierungshilfe im Feld der rund 100 deutschsprachigen B\u00f6rsendienste. F\u00fcr die bewerteten B\u00f6rsenbriefe ergeben sich aus der Bewertung neue Impulse zur Optimierung ihrer Redaktionsarbeit.<o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\">Der monatlich erscheinende AKTIEN-MONITOR hat sich als B\u00f6rsen-Digest spezialisiert, der f\u00fcr seine Leser Informationen aus B\u00f6rsenbriefen analysiert und bewertet. Das Redaktionsteam hat ein eigenes, seit Jahren bew\u00e4hrtes Rating entwickelt. Der AKTIEN-MONITOR erscheint im Investor Verlag, einem Unternehmensbereich der FID Verlag GmbH. <o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-size: 11pt; font-family: Arial\">B\u00f6rsenbriefe aus dem Investor Verlag und aus Schwesterverlagen wurden zur Wahrung der Objektivit\u00e4t von der Beurteilung ausgeschlossen. <o:p><\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><span style=\"font-family: Arial\"><o:p> <\/o:p><\/span><\/p> <p class=\"MsoNormal\" style=\"margin-right: 93.6pt\"><strong><span style=\"font-size: 10pt; font-family: Arial; color: black\">Kontakt:<\/span><\/strong><span style=\"font-size: 10pt; font-family: Arial; color: black\"><br \/> <!--[if !supportLineBreakNewLine]--><br \/> <!--[endif]--><o:p><\/o:p><\/span><\/p> <p style=\"margin-right: 93.6pt\"><strong>Oliver K\u00fcster<o:p><\/o:p><\/strong><\/p> <p style=\"margin-right: 93.6pt\"><strong>FID Verlag GmbH<\/strong>, Unternehmensbereich Investor Verlag<br \/> Koblenzer Stra\u00dfe 99, 53177 Bonn<\/p> <p style=\"margin-right: 93.6pt\">Telefon: 02 28 \/ 8205 7718<br \/> Fax: 02 28 \/ 82 05 57 56<\/p> <p style=\"margin-right: 93.6pt\">Internet: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.aktienmonitor.net\/\"  >www.aktienmonitor.net<\/a>.<br \/> E-Mail: <span class=\"email\"><span style=\"color: navy\">oku@fid-verlag.de<\/span><\/span><\/p> <p style=\"margin-right: 93.6pt\">USt.-ID: DE 811270471, Amtsgericht Bonn, HRB 7435<\/p> <p style=\"margin-right: 93.6pt\">Gesch\u00e4ftsf\u00fchrung: J\u00f6rg Ludermann (Vorsitzender), Helmut Graf, Sandra Witscher<\/p>","protected":false},"excerpt":{"rendered":"<p>Fachinformationsdienst AKTIEN-MONITOR zeichnet Platow B\u00f6rse, Hanseatischen B\u00f6rsendienst und Euro am Sonntag aus Stuttgart, 11. April 2008. #Auf der Anlegermesse Invest in Stuttgart wurde vom Fachinformationsdienst AKTIEN-MONITOR zum zweiten Mal der Deutsche B\u00f6rsenbrief-Award verliehen. Der Preis orientiert sich am Fonds-Rating bekannter Agenturen und wird in drei Kategorien vergeben. \u201eDer B\u00f6rsenbrief-Award ist f\u00fcr Anleger ein Indikator, um<\/p>\n","protected":false},"author":1,"featured_media":199083,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banken-kredit-finanzberatung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=187"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/187\/revisions"}],"predecessor-version":[{"id":276761,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/187\/revisions\/276761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/199083"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}