{"id":18798,"date":"2011-05-06T06:48:25","date_gmt":"2011-05-06T05:48:25","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=18798"},"modified":"2017-03-14T09:40:08","modified_gmt":"2017-03-14T08:40:08","slug":"testversion-verzeichnisdiensts","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/testversion-verzeichnisdiensts-1018798\/","title":{"rendered":"Daten in einheitlicher Form als zentrales Unternehmensadressbuch"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18801\" title=\"Software f\u00fcr zentrales Unternehmensadressbuch\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/18798\/xphone_box_uc_sch_l 2011_1-266x300.jpg\" alt=\"\" width=\"111\" height=\"125\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/18798\/xphone_box_uc_sch_l%202011_1-266x300.jpg 266w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/18798\/xphone_box_uc_sch_l%202011_1.jpg 888w\" sizes=\"auto, (max-width: 111px) 100vw, 111px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Die Software greift auf verteilte Kontaktdaten zu, vereinheitlicht diese und stellt ein zentrales Unternehmensadressbuch f\u00fcr verschiedenste Endger\u00e4te, Anwendungen und Systeme bereit.<br \/> Germering, 3. Mai 2011 \u2013 Der Germeringer Unified Communications  und CTI-Spezialist C4B stellt interessierten Anwendern und Administratoren ab sofort eine kostenlose Testversion seiner aktuellen Middleware XPhone Virtual Directory 2011 zum Download auf seiner Homepage zur Verf\u00fcgung. Die Software kann mit vollem Funktionsumfang f\u00fcr einen Zeitraum von 30 Tagen genutzt. <!--more-->Alternativ kann die Software aber auch im sogenannten Testbetrieb ohne zeitliche Beschr\u00e4nkung genutzt werden. In diesem Fall werden allerdings die Daten unkenntlich dargestellt.<br \/> Verteilte Kontaktdaten kommen in jedem Unternehmen vor. Bei der Software handelt es sich um einen LDAP basierten Verzeichnisdienst (LDAP Server), der auf all diese verteilten Kontaktdaten zugreift, auch wenn sie auf verschiedene Standorte, Datenbanken oder spezielle Anwendungen verteilt sind. Diese Daten werden in einheitlicher Form als zentrales Unternehmensadressbuch f\u00fcr verschiedenste Endger\u00e4te, Anwendungen und Systeme bereitgestellt. Ein zentrales webbasiertes Adressbuch f\u00fcr den Einsatz im Intranet von Unternehmen liefert der Hersteller gleich mit. Neben dem Einsatz als Erweiterung von CTI oder Unified Communications L\u00f6sungen, k\u00f6nnen Anwender mit LDAP-f\u00e4higen B\u00fcro- und Mobiltelefonen direkt auf dieses zentrale Adressbuch zugreifen. So k\u00f6nnen Kontaktinformationen aus Kundendatenbanken (CRM), Warenwirtschaftssystemen (ERP) im B\u00fcro und auch unterwegs genutzt werden. Mit Virtual Directory ist es m\u00f6glich, Benutzern Zugriff auf diese Kontaktdaten zu geben, auch wenn diese keinen Zugriff auf die Datenbanken beziehungsweise Anwendungen haben, in denen die Daten gespeichert sind. So kann auch das Sekretariat Kontakte und Rufnummern eines ERP-Systems abfragen, ohne dass das Sekretariat \u00fcberhaupt die ERP-Software nutzt.<br \/> Zugriff auf praktisch alle Datenquellen<br \/> Der Zugriff auf die Datenquellen erfolgt \u00fcber eine LDAP-Schnittstelle. Egal ob die Kontaktdaten in SQL-Datenbanken, CSV oder XML Dateien, in CRM beziehungsweise ERP-Systemen oder einem Microsoft Active Directory oder anderen Quellen abgelegt sind &#8211; mit XPhone Virtual Directory erreicht man praktisch den gesamten Datenbestand.  Selbst \u00f6ffentliche oder pers\u00f6nliche Outlook Kontaktordner lassen sich so verkn\u00fcpfen. Ein Konfigurationsassistent hilft dabei neue Datenquellen schnell und einfach hinzuzuf\u00fcgen, ohne dass daf\u00fcr Programmierkenntnisse notwendig sind. Datenbankfelder werden dabei ganz einfach per Drag &amp; Drop zugeordnet.<br \/> Keine doppelte Datenhaltung<br \/> Im Gegensatz zu anderen Verzeichnisdiensten greift XPhone Virtual Directory immer direkt auf die originalen Daten zu. Die Daten werden hierf\u00fcr nicht repliziert, so dass keine doppelte Datenhaltung stattfindet. Dadurch wird au\u00dferdem sichergestellt, dass stets auf aktuelle Informationen zugegriffen wird.<br \/> Single Sign On und sicherer Zugriff<br \/> Die Software unterst\u00fctzt die Windows-Authentifizierung. Das bedeutet, dass Benutzer automatisch erkannt werden, sobald sie sich an ihrem Computer anmelden. Welcher Mitarbeiter auf welche Datenquellen zugreifen darf, kann individuell festgelegt werden. Die Berechtigungen werden auf Basis von Active Directory Benutzern und Sicherheitsgruppen vergeben. \u00dcber LDAPS sind SSL-verschl\u00fcsselte Zugriffe m\u00f6glich.<br \/> Optimale Performance<br \/> Ein integrierter Index erm\u00f6glicht schnelles, flexibles und einfaches Suchen, wie man es von g\u00e4ngigen Suchmaschinen gewohnt ist. Kurzfristig wiederkehrende Suchanfragen werden durch den integrierten Cache gepuffert. Anwender haben so noch schneller Zugriff auf die relevanten Informationen und die Originaldatenquellen werden weniger belastet.<br \/> Lizenzierung und Verf\u00fcgbarkeit<br \/> Der Verzeichnisdienst XPhone Virtual Directory ist in zwei Ausbaustufen \u2013 Basic und Advanced \u2013 verf\u00fcgbar. Die Systemlizenz f\u00fcr den unternehmensweiten Einsatz ist bereits ab 499 Euro (UVP netto) erh\u00e4ltlich. Der Vertrieb erfolgt \u00fcber den TK-Fachhandel sowie \u00fcber die Distributoren Komsa, Itancia. Der Hersteller stellt ab sofort eine kostenfreie Testversion auf der Webseite www.xphonevirtualdirectory.com bereit.<br \/> \u00dcber C4B Com For Business AG Gesellschaft f\u00fcr Informations- und Kommunikationstechnik<br \/> Die 1999 gegr\u00fcndete C4B Com For Business AG entwickelt und vermarktet CTI- und Unified Communications-Software, die unter dem Markennamen XPhone in Unternehmen aller Gr\u00f6\u00dfen und Branchen eingesetzt wird. Mit Diensten wie Sprache, Fax, CTI, Presence und Instant Messaging sowie L\u00f6sungen f\u00fcr mobile Mitarbeiter verbessert Software von C4B die Interaktion von Unternehmen mit ihren Kunden nachhaltig und sorgt auch unternehmensintern f\u00fcr effiziente Kommunikationsprozesse. Die St\u00e4rke der herstellerunabh\u00e4ngigen L\u00f6sungen liegt in ihrer hohen Integrationsf\u00e4higkeit: Offene Schnittstellen stellen sicher, dass sich die XPhone-L\u00f6sungen reibungslos in verschiedensten Infrastrukturen und mit unterschiedlichen TK-Plattformen integrieren. Mit mehr als einer halben Million installierter Lizenzen in ganz Europa und dar\u00fcber hinaus geh\u00f6rt C4B zu den Marktf\u00fchrern im CTI- und Unified Communications-Umfeld. Der Vertrieb der L\u00f6sungen erfolgt \u00fcber ein umfassendes Netz qualifizierter Partner, darunter auch namhafte Hersteller wie Siemens, Deutsche Telekom und Swisscom. Mehr \u00fcber C4B erfahren Sie unter www.c4b.de.<br \/> Herstellerkontakt:<br \/> C4B Com For Business AG<br \/> Marko Gatzemeier<br \/> Marketing Manager<br \/> Gabriele-M\u00fcnter-Stra\u00dfe 3-5<br \/> D-82110 Germering<br \/> Telefon +49 (89) 84 07 98-194<br \/> PC-Fax +49 (89) 84 07 98-13194<br \/> Telefax +49 (89) 84 07 98-100<br \/> Email: marko.gatzemeier@c4b.de www.c4b.de<br \/> Presseagentur:<br \/> PROFIL MARKETING<br \/> Public Relations<br \/> Arno L\u00fccht<br \/> Tel.: 089 &#8211; 2424 16-93<br \/> Email: a.luecht@profil-marketing.com<br \/> www.profil-marketing.com<\/p> <p>Informieren Sie sich auch \u00fcber Fachzeitschriften zum Thema <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.fachzeitungen.de\/seite\/p\/kat\/katid\/27\" title=\"Fachzeitschriften f\u00fcr den Bereich Internet und Computer\" >Computer- Internet<\/a><\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Software greift auf verteilte Kontaktdaten zu, vereinheitlicht diese und stellt ein zentrales Unternehmensadressbuch f\u00fcr verschiedenste Endger\u00e4te, Anwendungen und Systeme bereit. Germering, 3. Mai 2011 \u2013 Der Germeringer Unified Communications und CTI-Spezialist C4B stellt interessierten Anwendern und Administratoren ab sofort eine kostenlose Testversion seiner aktuellen Middleware XPhone Virtual Directory 2011 zum Download auf seiner Homepage<\/p>\n","protected":false},"author":291,"featured_media":198303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-18798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-computer-und-videospiele"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=18798"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18798\/revisions"}],"predecessor-version":[{"id":268786,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/18798\/revisions\/268786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198303"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=18798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=18798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=18798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}