{"id":188,"date":"2008-04-14T18:42:58","date_gmt":"2008-04-14T17:42:58","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/neue-bucher-bei-hoffmann-und-campe-corporate-publishing\/"},"modified":"2010-07-26T14:23:03","modified_gmt":"2010-07-26T13:23:03","slug":"neue-bucher-bei-hoffmann-und-campe-corporate-publishing","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/neue-bucher-bei-hoffmann-und-campe-corporate-publishing-10188\/","title":{"rendered":"Neue B\u00fccher bei HOFFMANN UND CAMPE Corporate Publishing"},"content":{"rendered":"<p>Hamburg, 14. April 2008.# HOFFMANN UND CAMPE Corporate Publishing erschlie\u00dft neue Genres im Bereich Corporate Book. Dieser Tage erscheinen das Kochbuch Gaumenfreu(n)de zwischen Iller und Lech und das innovative Kinderbuch Energie! Entdecke, was die Welt bewegt! im Buchhandel.<!--more--><\/p> <p>Gaumenfreu(n)de zwischen Iller und Lech wurde im Auftrag der Lechwerke AG, Augsburg, realisiert. Das Kochbuch bietet nicht nur alte und neue Rezepte k\u00f6stlicher regionaler Spezialit\u00e4ten, auch prominente aus Bayerisch-Schwaben kommen zu Wort und pr\u00e4sentieren ihre Lieblingsrezepte. Das 144 Seiten starke Buch, das auf der Augsburger Fr\u00fchjahrsaustellung 2008 (AFA) vorgestellt wurde, ist im Buchhandel und in den Kundenforen der LEW erh\u00e4ltlich.<\/p> <p>Gaumenfreu(n)de zwischen Iller und Lech nimmt den Leser mit auf eine kulinarische Reise durch Bayerisch-Schwaben. Reiseleiter sind die Menschen aus der Region. Etwa die Sennerin Eva Endre\u00df, deren Romadur-K\u00e4se aussieht wie ein kleiner Goldbarren, oder der \u201eKr\u00e4uter-Michel\u201d, der aus Enzian-Wurzeln k\u00f6stliche Destillate zaubert.<\/p> <p>Mit dem Kinderbuch Energie! Entdecke, was die Welt bewegt setzt der Verlag seine erfolgreiche Zusammenarbeit mit der RWE AG fort. Das Wissensbuch, das sich an Kinder und Jugendliche zwischen 10 und 14 Jahren richtet, liefert ausf\u00fchrliche Informationen zum Themenkomplex Energie.<\/p> <p>Eingebettet in eine Rahmenhandlung, die als Comic gestaltet ist, werden in einem Sachbuchteil aktuelle Fragestellungen, die in das Interessensgebiet der Zielgruppe fallen, behandelt: Woher kommt der Strom f\u00fcr mein Handy, warum wird nicht alle Energie aus Solarzellen erzeugt und was ist das eigentlich, Energie? Spannend, unterhaltsam und verst\u00e4ndlich aufbereitet liefert Energie! Entdecke, was die Welt bewegt! Antworten und Hintergrundinformationen.<\/p> <p>Eine eigens zum Buch entwickelte Microsite (www.jungeenergie.com) erm\u00f6glicht zudem ab<br \/> 18. April die direkte Kommunikation mit der Zielgruppe. Hier werden die im Buch gestellten Fragen ausgeweitet, inhaltlich vertieft und dar\u00fcber hinaus durch multimediale Inhalte erg\u00e4nzt.<\/p> <p>Bibliografische Angaben<br \/> Gaumenfreu(n)de zwischen Iller und Lech\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 Energie! Entdecke, was die Welt bewegt!<br \/> HOFFMANN UND CAMPE VERLAG\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 HOFFMANN UND CAMPE VERLAG<br \/> 144 Seiten, Hardcover\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 208 Seiten, Broschur<br \/> 150 farbige Abbildungen\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 mit Comiczeichnungen und vielen Grafiken<br \/> \u20ac 22,00 [D], \u20ac 22,70 [A], sFr 38,90\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 \u20ac 17,95 [D] \/ \u20ac 18,50 [A] \/ sFr. 31,90<br \/> ISBN : 978-3-455-50082-0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 ISBN: 978-3-455-50080-6<\/p> <p>Weitere Informationen:<br \/> Presse- und \u00d6ffentlichkeitsarbeit<br \/> Simone Walper\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 Silke Ohlenforst<br \/> Fon: 040.44188-251\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0 Fon: 040.44188-212<br \/> Email: simone.walper@hoca.de\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 Email: silke.ohlenforst@hoca.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Hamburg, 14. April 2008.# HOFFMANN UND CAMPE Corporate Publishing erschlie\u00dft neue Genres im Bereich Corporate Book. Dieser Tage erscheinen das Kochbuch Gaumenfreu(n)de zwischen Iller und Lech und das innovative Kinderbuch Energie! Entdecke, was die Welt bewegt! im Buchhandel.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,17],"tags":[],"class_list":["post-188","post","type-post","status-publish","format-standard","hentry","category-ernahrung-umwelt-natur","category-familie-jugend-familie"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/188\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}