{"id":19914,"date":"2011-05-18T11:21:04","date_gmt":"2011-05-18T10:21:04","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=19914"},"modified":"2018-05-22T11:11:25","modified_gmt":"2018-05-22T10:11:25","slug":"prototyping-zahntechnik","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/prototyping-zahntechnik-1019914\/","title":{"rendered":"Neue Methodik f\u00fcr die Zahntechnik"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Dental-Prototyping nimmt das Risiko aus dem Prothetik-Workflow. Dental-Prototyping beruht auf der Methodik des Backward-Planning und hilft das wirtschaftliche Potential zu heben, das durch den digitalen Workflow in der Zahntechnik entsteht.<\/p> <p>Der Workflow<br \/> Nach der Erstellung des digitalen Modells (Modell- oder Mundscan), beginnt der Zahntechniker als erstes mit der CAD Konstruktion der Endversorgung. Die Detaillierung sollte vollst\u00e4ndig der endg\u00fcltigen Arbeit entsprechen, einschlie\u00dflich vollanatomischer Kaufl\u00e4chen.<\/p> <p><!--more-->Der Dental-Prototyp wird von diesem Datensatz weg aus dem Vollen gefr\u00e4st. Als Material sollte ein gut und schnell fr\u00e4sbarer, opaker Kunststoff verwendet werden. Excellente Biovertr\u00e4glichkeit und die Eignung f\u00fcr Endversorgungen sollten sichergestellt sein.<br \/> Der Dentale-Prototyp kommt fertig mit perfekten Oberfl\u00e4chen aus der CAM Maschine und wird ohne h\u00e4ndische, zahntechnische Bearbeitung direkt beim Patienten eingegliedert.<\/p> <p>In diesem Stadium sollte der Prototyp zun\u00e4chst nicht weiter bearbeitet werden. Nach 2-3 Tagen Tragezeit haben sich Zahnbewegungen wieder stabilisiert. Jetzt ist der richtige Zeitpunkt, um in einer Sitzung die notwendigen Anpassungen an der Arbeit des Patienten vorzunehmen. Das Einschleifen ist am Prototypen aus Kunststoff deutlich weniger aufw\u00e4ndig als bei Metall oder Keramik und ist daher auch schneller erledigt.<br \/> Gegebenenfalls kann sogar die Pr\u00e4paration angepasst und ein zweiter Prototyp angefertigt werden.<\/p> <p>Nach einer weiteren Trage-Phase oder nach Abschluss einer begleitenden Therapie, wenn der Patient beschwerdefrei ist, wird der Dental-Prototyp gescannt. Die Daten des Scans werden mit der CAD-Konstruktion abgeglichen und die CAD-Konstruktion entsprechend angepasst. Der Zahnarzt kann z.B. noch Hinweise f\u00fcr die Lachlinie aufbringen etc..<\/p> <p>Auf dieser Basis beginnt jetzt die Anfertigung der hochwertigen Endversorgung. Da die Daten des Prototypen im CAD\/CAM Prozess 1:1 reproduziert werden k\u00f6nnen, erh\u00e4lt der Patient eine sch\u00f6ne Endarbeit, die von Anfang an ohne Probleme passt und nicht mehr korrigiert werden muss.<\/p> <p>Zu guter Letzt kann der Prototyp nach der Behandlung noch als Zweit-, Ersatz- oder Reiseprothese gute Dienste tun.<\/p> <p>Die Vorteile<br \/> Die Anfertigung eines aufw\u00e4ndigen und teuren Provisoriums in Handarbeit entf\u00e4llt. Die Kostenersparnis ist erheblich. Dar\u00fcber hinaus ist der Prototyp im digitalen Workflow 1:1 reproduzierbar, was mit einem handgefertigten Provisorien kaum gelingt.<\/p> <p>Die Erfahrung zeigt, dass gerade ein opakes Material die Beurteilung von Form und Funktion erleichtert. Zum einen tritt die Form f\u00fcr den Behandler klarer hervor, zum andern wird bei transluzenten Materialien subjektiv immer die Farbigkeit zuerst beurteilt. Der Patient projiziert die Begeisterung f\u00fcr die h\u00fcbschen Z\u00e4hne auf die gesamte Arbeit und nimmt St\u00f6rungen der Kaufunktion erst sp\u00e4ter wahr. Die sonst zahlreichen Korrektursitzungen entfallen.<\/p> <p>Dank der hervorragenden Vertr\u00e4glichkeit eines guten industriell auspolymerisierten Materials k\u00f6nnen Sie sicher sein, dass Irritationen nicht am Material sondern an der Form liegen. Verbesserungen k\u00f6nnen somit einfach ausprobiert werden.<\/p> <p>Die Endarbeit passt sofort beim Eingliedern perfekt und der Patient erh\u00e4lt erst jetzt seine &#8222;sch\u00f6nen&#8220; Z\u00e4hne. Die h\u00e4ufig beobachtete Ent\u00e4uschung, wenn die Keramik anders aussieht als die Acrylz\u00e4hne des Provisoriums, tritt nicht mehr ein. Der Patient verl\u00e4sst die Praxis mit einem positiven Erlebnis.<\/p> <p>Teure Nacharbeiten an der Endversorgung und das Risiko einer Besch\u00e4digung der Arbeit beim Einpassen entfallen vollst\u00e4ndig.<\/p> <p>Das Prototyping-Material<br \/> Promysan hat sich als ideales Material f\u00fcr das Dental-Prototyping erwiesen. Der Kunststoff auf PET-Basis ist ein seit 1997 eingef\u00fchrtes Medizinprodukt und anerkannterma\u00dfen hochvertr\u00e4glich. Die CAD\/CAM Verarbeitung ist problemlos, schnell und kosteng\u00fcnstig. Im Gegensatz zu PMMA und Acetal ist Promysan ein teilkristalliner Kunststoff der nicht transluzent ist und 0,00% Restmonomer enth\u00e4lt. Promysan ist f\u00fcr Endanwendungen zugelassen, so dass die Tragedauer nicht begrenzt ist.<\/p> <p>Das Fr\u00e4szentrum<br \/> Dental-Prototyping wird von DMC-Cologne als Bestandteil des Produktions-Workflows angeboten. Alle Neukunden erhalten in den ersten 6 Monaten bei Zirkon und Implantatarbeiten ab 8 Glieder ein kostenloses Dental-Prototyping.<\/p> <p>Dental-Prototyping ist eine Methodik, die von Frank Wallossek (ZTM, Wallossek Dentaltechnik, DMC-Cologne) mit Antonio Pedrazzini (Promysan) entwickelt wurde.<\/p> <p>Angaben zum Unternehmen:<\/p> <p>DMC Cologne GmbH &amp; Co. KG<br \/> Ruth-Hallensleben Str. 4<br \/> 50739 K\u00f6ln<\/p> <p>Telefon: +49 (0) 221 170 499 56<br \/> Fax: +49 (0) 221 170 490 53<br \/> E-Mail: info@dmc-cologne.com<br \/> Internet: www.dmc-cologne.com<\/p> <p>Firmenkontakt<br \/> Wallossek Dentalklinik GmbH<br \/> Frank Wallossek<br \/> Kuseler Str. 1<\/p> <p>50739 K\u00f6ln<br \/> Deutschland<\/p> <p>E-Mail: f.w@wallossek-dentaltechnik.de<br \/> Homepage: http:\/\/www.dmc-cologne.com<br \/> Telefon: 0221\/917466-0<\/p> <p>Pressekontakt<br \/> Wallossek Dentalklinik GmbH<br \/> Frank Wallossek<br \/> Kuseler Str. 1<\/p> <p>50739 K\u00f6ln<br \/> Deutschland<\/p> <p>E-Mail: f.w@wallossek-dentaltechnik.de<br \/> Homepage: http:\/\/www.dmc-cologne.com<br \/> Telefon: 0221\/917466-0<\/p>","protected":false},"excerpt":{"rendered":"<p>Dental-Prototyping nimmt das Risiko aus dem Prothetik-Workflow. Dental-Prototyping beruht auf der Methodik des Backward-Planning und hilft das wirtschaftliche Potential zu heben, das durch den digitalen Workflow in der Zahntechnik entsteht. Der Workflow Nach der Erstellung des digitalen Modells (Modell- oder Mundscan), beginnt der Zahntechniker als erstes mit der CAD Konstruktion der Endversorgung. Die Detaillierung sollte<\/p>\n","protected":false},"author":291,"featured_media":198278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-19914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/19914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=19914"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/19914\/revisions"}],"predecessor-version":[{"id":269793,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/19914\/revisions\/269793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198278"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=19914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=19914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=19914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}