{"id":204534,"date":"2015-09-03T08:06:49","date_gmt":"2015-09-03T08:06:49","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=204534"},"modified":"2025-03-28T14:59:12","modified_gmt":"2025-03-28T13:59:12","slug":"alles-im-netz","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/alles-im-netz-10204534\/","title":{"rendered":"Alles im Netz"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Auch Wohnr\u00e4ume profitieren von vernetzten Ger\u00e4ten\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/0a0070e42de53fc4e52935ac96ebfd6f.jpg\" alt=\"Bild\" width=\"150\" height=\"150\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/0a0070e42de53fc4e52935ac96ebfd6f.jpg\" \/>Vollkommen vernetzt<\/p> <p>Moderne Empfangs- und Verteiltechnik legt die Medienwelt zu F\u00fc\u00dfen<\/p> <p>Das Stichwort &#8222;Vernetzung&#8220; spielt in unserem Alltag eine immer gr\u00f6\u00dfere Rolle. Tablet-PC, Smartphone und Notebook sind miteinander verbunden, \u00fcber sie lassen sich Kontakte zu Freunden und Familie aufrechterhalten. Gleichzeitig k\u00f6nnen wir mit ihnen die Haustechnik steuern &#8211; vom Heizkessel im Keller bis zu den Rolll\u00e4den unter dem Dach. Und immer enger spinnt sich das multimediale Netz: Stets mit dem Ziel, unseren Alltag in jeglicher Hinsicht noch komfortabler zu gestalten.<\/p> <p><!--more-->Die Firma WISI widmet sich seit \u00fcber acht Jahrzehnten der Optimierung von Empfangs- und Verteiltechnik. So z\u00e4hlt es zu den Aufgaben der Experten, zu gew\u00e4hrleisten, dass die Signale f\u00fcr TV und Internet schnell und zuverl\u00e4ssig dort hingelangen, wo sie ben\u00f6tigt werden &#8211; sie schaffen die Voraussetzungen daf\u00fcr, dass die Vernetzung wirklich problemlos funktioniert. Beispielsweise erachten wir es heute bereits als nahezu selbstverst\u00e4ndlich, dass der teure neue Flatscreen alle bekannten Sender in bester Qualit\u00e4t zeigt. In Krankenh\u00e4usern, Hotels und Co erwarten wir ein Entertainment-System, au\u00dferdem halten wir guten W-LAN-Empfang in \u00f6ffentlichen Geb\u00e4uden mittlerweile f\u00fcr ein Muss. Hier kommt jeweils WISI ins Spiel. Sei es eine moderne Satellitenempfangsanlage auf dem Dach, die Verteilung des Signals an die Ger\u00e4te im Haus oder &#8211; weit dar\u00fcber hinausgehend &#8211; die Verschmelzung von Fernsehen und Internet zum sogenannten Smart TV: Die Experten k\u00fcmmern sich um den reibungslosen Empfang und die bestm\u00f6gliche Kommunikation zwischen den einzelnen Ger\u00e4ten. F\u00fcr gro\u00dfe Objekte halten sie auch komplexe Systeml\u00f6sungen bereit &#8211; so sind etwa ein personalisierter Informationsdienst, ein eigenes Welcome-Men\u00fc, die Pay-TV-Einspeisung oder individuelle Senderlisten, zum Beispiel f\u00fcr Hotelg\u00e4ste, m\u00f6glich.<\/p> <p>Um solche W\u00fcnsche umfassend erf\u00fcllen zu k\u00f6nnen, f\u00fchrt WISI eine eigene Planungsabteilung &#8211; ein f\u00fcr H\u00e4ndler kostenfreier Service. F\u00fcr den Einbau der Technik vermittelt die Firma zudem an Partner weiter, die die Arbeiten fachm\u00e4nnisch ausf\u00fchren. Ob also privater H\u00e4uslebauer, Modernisierer, Hotelier oder Planer im Objektgesch\u00e4ft: WISI legt mit der passenden Empfangs- und Verteiltechnik &#8222;made in Germany&#8220; allen die Medienwelt zu F\u00fc\u00dfen. Mehr unter www.wisi.de.<\/p> <p>easy-PR\u00ae (epr) ist der f\u00fchrende Pressedienst f\u00fcr die Branchen Bauen, Wohnen und Einrichten.<\/p> <p>Kontakt<br \/> Faupel Communication GmbH<br \/> Frank W\u00e4lscher<br \/> D\u00fcsseldorfer Stra\u00dfe 88<br \/> 40545 D\u00fcsseldorf<br \/> 0211-74005-0<br \/> f.waelscher@faupel-communication.de<br \/> http:\/\/www.easy-pr.de<\/p> <p>&nbsp;<\/p> <p>Bildquelle: WISI<\/p>","protected":false},"excerpt":{"rendered":"<p>Vollkommen vernetzt Moderne Empfangs- und Verteiltechnik legt die Medienwelt zu F\u00fc\u00dfen Das Stichwort &#8222;Vernetzung&#8220; spielt in unserem Alltag eine immer gr\u00f6\u00dfere Rolle. Tablet-PC, Smartphone und Notebook sind miteinander verbunden, \u00fcber sie lassen sich Kontakte zu Freunden und Familie aufrechterhalten. Gleichzeitig k\u00f6nnen wir mit ihnen die Haustechnik steuern &#8211; vom Heizkessel im Keller bis zu den<\/p>\n","protected":false},"author":1,"featured_media":204901,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8806],"tags":[1734],"class_list":["post-204534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technik","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/204534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=204534"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/204534\/revisions"}],"predecessor-version":[{"id":277267,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/204534\/revisions\/277267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/204901"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=204534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=204534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=204534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}