{"id":2050,"date":"2009-09-21T06:38:04","date_gmt":"2009-09-21T05:38:04","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=2050"},"modified":"2010-07-26T14:20:02","modified_gmt":"2010-07-26T13:20:02","slug":"lohncologne-verstarkt-sich-personell","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/lohncologne-verstarkt-sich-personell-102050\/","title":{"rendered":"LohnCologne verst\u00e4rkt sich personell"},"content":{"rendered":"<p>Auszubildende nach erfolgreicher Pr\u00fcfung jetzt festangestellt<\/p> <p>Die K\u00f6lner Lohnabrechnungsfirma LohnCologne (www.lohncologne.de) vergr\u00f6\u00dfert ihre Belegschaft. Claudia Wassmann, seit August 2007 Auszubildende zur Kauffrau f\u00fcr B\u00fcrokommunikation, hat ihre m\u00fcndliche Pr\u00fcfung mit &#8222;sehr gut&#8220; absolviert und ist jetzt fester Bestandteil des LohnCologne-Teams. <!--more--><\/p> <p>&#8222;Mit der Festanstellung m\u00f6chten wir Frau Wassmann f\u00fcr die erfolgreiche Zusammenarbeit in den letzten zwei Jahren danken&#8220;, sagt LohnCologne-Inhaberin Katharina Schumacher. &#8222;Au\u00dferdem m\u00f6chten wir in der angespannten Wirtschaftslage ein positives Signal setzen und daf\u00fcr sorgen, dass wir personell optimal aufgestellt sind, sobald die Konjunktur wieder anzieht.&#8220;<\/p> <p>Gem\u00e4\u00df dem Motto &#8222;Wir entlasten Ihr Personalwesen&#8220; bietet die Firma LohnCologne ihren Kunden seit Anfang 2004 eine individuelle Betreuung in allen Fragen der Lohn-, Gehalts- und Entgeltabrechnung. Das Unternehmen bietet die Lohnabrechnungs-Servicepakete Lohn Classic, Lohn ClassicPlus und Lohn Baulohn &#8211; ein Leistungsangebot, das genau auf den Bedarf klein- und mittelst\u00e4ndischer Unternehmen abgestimmt ist.<\/p> <p>Daneben tritt LohnCologne als private Arbeitsvermittlung f\u00fcr Unternehmen und Bewerber auf. Die Branchenschwerpunkte liegen auf dem Sicherheits-, Reinigungs- und Baugewerbe. Inhaberin Katharina Schumacher kann auf mehr als 25 Jahre Berufserfahrung in der Personal- und Lohnbuchhaltungsbranche zur\u00fcckblicken,<\/p> <p>Lohnabrechnung auslagern<\/p> <p>Kleine und mittelst\u00e4ndische Unternehmen m\u00fcssen viel Zeit mit der Lohn- und Gehaltsabrechnung verbringen, insbesondere wenn Mitarbeiter nicht vollbesch\u00e4ftigt sind und sich die Anzahl der Mitarbeiter h\u00e4ufig \u00e4ndert. Diese Zeit, die bei Kleinunternehmen oft die Gesch\u00e4ftsf\u00fchrung aufwendet, lie\u00dfe sich bei der eigentlichen Gesch\u00e4ftst\u00e4tigkeit deutlich sinnvoller einsetzen. Das Auslagern der Lohn- und Gehaltsabrechnung an eine Lohnbuchhaltungsfirma f\u00fchrt in der Regel zu einer deutlichen Entlastung in den Unternehmen.<\/p> <p>&#8222;Die Kostenintensit\u00e4t der eigenen Personalabteilung ist meist ausschlaggebend f\u00fcr den Wechsel zu einer Lohnabrechnungsfirma. Oft ist es aber auch einfach der Wunsch nach mehr Service, der die Kunden zu uns f\u00fchrt, oder die nicht ganz einfachen gesetzlichen Bestimmungen, die sich permanent \u00e4ndern&#8220;, erl\u00e4utert Schumacher.<\/p> <p>Ihr pers\u00f6nlicher Ansprechpartner:<\/p> <p>Katharina Schumacher<br \/> LohnCologne<br \/> Pastor-Fa\u00dfbender-Str. 3<br \/> 50374 Erftstadt<br \/> Telefon: (02235) 95 43 49<br \/> Telefax: (02235) 95 43 50<br \/> E-Mail: info@lohncologne.de<br \/> Internet: www.lohncologne.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Auszubildende nach erfolgreicher Pr\u00fcfung jetzt festangestellt Die K\u00f6lner Lohnabrechnungsfirma LohnCologne (www.lohncologne.de) vergr\u00f6\u00dfert ihre Belegschaft. Claudia Wassmann, seit August 2007 Auszubildende zur Kauffrau f\u00fcr B\u00fcrokommunikation, hat ihre m\u00fcndliche Pr\u00fcfung mit &#8222;sehr gut&#8220; absolviert und ist jetzt fester Bestandteil des LohnCologne-Teams.<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-2050","post","type-post","status-publish","format-standard","hentry","category-wirtschaft-management-versicherung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/2050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=2050"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/2050\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=2050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=2050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=2050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}