{"id":20889,"date":"2011-06-06T13:59:49","date_gmt":"2011-06-06T12:59:49","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=20889"},"modified":"2013-08-09T10:29:34","modified_gmt":"2013-08-09T09:29:34","slug":"textinspektion-dienstleistungsangebot","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/textinspektion-dienstleistungsangebot-1020889\/","title":{"rendered":"Unterst\u00fctzung f\u00fcr Autoren eigener Webtexte"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Beckum- In Sachen Page-Content Produktion ist noch kein Meister vom Himmel gefallen. Doch ehrgeizige Lehrlinge und viel versprechende Azubis gibt es in hellen Scharen. Und die stecken oft all ihre Leistungsmotivation und nicht selten auch all ihr Herzblut in die Erzeugung eigener Webtexte. Was dabei herauskommt, kann sogar ein lesenswerter und spannender Fachartikel sein. Doch in der Mehrzahl der F\u00e4lle fehlt es den Amateur-Autoren schlie\u00dflich doch am verbalen Know-How und an den schriftstellerischen Profi-Tricks langj\u00e4hrig berufserfahrener Konzeptionstexter. <!--more-->Und dann leidet der mit kreativem Eifer, aber ohne schriftstellerische Sachkompetenz gebastelte Text an erheblichen Schw\u00e4chen, die der Webseite erhebliche Attraktivit\u00e4tseinbu\u00dfen bescheren k\u00f6nnen. Doch soll man als schreibfreudiger Webmaster oder Blogbetreiber deswegen gleich die Flinte ins Korn werfen?<br \/> &#8222;Jeder Autor und Texter hat irgendwann mal klein angefangen&#8220;, so wei\u00df Daniel Deppe, Inhaber der Beckumer Textagentur www.ONLINETEXTE.com, aus eigener Erfahrung zu berichten. &#8222;Nat\u00fcrlich macht man bei den ersten eigenen Gehversuchen auf dem Onlinetexte-Parkett auch schon mal Fehler, weil man eben noch nicht die n\u00f6tige Erfahrung und Routine hat. Doch davon soll man sich nicht verunsichern lassen. Schlie\u00dflich sind Fehler ja dazu da, dass man aus ihnen lernt. Und deshalb m\u00f6chte ich jeden, der sich selbst als Autor der eigenen Webtexte erproben will, erst ausdr\u00fccklich ermutigen, und dann tatkr\u00e4ftig unterst\u00fctzen&#8220;, so Herr Deppe weiter.<\/p> <p>Doch wie sieht diese Unterst\u00fctzung aus? &#8222;Wer es m\u00f6chte, kann mir seine selbst verfassten Onlinetexte zukommen lassen. Zus\u00e4tzlich brauche ich noch Informationen dar\u00fcber, f\u00fcr welche Zielgruppe die Onlinetexte gedacht sind, welche fachliche Breite und Tiefe sie haben sollen, welches sprachliche Qualit\u00e4tslevel angestrebt wird, und welche SEO-Kriterien zu erf\u00fcllen sind. Dann werde ich sehr gerne f\u00fcr ein ausgesprochen moderates Honorar die Texte gegenlesen, und notwendige Modifikationen detailliert vorschlagen. Dadurch bekommen die Texte einen professionellen Feinschliff, an dem auch die individuelle Schreibkunst des Autors best\u00e4ndig wachsen kann&#8220;. Keine Frage: Bei ONLINETEXTE.com ist die Textinspektion immer Chefsache. Daran l\u00e4sst Herr Deppe keine Zweifel aufkommen.<\/p> <p>Selbstverst\u00e4ndlich kann bei diesem fachkundigen Revisionsprozess auch die pers\u00f6nliche Erkenntnis reifen, dass man nicht so wirklich zum Schriftsteller oder Redakteur geboren ist. Auch in diesem Fall kann der Textservice ONLINETEXTE.com kompetent und kosteng\u00fcnstig weiterhelfen. Denn hier k\u00f6nnen weit \u00fcber 1000 bereits fertig produzierte redaktionelle Texte und Fachartikel f\u00fcr jedes Webseitenprojekt und f\u00fcr jedes Budget sofort abgerufen werden.<br \/> Egal, ob man an den eigenen literarischen F\u00e4higkeiten feilen m\u00f6chte, oder ob man sich sofort verf\u00fcgbaren Page Content preiswert beschaffen will &#8211; bei ONLINETEXE.com ist man immer an der richtigen Adresse.<\/p> <p>Fragen rund um das Angebot von www.ONLINETEXTE.com beantwortet Gesch\u00e4ftsf\u00fchrer Daniel Deppe gern pers\u00f6nlich:<\/p> <p>E-Mail: office@onlinetexte.com<br \/> Tel. +49 2521 8579391<br \/> Fax +49 2521 8579354<\/p> <p>Pressekontakt<\/p> <p>ONLINETEXTE.com<br \/> Inhaber: Daniel Deppe<br \/> Im Soestkamp 11<br \/> 59269 Beckum<br \/> Tel. +49 2521 8579391<br \/> Fax +49 2521 8579354<br \/> E-Mail: office@onlinetexte.com<br \/> Internet: http:\/\/www.onlinetexte.com<\/p> <p>Firmenportr\u00e4t<\/p> <p>ONLINETEXTE.com startete im Fr\u00fchjahr 2007 mit einem bis dahin fast unbekannten Konzept. Texte f\u00fcr Webmaster, Blogs, Pressemeldungen oder Templates konnten vorgefertigt in einem Onlineshop ausgesucht, bestellt und dann einfach f\u00fcr die eigenen Projekte verwendet werden.<br \/> Dieser neuartige Ansatz entwickelte sich geradezu beispiellos. Denn die bereits fertig produzierten Texte landen ohne Wartefrist beim Kunden und bringen dabei, zus\u00e4tzlich zum ben\u00f6tigten Inhalt, immer auch neue journalistische Ideen mit. So sind heute unter der Leitung von Gesch\u00e4ftsf\u00fchrer Daniel Deppe ein gutes Dutzend Autorinnen und Autoren f\u00fcr ONLINETEXTE.com t\u00e4tig, um regelm\u00e4\u00dfig neue Artikel f\u00fcr den Onlineshop zu verfassen. Und nat\u00fcrlich auch, um ma\u00dfgeschneiderte Werke im individuellen Kundenauftrag zu erstellen.<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Beckum- In Sachen Page-Content Produktion ist noch kein Meister vom Himmel gefallen. Doch ehrgeizige Lehrlinge und viel versprechende Azubis gibt es in hellen Scharen. Und die stecken oft all ihre Leistungsmotivation und nicht selten auch all ihr Herzblut in die Erzeugung eigener Webtexte. Was dabei herauskommt, kann sogar ein lesenswerter und spannender Fachartikel sein. Doch<\/p>\n","protected":false},"author":291,"featured_media":20892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-20889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/20889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=20889"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/20889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/20892"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=20889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=20889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=20889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}