{"id":21645,"date":"2011-06-16T16:59:02","date_gmt":"2011-06-16T15:59:02","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=21645"},"modified":"2012-08-02T08:17:44","modified_gmt":"2012-08-02T07:17:44","slug":"starkoch-schulter-schauen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/starkoch-schulter-schauen-1021645\/","title":{"rendered":"&#8222;Outdoor-Homing&#8220;: Wettbewerb mit Starkoch"},"content":{"rendered":"<p>Er ist einer der bekanntesten und beliebtesten K\u00f6che Deutschlands &#8211; und wom\u00f6glich auch einer der besten. Die Rede ist von Johann Lafer. Dass der Fernsehkoch nicht nur am Herd, sondern auch am Grill eine Koryph\u00e4e ist, davon k\u00f6nnen sich in diesem Sommer eine Familie und deren Freunde hautnah \u00fcberzeugen. Das Bausparermagazin &#8222;Mein Eigenheim&#8220; hat in Kooperation mit den Unternehmen Solarlux, Somfy und Weber-Stephen die Aktion &#8222;Genie\u00dferterrasse&#8220; gestartet. <!--more-->Der Gewinner erh\u00e4lt eine komplette Terrassenausstattung im Wert von 37.000 Euro und als Sahneh\u00e4ubchen einen exklusiven Grillabend mit dem Starkoch pers\u00f6nlich.<\/p> <p>Die Bewerbungsphase hat Mitte Mai begonnen und l\u00e4uft noch bis Anfang Juli. Wer sich bei dem Wettbewerb als Sieger durchsetzt, bekommt ein Glashaus, das auf der Terrasse montiert wird, eine automatisch gesteuerte Markise und einen Kugelgrill &#8211; gesponsort von den drei Kooperationspartnern der Aktion. Damit sind Hausbesitzer unabh\u00e4ngig von Wind, Wetter und Extremtemperaturen. Vielen genussvollen Abenden auf der eigenen Terrasse steht nichts mehr im Wege.<\/p> <p>Alle Details zum Wettbewerb, den Preisen und was bei der Bewerbung zu beachten ist, ist \u00fcber www.terrassenwelt.de erh\u00e4ltlich. Mitmachen kann praktisch jeder. Einzige Voraussetzung: Man muss selbst Eigent\u00fcmer der Terrasse sein. Wer nur einen Balkon besitzt, ist ebenfalls nicht von der Teilnahme ausgeschlossen. Als Sonderpreis loben die Sponsoren zus\u00e4tzlich eine Balkonausstattung mit Verglasung, Sonnenschutz und Grill aus. Damit k\u00f6nnen auch Balkonbesitzer ihren Platz an der Sonne voll genie\u00dfen.<\/p> <p>Das Konzept und die Idee zu dem Wettbewerb wurde von der Schaal.Trostner Kommunikation entwickelt &#8211; eine der erfahrensten Agenturen im Bereich Bauen und Wohnen in Deutschland -, die mit dieser Aktion drei herausragende Firmen ihrer jeweiligen Branche an einen Tisch bringt. Mit &#8222;Mein Eigenheim&#8220; wurde als Medienpartner eines der auflagenst\u00e4rksten Magazine f\u00fcr Bausparer und Bauherren gewonnen. Mit dem Konzept forciert die Agentur das Trendthema &#8222;Outdoor-Homing&#8220; zum Vorteil ihrer Kunden und besetzt es mit Johann Lafer als Aush\u00e4ngeschild besonders \u00f6ffentlichkeitswirksam. Ziel ist es, die Bekanntheit der beteiligten Firmen zu st\u00e4rken und schlie\u00dflich den Absatz ihrer Produkte zu f\u00f6rdern.<\/p> <p>Foto: Johann Lafer Unternehmensgruppe<\/p> <p>Firmenkontakt<br \/> Schaal.Trostner Kommunikation<br \/> Alexander Wei\u00df<br \/> Eichwiesenring 1\/1<\/p> <p>70567 Stuttgart<br \/> Deutschland<\/p> <p>E-Mail: Alexander.Weiss@schaal-trostner.de<br \/> Homepage: http:\/\/www.schaal-trostner.de\/<br \/> Telefon: 0711 77000 14<\/p> <p>Pressekontakt<br \/> Schaal.Trostner Kommunikation<br \/> Alexander Wei\u00df<br \/> Eichwiesenring 1\/1<\/p> <p>70567 Stuttgart<br \/> Deutschland<\/p> <p>E-Mail: Alexander.Weiss@schaal-trostner.de<br \/> Homepage: http:\/\/www.schaal-trostner.de\/<br \/> Telefon: 0711 77000 14<\/p>","protected":false},"excerpt":{"rendered":"<p>Er ist einer der bekanntesten und beliebtesten K\u00f6che Deutschlands &#8211; und wom\u00f6glich auch einer der besten. Die Rede ist von Johann Lafer. Dass der Fernsehkoch nicht nur am Herd, sondern auch am Grill eine Koryph\u00e4e ist, davon k\u00f6nnen sich in diesem Sommer eine Familie und deren Freunde hautnah \u00fcberzeugen. Das Bausparermagazin &#8222;Mein Eigenheim&#8220; hat in<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21645","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/21645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=21645"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/21645\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=21645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=21645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=21645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}