{"id":21797,"date":"2011-06-17T08:39:13","date_gmt":"2011-06-17T07:39:13","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=21797"},"modified":"2013-09-13T11:33:00","modified_gmt":"2013-09-13T10:33:00","slug":"bewerbungsentspurt-masterprogramme","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/bewerbungsentspurt-masterprogramme-1021797\/","title":{"rendered":"Einblicke in die neuesten wissenschaftlichen Managementans\u00e4tze in einem globalen Kontext"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Wer noch im September das Masterstudium an einer der f\u00fchrenden Wirtschaftshochschulen Deutschlands aufnehmen m\u00f6chte, muss schnell sein. Bewerbungsschluss f\u00fcr den Vollzeit-Master-Studiengang in Management (M.Sc.) sowie in General Management (MBA) ist der 20. bzw. 30. Juni 2011. Zugangsvoraussetzungen sind ein erster Hochschulabschluss, berufspraktische Erfahrungen sowie sehr gute Englischkenntnisse. Das Ergebnis des GMAT-Tests kann bis zum Studienstart nachgereicht werden. Die HHL bietet dazu am 2. Juli ein GMAT-Vorbereitungsseminar an. Weitere Informationen: www.hhl.de\/master<\/p> <p><!--more-->Der <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.hhl.de\/master\" title=\"Informationen zum Master-Studiengang in General Management\" >Master-Studiengang<\/a> in General Management (MBA) an der HHL<\/p> <p>Die von der HHL angebotenen englischsprachigen MBA-Programme z\u00e4hlen zu den besten unabh\u00e4ngig entwickelten Programmen ihrer Art in Deutschland. Herausragend im globalen Vergleich der Vollzeit-MBA-Angebote liegt der Anteil internationaler Studierender in diesem HHL-Programm bei ca. 70 Prozent. Seit seiner Einf\u00fchrung im Jahre 2000 ist das 18-monatige Vollzeit-MBA-Programm auf die Vermittlung von Management- und F\u00fchrungsf\u00e4higkeiten in einem globalen Kontext ausgerichtet. Verst\u00e4rkt wird dies durch ein innovatives Curriculum, das nicht mehr rein funktional, sondern interdisziplin\u00e4r nach Managementherausforderungen gegliedert ist (Managing Investors, Managing Society, Managing Customers, etc.). Diese funktions\u00fcbergreifende, stakeholderorientierte Perspektive verbindet die Inhalte der einzelnen Kurse und bietet den Studenten einen erheblichen Mehrwert. Sichergestellt wird dies durch 28 Dozenten aus sieben L\u00e4ndern. Sie geben den Studierenden Einblicke in die neuesten wissenschaftlichen Managementans\u00e4tze in einem globalen Kontext.<br \/> Der Praxisbezug wird u.a. durch praxisrelevante Lehrinhalte unter Einbeziehung von Fallstudien, einem studienbegleitenden Praxisprojekt, oder einem optionalen Praxisaufenthalt im Ausland sichergestellt. Internationales Management wird durch den internationalen Hintergrund von Studierenden und Professoren an der HHL nicht nur gelehrt, sondern auch t\u00e4glich gelebt. Die internationale Vernetzung des Programms kommt auch durch die zahlreichen Kooperationen mit ausl\u00e4ndischen Universit\u00e4ten zum Ausdruck. Von Australien bis Uruguay &#8211; die HHL verf\u00fcgt \u00fcber mehr als 100 Partneruniversit\u00e4ten im Ausland. Die Studenten haben die M\u00f6glichkeit, einen Term an einer dieser Partneruniversit\u00e4ten zu absolvieren.<br \/> Besonders hervorzuheben ist die intensive und professionelle Betreuung und Beratung der Studierenden, von der Kontaktaufnahme bis zum Alumninetzwerk. Ein Career Service begleitet zudem die Studierenden vom Tag der Zulassung zum Studiengang bis zur erfolgreichen Bewerbung. Weitere Informationen unter: www.hhl.de\/mba<\/p> <p>Der Master-Studiengang in Management (M.Sc.) an der HHL<\/p> <p>Der englischsprachige Masterstudiengang in Management (M.Sc.) der HHL beleuchtet ein vielseitiges Spektrum an Wirtschaftsthemen und baut auf einen wirtschaftswissenschaftlichen Bachelor auf. Die HHL legt besonderen Wert auf die Vermittlung von &#8222;Soft skills&#8220;. Kurse wie Problem Solving &amp; Communication, Negotiation oder International Management Competencies sind fester Bestandteil der Ausbildung. Das zweij\u00e4hrige Programm bietet acht Spezialisierungsm\u00f6glichkeiten, d.h. Finance, Accounting, Marketing, Logistics &amp; Supply Chain Management, Strategy, Entrepreneurship, Advanced Economics und Advanced General Management. Durch die Wahl von vier Modulen k\u00f6nnen die Studierenden den inhaltlichen Fokus f\u00fcr die angestrebte Karriere setzen. Fest integriert im Curriculum dieses zweij\u00e4hrigen Programms ist neben dem Auslandsstudium an einer der \u00fcber 100 Partnerhochschulen der HHL auch ein Praktikum. Weitere Informationen: www.hhl.de\/msc<\/p> <p>Die Handelshochschule Leipzig (HHL)<\/p> <p>Die HHL ist eine universit\u00e4re Einrichtung und z\u00e4hlt zu den f\u00fchrenden internationalen Business Schools. Ziel der \u00e4ltesten betriebswirtschaftlichen Hochschule im deutschsprachigen Raum ist die Ausbildung leistungsf\u00e4higer, verantwortungsbewusster und unternehmerisch denkender F\u00fchrungspers\u00f6nlichkeiten. Neben der internationalen Ausrichtung spielt die Verkn\u00fcpfung von Theorie und Praxis eine herausragende Rolle. Die HHL zeichnet sich aus durch exzellente Lehre, klare Forschungsorientierung und praxisnahen Transfer sowie hervorragenden Service f\u00fcr ihre Studierenden. Weitere Informationen: www.hhl.de<\/p> <p>Firmenkontakt<br \/> Handelshochschule Leipzig gGmbH<br \/> Volker St\u00f6\u00dfel<br \/> Jahnallee 59<\/p> <p>04109 Leipzig<br \/> Deutschland<\/p> <p>E-Mail: volker.stoessel@hhl.de<br \/> Homepage: http:\/\/www.hhl.de<br \/> Telefon: 0341-9851-614<\/p> <p>Pressekontakt<br \/> Handelshochschule Leipzig gGmbH<br \/> Volker St\u00f6\u00dfel<br \/> Jahnallee 59<\/p> <p>04109 Leipzig<br \/> Deutschland<\/p> <p>E-Mail: volker.stoessel@hhl.de<br \/> Homepage: http:\/\/www.hhl.de<br \/> Telefon: 0341-9851-614<\/p>","protected":false},"excerpt":{"rendered":"<p>Wer noch im September das Masterstudium an einer der f\u00fchrenden Wirtschaftshochschulen Deutschlands aufnehmen m\u00f6chte, muss schnell sein. Bewerbungsschluss f\u00fcr den Vollzeit-Master-Studiengang in Management (M.Sc.) sowie in General Management (MBA) ist der 20. bzw. 30. Juni 2011. Zugangsvoraussetzungen sind ein erster Hochschulabschluss, berufspraktische Erfahrungen sowie sehr gute Englischkenntnisse. Das Ergebnis des GMAT-Tests kann bis zum Studienstart<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8808],"tags":[],"class_list":["post-21797","post","type-post","status-publish","format-standard","hentry","category-wissenschaft"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/21797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=21797"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/21797\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=21797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=21797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=21797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}