{"id":21904,"date":"2011-06-20T10:40:51","date_gmt":"2011-06-20T09:40:51","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=21904"},"modified":"2011-06-20T10:40:51","modified_gmt":"2011-06-20T09:40:51","slug":"weltblutspendertag-erfolg","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/weltblutspendertag-erfolg-1021904\/","title":{"rendered":"Blutspender sind Lebensretter"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"121\" height=\"126\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21907\" title=\"j\u00e4hrlicher Blutspendertag \" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/21904\/weltblutspendertag-200.jpg\" alt=\"\" width=\"139\" height=\"139\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/21904\/weltblutspendertag-200.jpg 200w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/21904\/weltblutspendertag-200-150x150.jpg 150w\" sizes=\"auto, (max-width: 139px) 100vw, 139px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Auch oder gerade wegen der EHEC-Thematik nahmen bundesweit wieder Tausende Blutspender und Interessierte an den zum 8. Weltblutspendertag am 14. Juni angebotenen Terminen teil. Zudem wurden Blutspender und ehrenamtliche Helfer aus ganz Deutschland in Berlin geehrt.<\/p> <p>Der 8. Weltblutspendertag stand dieses Jahr, zumindest in Deutschland, im Schatten der EHEC-Thematik. Vielleicht nutzten auch gerade deshalb am Weltblutspendertag wieder Tausende die von den Blutspendediensten des DRK (Deutsches Rotes Kreuz) angeboten Termine, um sich ausf\u00fchrlich \u00fcber das Thema Blutspende zu informieren oder gleich vor Ort Blut zu spenden.<\/p> <p><!--more-->Der Weltblutspendertag wird zu Ehren von Karl Landsteiner, dem Entdecker des ABO-Systems der Blutgruppen und Begr\u00fcnder der modernen Transfusionsmedizin, j\u00e4hrlich an seinem Geburtstag, dem 14. Juni begangen und macht darauf aufmerksam, wie notwendig die freiwillige und unentgeltliche Blutspende ist.<\/p> <p>Seit 2004 nehmen die Blutspendedienste des DRK diesen Tag zum Anlass, um das pers\u00f6nliche Engagement der Blutspender und ehrenamtlichen Helfer, die sich besonders verdient gemacht haben, zu w\u00fcrdigen. So wurden auch dieses Jahr wieder, stellvertretend f\u00fcr alle anderen, 65 Personen aus dem gesamten Bundesgebiet nach Berlin eingeladen und im feierlichen Rahmen f\u00fcr ihre Verdienste geehrt.<\/p> <p>Neben der feierlichen Auszeichnung im Schloss Charlottenburg mit der von Jette Joop designten Ehrennadel und der \u00dcbergabe einer Ehrenurkunde durch die DRK-Vizepr\u00e4sidentin Donata Freifrau Schenck zu Schweinsberg und der Rotkreuz-Botschafterin Carmen Nebel, wurde den Teilnehmern an den drei Tagen ihres Berlin-Aufenthaltes ein abwechselungsreiches Programm geboten.<\/p> <p>Die Anreise erfolgte am Montag, den 13. Juni. Untergebracht wurden die G\u00e4ste im \u201eMARITIM proArte\u201c Hotel Berlin. Nach der Begr\u00fc\u00dfung, dem obligatorischen Fototermin und dem Abendessen stand ein Besuch des Udo Lindenberg Musicals \u201eHinterm Horizont\u201c im Theater am Potsdamer Platz auf dem Programm. Der Weltblutspendertag am Dienstag begann mit einer Fahrt zum Gendarmenmarkt, einem Mittagessen sowie weiteren Fotoaufnahmen. Anschlie\u00dfend erfolgte eine zweieinhalbst\u00fcndige Schiffsrundfahrt vom Anleger Schlossbr\u00fccke Charlottenburg zum Schiffsanleger Friedrichstra\u00dfe\/Reichstagufer. Von dort aus konnten die G\u00e4ste zu Fu\u00df zur\u00fcck zum Hotel gehen, um sich zu erholen und f\u00fcr die Abendveranstaltung frisch zu machen. Am Abend ging es dann mit dem Bus zum Schloss Charlottenburg, wo in der Orangerie ein Abendessen eingenommen und die eigentliche Ehrung vollzogen wurde.<\/p> <p>Am Mittwochvormittag stand zum Abschluss noch eine Besichtigung des Bundeskanzleramtes auf dem Programm, ehe sich die G\u00e4ste wieder auf die Heimreise machten.<\/p> <p>Dazu DRK Vizepr\u00e4sidentin Donata Freifrau Schenck zu Schweinsberg: \u201eEigentlich ist es etwas zu bedauern, dass aufgrund der EHEC-Thematik der Weltblutspendertag ein wenig in den Hintergrund des medialen Interesses ger\u00fcckt ist. Die 65 Personen, die hier stellvertretend f\u00fcr die vielen freiwilligen Blutspender und ehrenamtlichen Helfer geehrt werden, leisten einen unsch\u00e4tzbaren Dienst f\u00fcr das Gemeinwohl. Blutspender sind Lebensretter. Das Deutsche Rote Kreuz sichert mit j\u00e4hrlich 3,8 Mio. Blutspenden zu 75% die Blutversorgung in Deutschland. Das ist nur m\u00f6glich, weil ca. 200.000 ehrenamtliche Helferinnen und Helfer bereitstehen, die einzelnen Blutspendetermine zu begleiten und zu betreuen. Den vielen Blutspendern und ehrenamtlichen Helfern geh\u00f6rt deshalb unser aller Dank.\u201c<\/p> <p>Auflistung der diesj\u00e4hrig geehrten Personen nach Bundesl\u00e4ndern:<\/p> <p>\u2022\tBaden-W\u00fcrttemberg: Kurt Holzwarth aus Kirchardt, Joachim Junghans aus Horb am Neckar, Edeltraud L\u00e4uger aus Umkirch, Nadine Mast aus Neulingen, Erich Noller aus Mauer, Thomas Schmalz aus Baden-Baden, Bernd Schwab aus Ittlingen und Armin Zumstein aus Markdorf<\/p> <p>\u2022\tBayern: Wilhelm E\u00dft aus Gersthofen, Elisabeth H\u00f6llein aus Hof, Heinrich M\u00fchlenbach aus Penzing, Karl Pfeilschifter aus Cham-Nunsting, Martin Riesemann aus Lechbruck am See, Joachim Strau\u00df aus Hilpoltstein und Johann Uhl aus Albertshofen<\/p> <p>\u2022\tBerlin: J\u00fcrgen Pally aus Charlottenburg-Wilmersdorf<\/p> <p>\u2022\tBrandenburg: Frank Baumann aus Baruth, Dieter Illgen aus Frankfurt an der Oder und Regina Schwarzer aus Spremberg<\/p> <p>\u2022\tBremen: Paul Sinsch aus Bremen \u2013 Huchting<\/p> <p>\u2022\tHessen: Katja Frauenfelder aus Rhina im Haunetal, Bettina Gibson-Altmann aus Gro\u00df-Zimmern, Dietmar Lenski aus Frankenberg, Inken Roth aus Neu-Anspach, Manuela Sturm aus Stadtallendorf und Helmut Urban aus Freigericht<\/p> <p>\u2022\tMecklenburg-Vorpommern: J\u00f6rg-Ulrich Leesch aus Gro\u00df L\u00fcdershagen, Werner Mann aus Dargen OT G\u00f6rke und Heike Neudel aus Rostock<\/p> <p>\u2022\tNiedersachsen: Egon Hillen aus Oldenburg, Hans-Hinnerk Meyer aus Hemslingen, Uwe Mischel aus Dornum, Hans M\u00fcller aus Schortens, Karl M\u00fcller aus Rhauderfehn, Wilhelm Rolfs aus Twistringen und Norbert Stolze aus Hilter<\/p> <p>\u2022\tNordrhein-Westfalen: Hubert Breuer aus Simmerath, Helmut Demers aus T\u00f6nisvorst, Manfred Eigendorf aus Porta Westfalica, Hildegard Ewert aus Bielefeld, Rainer Frenz aus G\u00fctersloh, Manfred Hibbeln aus Lichtenau-Kleinenberg, Karl Walter Przybyl aus Bergkamen, Joachim Schindler aus L\u00fcnen, Jennifer R\u00f6\u00dfler aus Soest, Hans-Hermann Schmitz aus Duisburg, Petra Schr\u00f6der aus Holzwickede und Franz Schwister aus Euskirchen<\/p> <p>\u2022\tRheinland-Pfalz: Elisabeth Mies aus Kirchen (Sieg) sowie Peter Ott und Heinz-Werner Kleine-Natrop, die beide aus Ettringen kommen<\/p> <p>\u2022\tSaarland: Franz Meiers aus Losheim am See<\/p> <p>\u2022\tSachsen: Christian Krug aus Leipzig, Manfred Nitzsche aus Glauchau, Peter Steudel aus Reichenbach sowie Manfred Buhrow und Heinz Linn\u00e9, die beide aus Dresden kommen<\/p> <p>\u2022\tSachsen-Anhalt: Hans J\u00fcrgen Becker aus Oschersleben und Reinhard Reinelt aus Zahna<\/p> <p>\u2022\tSchleswig-Holstein: Helmut Ihms aus Heikendorf, Johannes Godbersen aus Gro\u00dfenwiehe und Susanne Nicola aus Selent<\/p> <p>\u2022\tTh\u00fcringen: Inge Kautz aus Eisenberg und Rita Milde aus P\u00f6\u00dfneck<\/p> <p>Weitere Informationen \u00fcber den Weltblutspendertag, detaillierte Ausk\u00fcnfte zur Blutspende sowie zu den aktuellen Blutspendeterminen sind unter der kostenlosen Spender-Hotline 0800 \u2013 11 949 11 oder im Internet unter www.drk-blutspende.de abrufbar.<\/p> <p>Ansprechpartner f\u00fcr R\u00fcckfragen zu dieser Pressemitteilung:<\/p> <p>(1) Pressekontakt Weltblutspendertag<\/p> <p>Ansprechpartner: Herr Friedrich-Ernst D\u00fcppe<\/p> <p>DRK-Blutspendedienst West gGmbH<br \/> Feithstr. 182<br \/> D-58097 Hagen<\/p> <p>Telefon: +49 (0) 2331 8 07 &#8211; 110<br \/> Fax: +49 (0) 2331 8 81 &#8211; 326<br \/> E-Mail: f.dueppe@bsdwest.de<br \/> Internet: http:\/\/www.blutspendedienst-west.de<\/p> <p>(2) Pressekontakt PR-Agentur PR4YOU<\/p> <p>Ansprechpartner: Marko Homann, Holger Ballwanz<\/p> <p>PR-Agentur PR4YOU<br \/> Schonensche Stra\u00dfe 43<br \/> D-13189 Berlin<\/p> <p>Telefon: +49 (0) 30 43 73 43 43<br \/> Fax: +49 (0) 30 44 67 73 99<br \/> E-Mail: presse@pr4you.de<br \/> Internet: http:\/\/www.pr4you.de<\/p> <p>(3) Kontakt Deutsches Rotes Kreuz &#8211; Generalsekretariat<\/p> <p>Ansprechpartner: Herr Andreas Rieger<\/p> <p>Deutsches Rotes Kreuz &#8211; Generalsekretariat<br \/> Carstennstra\u00dfe 58<br \/> D-12205 Berlin<\/p> <p>Telefon: +49 (0) 30 8 54 04 &#8211; 153<br \/> Fax: +49 (0) 30 8 54 04 &#8211; 456<br \/> E-Mail: riegera@drk.de<br \/> Internet: http:\/\/www.drk.de<\/p> <p>Hintergrundinformationen:<\/p> <p>\u00dcber den Weltblutspendertag:<\/p> <p>Am Weltblutspendertag am 14. Juni ehrt das Deutsche Rote Kreuz (DRK) besonders verdiente Blutspender und Ehrenamtliche. Die Blutspendedienste des DRK laden dazu seit 2004 jedes Jahr 65 B\u00fcrgerinnen und B\u00fcrger aus ganz Deutschland stellvertretend f\u00fcr die j\u00e4hrlich 3,8 Mio. Blutspender\/innen beim DRK zu einer Festveranstaltung nach Berlin ein. Damit w\u00fcrdigt das DRK das freiwillige und unentgeltliche Engagement seiner besonders aktiven Blutspender und ehrenamtlichen Mitarbeiter der Blutspendedienste.<\/p> <p>W\u00e4hrend ihres Hauptstadtaufenthaltes erwartet die G\u00e4ste ein abwechslungsreiches Rahmenprogramm. H\u00f6hepunkt ist ein festlicher Empfang am Abend des Weltblutspendertages. Hier erhalten die G\u00e4ste aus der Hand des DRK-Pr\u00e4sidenten Dr. Rudolf Seiters und eines prominenten DRK-Botschafters eine Ehrenurkunde sowie die von der DRK-Botschafterin Jette Joop eigens f\u00fcr diesen Anlass gestaltete Ehrennadel der Blutspendedienste.<\/p> <p>Weltblutspendertag<\/p> <p>Im Jahr 2004 hat die Weltgesundheitsorganisation WHO gemeinsam mit der Internationalen F\u00f6deration der Rotkreuz- und Rothalbmondgesellschaften den Weltblutspendertag ins Leben gerufen, um auf die Bedeutung der Blutspende und die humanit\u00e4re Leistung der Spender aufmerksam zu machen.<\/p> <p>In Deutschland werden j\u00e4hrlich knapp f\u00fcnf Millionen Vollblutspenden ben\u00f6tigt. Davon stellen die sieben DRK-Blutspendedienste j\u00e4hrlich 3,8 Mio. Vollblutspenden. Das entspricht 15.000 Blutspenden t\u00e4glich oder elf Spenden pro Minute allein beim DRK. Das DRK deckt auf der Grundlage freiwilliger und unentgeltlicher Blutspenden knapp 75 Prozent der Blutversorgung in Deutschland ab. Die Grunds\u00e4tze der Freiwilligkeit und Unentgeltlichkeit der Blutspende sind im ethischen Kodex der WHO und der internationalen Rotkreuz- und Rothalbmondbewegung festgesetzt und in den Richtlinien der EU und im deutschen Transfusionsgesetz umgesetzt.<\/p> <p>Blutspendetermine<\/p> <p>Unter der geb\u00fchrenfreien Service-Rufnummer 0800-11 949 11 k\u00f6nnen alle Fragen rund um das Thema Blutspende beantwortet und die aktuellen Blutspendetermine abgefragt werden. Weitere Informationen sind unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.drk-blutspende.de\" title=\"Informationen und aktuelle Blutspendetermine\" >http:\/\/www.drk-blutspende.de<\/a> abrufbar.<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Auch oder gerade wegen der EHEC-Thematik nahmen bundesweit wieder Tausende Blutspender und Interessierte an den zum 8. Weltblutspendertag am 14. Juni angebotenen Terminen teil. Zudem wurden Blutspender und ehrenamtliche Helfer aus ganz Deutschland in Berlin geehrt. Der 8. Weltblutspendertag stand dieses Jahr, zumindest in Deutschland, im Schatten der EHEC-Thematik. Vielleicht nutzten auch gerade deshalb am<\/p>\n","protected":false},"author":291,"featured_media":21907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-21904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/21904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=21904"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/21904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/21907"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=21904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=21904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=21904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}