{"id":22125,"date":"2011-06-22T07:59:33","date_gmt":"2011-06-22T06:59:33","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=22125"},"modified":"2017-10-06T13:37:36","modified_gmt":"2017-10-06T12:37:36","slug":"luftsauerstoff-lebenselixier","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/luftsauerstoff-lebenselixier-1022125\/","title":{"rendered":"Belebend und gleichzeitig entspannend"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Menschen m\u00fcssen ununterbrochen atmen, um lebenswichtigen Sauerstoff aus der Atemluft aufzunehmen. Pro Tag kommen da leicht 26.000 Atemz\u00fcge zusammen.<\/p> <p>Ohne Essen kann ein Mensch etwa 40 Tage, ohne Trinken fast f\u00fcnf Tage \u00fcberleben, ohne Sauerstoff aber nur wenige Minuten. Sauerstoff gilt daher zu Recht als Lebensmittel Nummer eins. 90 Prozent der rund 70 Billionen (das ist eine 7 mit 13 Nullen!) K\u00f6rperzellen, die unseren Organismus &#8222;von Kopf bis Fu\u00df&#8220; ausmachen, brauchen Sauerstoff. Nur mit Sauerstoff kann die Energie in den Zellen gebildet werden, die f\u00fcr die Vielzahl von Funktionen im K\u00f6rper ben\u00f6tigt wird: in Muskeln, Haut, Gehirn, Organen, Knochen, Nerven&#8230;<\/p> <p><!--more-->Unsere Atemluft besteht zu 21 Prozent aus Sauerstoff, von dem aber nur ein Viertel vom K\u00f6rper genutzt wird. Dreiviertel werden wieder ausgeschieden (Zum Vergleich: Das gr\u00f6\u00dfte S\u00e4ugetier, der Wal, verwertet 90 Prozent seines Luftsauerstoffs.) Diese Bilanz ist normalerweise ausreichend. Mit zunehmendem Alter, bei Stress, w\u00e4hrend eines anstrengenden Arbeitstages oder besonders auch bei chronischen Erkrankungen kommt es zu einem Nachlassen der Nutzungsf\u00e4higkeit der K\u00f6rperzellen. Wir f\u00fchlen das, indem wir nicht mehr so leistungsf\u00e4hig sind, schneller m\u00fcde werden, uns schlechter konzentrieren k\u00f6nnen, die Haut an Spannkraft verliert, und, und, und. Kurz: Der ganze Organismus l\u00e4uft zunehmend auf &#8222;Sparflamme&#8220;.<\/p> <p>Die L\u00f6sung ist jedoch simpel: Die Sauerstoffverwertung muss verbessert werden! Nicht ein Mehr an Sauerstoff, sondern die bessere Nutzung des in der Atemluft zur Verf\u00fcgung stehenden Sauerstoffs ist die L\u00f6sung, also mehr Qualit\u00e4t statt Quantit\u00e4t! Mit der so genannten Spirovital-Methode gelingt das nach jahrelanger Forschung. Die Natur stand Pate als man die technische L\u00f6sung fand: Der Luftsauerstoff wird so aufbereitet, wie der K\u00f6rper ihn kennt und wie er von den Zellen bestm\u00f6glich verwertet werden kann. Es werden also weder die Sauerstoffmenge erh\u00f6ht noch wird ionisiert oder Ozon zugef\u00fcgt oder gar chemische Substanzen eingesetzt.<\/p> <p>Durch die bessere Ausnutzung des vorhandenen Luftsauerstoffs in der Atemluft k\u00f6nnen die Zellen mehr Energie bereitstellen. Die Schutzfunktion der Zellen gegen so genannte Freie Radikale wird verbessert, der K\u00f6rper kann vermehrt eigene Schutzenzyme bilden, ohne dass irgendetwas von au\u00dfen zugef\u00fcgt wird.<\/p> <p>Wer die Spirovital-Methode schon einmal angewendet hat, wei\u00df nur Gutes zu berichten. Die Anwendung ist belebend und gleichzeitig entspannend &#8211; so Herbert Gr\u00f6nemeyer, der schon seit drei Jahren &#8222;bekennender Airnegetiker&#8220; ist. Grunds\u00e4tzlich wirkt sich die regelm\u00e4\u00dfige Anwendung positiv auf den gesamten Organismus aus: Die k\u00f6rpereigene Regenerationsf\u00e4higkeit wird erh\u00f6ht, das Immunsystem wird gest\u00e4rkt und der gesamte Stoffwechsel sowie der Energieaustausch zwischen den Zellen werden verbessert. Insgesamt kommt es zu mehr Lebenskraft und Lebenslust. Auf den Websites www.atemluft.info oder <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.airnergy.com\" title=\"Aufbereitung des Sauerstoffes zur besseren Ausnutzung\" >www.airnergy.com<\/a> gibt es jede Menge Informationen zur Spirovitalisierung und eine Vielzahl von Referenzen, von bekannten und ber\u00fchmten Anwendern. Per Mausklick auf eine Deutschlandkarte kann man durch die Angabe der Postleitzahl einen Therapeuten, ein Kosmetikinstitut oder ein Atemstudio in der N\u00e4he finden, wo die neue Atem-Methode angeboten wird. Dar\u00fcber hinaus gibt es eine umfangreiche Atemluft-Brosch\u00fcre zum Download. Sie enth\u00e4lt ebenfalls eine Vielzahl erstaunlicher Informationen und Tipps rund ums Atmen und das Lebensmittel Sauerstoff &#8211; eine spannende Lekt\u00fcre, denn wie bei allen Selbstverst\u00e4ndlichkeiten im Leben denkt man \u00fcber das Atmen erst dann nach, wenn einem im wahrsten Sinne der Atem stockt.<\/p> <p>Firmenkontakt<br \/> WEDOpress GmbH<br \/> Angelika Lemp<br \/> Im Portugall 9c<\/p> <p>61440 Oberursel<br \/> Deutschland<\/p> <p>E-Mail: Angelika.Lemp@wedopress.de<br \/> Homepage: http:\/\/www.wedopress.de<br \/> Telefon: 06171 91 41 0<\/p> <p>Pressekontakt<br \/> WEDOpress GmbH<br \/> Angelika Lemp<br \/> Im Portugall 9c<\/p> <p>61440 Oberursel<br \/> Deutschland<\/p> <p>E-Mail: Angelika.Lemp@wedopress.de<br \/> Homepage: http:\/\/www.wedopress.de<br \/> Telefon: 06171 91 41 0<\/p>","protected":false},"excerpt":{"rendered":"<p>Menschen m\u00fcssen ununterbrochen atmen, um lebenswichtigen Sauerstoff aus der Atemluft aufzunehmen. Pro Tag kommen da leicht 26.000 Atemz\u00fcge zusammen. Ohne Essen kann ein Mensch etwa 40 Tage, ohne Trinken fast f\u00fcnf Tage \u00fcberleben, ohne Sauerstoff aber nur wenige Minuten. Sauerstoff gilt daher zu Recht als Lebensmittel Nummer eins. 90 Prozent der rund 70 Billionen (das<\/p>\n","protected":false},"author":291,"featured_media":198227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-22125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernahrung-umwelt-natur"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=22125"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22125\/revisions"}],"predecessor-version":[{"id":269226,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22125\/revisions\/269226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198227"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=22125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=22125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=22125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}