{"id":22171,"date":"2011-06-22T08:43:19","date_gmt":"2011-06-22T07:43:19","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=22171"},"modified":"2014-11-26T16:59:24","modified_gmt":"2014-11-26T15:59:24","slug":"startschuss-zusammenarbeit","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/startschuss-zusammenarbeit-1022171\/","title":{"rendered":"Partnerschaft im Bereich \u00d6kologie und Umwelt"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>eBooks von Island Press zu \u00d6kologie und Umwelt auf SpringerLink<\/p> <p>Heidelberg \/ Dordrecht, 21. Juni 2011<\/p> <p>Springer wird in den n\u00e4chsten zwei Jahren mit Island Press, dem f\u00fchrenden gemeinn\u00fctzigen Verlag f\u00fcr \u00f6kologische Publikationen, kooperieren und seine Titel \u00fcber die Plattform SpringerLink verbreiten. Die B\u00fccher von Island Press werden Teil der Springer eBook Collections. Aufgrund seiner langj\u00e4hrigen Beziehungen zu Bibliotheken und seiner internationalen Marketing- und Vertriebsstruktur kann der Wissenschaftsverlag Springer Island Press bei der globalen Positionierung seiner Titel unterst\u00fctzen.<\/p> <p><!--more-->Von der Partnerschaft profitieren so angesehene Autoren von Island Press wie Peter H. Gleick, der international anerkannte Experte f\u00fcr Wasser, David W. Orr, eine Koryph\u00e4e auf dem Gebiet von Umweltpublikationen und Timothy Beatley, Experte f\u00fcr nachhaltige Gemeinschaften. Die Zusammenarbeit beginnt mit dem laufenden Copyright-Jahr 2011 und umfasst j\u00e4hrlich etwa 20 neue Titel von Island Press, die in der eBook Collection der Geo- und Umweltwissenschaften von Springer gef\u00fchrt werden. Island Press vertreibt weiterhin selbst seine Printb\u00fccher und eBooks f\u00fcr den Endnutzer.<\/p> <p>Catherine Cotton, Senior Publishing Editor in Life Sciences bei Springer, sagt: \u201eIsland Press ist weltweit bekannt f\u00fcr seine exzellenten B\u00fccher im Bereich \u00d6kologie und Umwelt, und wir sind gl\u00fccklich dar\u00fcber, dass wir diese Titel in unsere eBook Collection f\u00fcr Umwelt aufnehmen k\u00f6nnen.\u201c<\/p> <p>Brian Weese, Marketing Director bei Island Press, f\u00fcgt hinzu: \u201eIsland Press arbeitet unerm\u00fcdlich daran, die neuesten Ideen und Informationen denjenigen zug\u00e4nglich zu machen, die die Umwelt verstehen, sch\u00fctzen und L\u00f6sungen f\u00fcr Ihre komplexen Probleme entwickeln m\u00f6chten. Durch die Aufnahme von Island-Press-Titeln in die eBook Collections von Springer ist es m\u00f6glich, die B\u00fccher von Island Press mitsamt  unseren exzellenten Autoren einem breiteren Publikum zug\u00e4nglich zu machen.\u201c<\/p> <p>Island Press (www.islandpress.org) ist seit 1984 eine zuverl\u00e4ssige Quelle f\u00fcr Informationen und L\u00f6sungsans\u00e4tze im Bereich Umwelt. Island Press sorgt daf\u00fcr, dass sehr gute Ideen zum Umweltschutz erscheinen, sei es durch Print- oder Online-Produkte oder durch Experten-Know-How auf dem Gebiet der Naturschutzbiologie, Meereswissenschaft, Landschaftserhaltung, \u00f6kologische Bauweise, nachhaltige Landwirtschaft, Klimawandel und Umweltsanierung. Neben der Ver\u00f6ffentlichung von B\u00fcchern unterh\u00e4lt Island Press mehrere Programme im Bildungsbereich und zur F\u00f6rderung der Zusammenarbeit zwischen politischen Entscheidungstr\u00e4gern, Wirtschaftsf\u00fchrern, Anw\u00e4lten, Medien und der \u00d6ffentlichkeit zu relevanten Umweltproblemen.<\/p> <p>Springer (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.springer.com\/\" title=\"nahezu 500 Zeitschriften f\u00fcr wissenschaftliche Gesellschaften und Berufsverb\u00e4nde\" >www.springer.com<\/a>) ist ein international f\u00fchrender Wissenschaftsverlag, der hochwertige Inhalte in innovativen Informationsprodukten und Dienstleistungen publiziert. Springer ist Teil der Fachverlagsgruppe Springer Science+Business Media und ver\u00f6ffentlicht nahezu 500 Zeitschriften f\u00fcr wissenschaftliche Gesellschaften und Berufsverb\u00e4nde.  Im Bereich Science, Technology, Medicine (STM) ver\u00f6ffentlicht das Unternehmen j\u00e4hrlich etwa 2.000 Fachjournale, mehr als 7.000 neue B\u00fccher und die weltweit umfangreichste eBook Collection. Mit rund 5.500 Mitarbeitern hat die Gruppe Niederlassungen in \u00fcber 20 L\u00e4ndern in Europa, den USA und Asien.<\/p> <p>Kontakt: Joan Robinson, Springer, Tel.: +49-6221-487-8130, E-Mail: joan.robinson@springer.com<\/p> <p>Springer-Verlag GmbH, Heidelberg, Zweigniederlassung der Springer-Verlag GmbH, BerlinTiergartenstrasse 17D-69121 Heidelberg<\/p>","protected":false},"excerpt":{"rendered":"<p>eBooks von Island Press zu \u00d6kologie und Umwelt auf SpringerLink Heidelberg \/ Dordrecht, 21. Juni 2011 Springer wird in den n\u00e4chsten zwei Jahren mit Island Press, dem f\u00fchrenden gemeinn\u00fctzigen Verlag f\u00fcr \u00f6kologische Publikationen, kooperieren und seine Titel \u00fcber die Plattform SpringerLink verbreiten. Die B\u00fccher von Island Press werden Teil der Springer eBook Collections. Aufgrund seiner<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[361],"tags":[],"class_list":["post-22171","post","type-post","status-publish","format-standard","hentry","category-verlagsnachrichten"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=22171"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22171\/revisions"}],"predecessor-version":[{"id":173106,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22171\/revisions\/173106"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=22171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=22171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=22171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}