{"id":22272,"date":"2011-06-22T10:51:37","date_gmt":"2011-06-22T09:51:37","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=22272"},"modified":"2014-11-12T15:07:21","modified_gmt":"2014-11-12T14:07:21","slug":"krise-welt","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/krise-welt-1022272\/","title":{"rendered":"Ausblick auf die Welt von Morgen"},"content":{"rendered":"<p>(ddp direct) Franck Biancheri, europ\u00e4ischer Vordenker, politischer Aktivist und Verfasser des weltweit gelesenen Newsletters GEAB, hat Ende 2010 ein Buch vorgelegt. Anfang 2011 ist der 170 Seiten umfassende Text auch in Deutsch erschienen. Sein Titel lautet Nach der Krise Auf dem Weg in die Welt von Morgen. Europa und die Welt im Jahrzehnt 2010 bis 2020.<\/p> <p>* Das Buch ist in vier Kapitel gegliedert. Es beginnt mit einer Bestandsaufnahme und schildert die umfassende weltweite Krise als einen Infarkt im Herzen des globalen Systems. Dieser markiert nicht nur das Ende der Nachkriegszeit, sondern auch das Ende einer Welt, wie sie in Jahrhunderten europ\u00e4ischer und westlicher Dominanz geschaffen wurde. Damit kann auch die bisherige globale Steuerung und deren Institutionen wie beispielsweise G7 oder G20 nicht mehr funktionieren. <!--more-->Die Welt steht vor einem Scheideweg. Wenn die Jahre bis 2020 nun nicht dazu genutzt werden, eine neue, gerechtere globale Steuerung aufzubauen, droht ihr ein Abgleiten in Konflikte zwischen gro\u00dfen regionalen Bl\u00f6cken. In diesem zweiten Kapitel zeigt Franck Biancheri f\u00fcr jede dieser Regionen deren m\u00f6gliche Entwicklung nach der von ihm erarbeiteten Methode der Politischen Antizipation. Im dritten Kapitel kommen die Europ\u00e4er ins Spiel. Sie sollten dieses Jahrzehnt nicht ungenutzt verstreichen lassen, sofern Europa die Heimat der Europ\u00e4er werden und sich als globaler Akteur in der Welt von Morgen positionieren m\u00f6chte. Die Eliten der EU haben seit Mitte der 90er Jahre jedoch kein weiteres Ziel, als die Menschen daran zu hindern, aus Europa wieder ein politisches Projekt zu machen. Franck Biancheri sieht die EU vor der Herausforderung ihrer Demokratisierung und Euroland nun als Motor der Integration. Das Buch schlie\u00dft mit zwei m\u00f6glichen globalen Szenarien, wie sie sich im Laufe des kommenden Jahrzehnts entfalten k\u00f6nnten.<\/p> <p>* Das Buch ist im Eigenverlag Editions Anticipolis in Nizza erschienen. Programm des Verlags ist es, alle Ver\u00f6ffentlichungen gleich in f\u00fcnf europ\u00e4ischen Sprachen herauszugeben, um so eine europ\u00e4ische Debatte anzusto\u00dfen. Um diese mehrsprachige Debatte zu erm\u00f6glichen, wurde das Forum Anticipolis (http:\/\/forum-anticipolis.eu) eingerichtet.<\/p> <p>* Franck Biancheri ist Forschungsdirektor des europ\u00e4ischen Think Tanks LEAP\/Europe2020 (www.leap2020.eu) in Paris. Die spanische Pr\u00e4sidentschaft der EU hat ihn 2010 als einen von 14 Europ\u00e4ern pr\u00e4sentiert, die unser Leben ver\u00e4ndert haben. Er z\u00e4hlt zu den Gr\u00fcnderv\u00e4tern des ERASMUS-Programms und zu den Gr\u00fcndern der europaweiten Studierendenorganisation AEGEE. Franck Biancheri ist Vorsitzender der europ\u00e4ischen B\u00fcrgerbewegung Newropeans, die sich f\u00fcr die Demokratisierung Eurolands einsetzt.<\/p> <p>Shortlink zu diesem Social Media Release:<br \/> http:\/\/shortpr.com\/ea80fm<\/p> <p>Permanentlink zu diesem Social Media Release:<br \/> http:\/\/www.themenportal.de\/wirtschaftspolitik\/franck-biancheri-nach-der-krise-auf-dem-weg-in-die-welt-von-morgen-97671<\/p> <p>Die gesamteurop\u00e4ische B\u00fcrgerbewegung Newropeans wurde 2005 gegr\u00fcndet. Sie sieht sich weder rechts noch links und will f\u00fcr die gemeinsamen Interessen der europ\u00e4ischen B\u00fcrgerinnen und B\u00fcrger eintreten. Newropeans will au\u00dferdem nur so lange aktiv sein, bis die Demokratisierung der EU erreicht ist. Newropeans ist ein Verein in den Niederlanden und unabh\u00e4ngig.<\/p> <p>Firmenkontakt<br \/> Newropeans<br \/> Margit Reiser-Schober<br \/> &#8211;<\/p> <p>65824 Schwalbach am Taunus<br \/> Hessen<\/p> <p>E-Mail: mreiser-schober@newropeans.eu<br \/> Homepage: www.newropeans.eu<br \/> Telefon: &#8211;<\/p> <p>Pressekontakt<br \/> Newropeans<br \/> Margit Reiser-Schober<br \/> &#8211;<\/p> <p>65824 Schwalbach am Taunus<br \/> Hessen<\/p> <p>E-Mail: mreiser-schober@newropeans.eu<br \/> Homepage:<br \/> Telefon: &#8211;<\/p>","protected":false},"excerpt":{"rendered":"<p>(ddp direct) Franck Biancheri, europ\u00e4ischer Vordenker, politischer Aktivist und Verfasser des weltweit gelesenen Newsletters GEAB, hat Ende 2010 ein Buch vorgelegt. Anfang 2011 ist der 170 Seiten umfassende Text auch in Deutsch erschienen. Sein Titel lautet Nach der Krise Auf dem Weg in die Welt von Morgen. Europa und die Welt im Jahrzehnt 2010 bis<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-22272","post","type-post","status-publish","format-standard","hentry","category-politik-gesellschaft"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=22272"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22272\/revisions"}],"predecessor-version":[{"id":173015,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22272\/revisions\/173015"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=22272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=22272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=22272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}