{"id":22344,"date":"2011-06-24T09:57:00","date_gmt":"2011-06-24T08:57:00","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=22344"},"modified":"2011-06-24T09:57:00","modified_gmt":"2011-06-24T08:57:00","slug":"moderation-erfolg","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/moderation-erfolg-1022344\/","title":{"rendered":"Arbeits- und Kommunikationsprozesse effektiv planen und gestalten"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"121\" height=\"126\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-22347\" title=\"berufsbegleitende Moderationsausbildung\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/22344\/GOE_Moderation-279x300.jpg\" alt=\"\" width=\"119\" height=\"127\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/22344\/GOE_Moderation-279x300.jpg 279w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/22344\/GOE_Moderation.jpg 336w\" sizes=\"auto, (max-width: 119px) 100vw, 119px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Jetzt anmelden: Kompakte Weiterbildung ab August 2011 beim Bildungswerk ver.di<br \/> G\u00f6ttingen. Oft versanden neue Ideen im Arbeitsalltag, werden boykottiert oder einfach ausgesessen und vergessen. Dann ist es meist nicht gelungen, Mitarbeiter\/innen zu motivieren, Verantwortung f\u00fcr die Umsetzung zu \u00fcbernehmen. Hierf\u00fcr werden Handwerkszeuge gebraucht, die es erm\u00f6glichen, Betroffene zu Beteiligten zu machen. Moderationstechniken sind geeignet, um zu besseren Ergebnissen zu gelangen.<br \/> <!--more-->Das Bildungswerk ver.di in G\u00f6ttingen bietet ab August 2011 eine berufsbegleitende Moderationsausbildung an f\u00fcr Interessierte aus der Organisations- und Personalentwicklung, f\u00fcr Lehrer\/innen, Trainer\/innen, Berater\/innen und alle Interessierten, die in Teams und Projekten arbeiten oder in Gremien wie Betriebs- und Personalr\u00e4ten. In 100 Unterrichtsstunden werden Methoden vermittelt, um Arbeits- und Kommunikationsprozesse effektiv zu planen und zu gestalten. Die f\u00fcnf Module der \u201eMethodischeGruppenModeration (MGM)\u201c sind anwendungsorientiert und vermitteln Instrumente f\u00fcr unterschiedliche Einsatzbereiche. Immer ist es das Ziel, die Ideen aller Mitwirkenden einzubeziehen und als Potential f\u00fcr kreative Probleml\u00f6sungen zu verarbeiten. Mit Moderationsmethoden gelingt es, in Projektgruppen und Teams zu nachvollziehbaren Ergebnissen zu kommen, die von allen getragen und zielorientiert umgesetzt werden. Dies sichert den Projekterfolg und schafft Zufriedenheit. Auch Lehrkr\u00e4fte k\u00f6nnen diese Instrumente bei der Unterrichtsgestaltung nutzen.<br \/> Die Weiterbildung \u201eMethodischeGruppenModeration (MGM)\u201c vermittelt Kompetenzen auf drei zentralen Ebenen: Methoden-, Sozial- und Prozessgestaltungskompetenz. Inputs, \u00dcbungen, Rollenspiele und Praxisanteile sorgen f\u00fcr ein abwechslungsreiches Programm. Konzeptionelle Fragen stehen dabei ebenso im Mittelpunkt wie konkrete Werkzeuge und Anwendungsbeispiele. Am Ende der Weiterbildung wissen die Teilnehmenden auch, wie WorldCaf\u00e9 und Fishbowl funktionieren und was Open Space bedeutet. Ein Zertifikat bildet den Abschluss der Fortbildung, die in Zusammenarbeit mit der deutschen gesellschaft f\u00fcr MethodischeGruppenModeration (dg.MGM) statt.<br \/> Unter bestimmten Voraussetzungen k\u00f6nnen Teilnehmer\/innen eine F\u00f6rderung durch das F\u00f6rderprogramm IWiN (Individuelle Weiterbildung in Niedersachsen) oder \u00fcber den Bildungspr\u00e4miengutschein des Bundesministerium f\u00fcr Bildung und Forschung erhalten. Die f\u00fcnf Wochenendmodule finden von August bis Dezember von donnerstags, 18 Uhr bis samstags 15.30 Uhr statt.<br \/> Kontakt &amp; Anmeldung: Bildungwerk ver.di in Niedersachsen e.V., Region G\u00f6ttingen, Jochen Kampmeier, Rote Str. 19, 37073 G\u00f6ttingen, goettingen(at)erfolgreich-weiterbilden.de, Tel.: 0551 \/ 47 188, jochen.kampmeier(at)bw-verdi.de<\/p> <p>Informieren Sie sich weiter \u00fcber Fachzeitschriften aus dem Bereich <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.fachzeitungen.de\/seite\/p\/katdet\/katid\/9\/katidsub\/35\" title=\"Fachzeitschriften zum Thema Aus- und Weiterbildung\" >Bildung<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Jetzt anmelden: Kompakte Weiterbildung ab August 2011 beim Bildungswerk ver.di G\u00f6ttingen. Oft versanden neue Ideen im Arbeitsalltag, werden boykottiert oder einfach ausgesessen und vergessen. Dann ist es meist nicht gelungen, Mitarbeiter\/innen zu motivieren, Verantwortung f\u00fcr die Umsetzung zu \u00fcbernehmen. Hierf\u00fcr werden Handwerkszeuge gebraucht, die es erm\u00f6glichen, Betroffene zu Beteiligten zu machen. Moderationstechniken sind geeignet, um<\/p>\n","protected":false},"author":291,"featured_media":198217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-22344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeit-erziehung-bildung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=22344"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198217"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=22344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=22344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=22344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}