{"id":22423,"date":"2011-06-24T11:24:02","date_gmt":"2011-06-24T10:24:02","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=22423"},"modified":"2024-01-19T12:43:34","modified_gmt":"2024-01-19T11:43:34","slug":"interdisziplinaeres-sport","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/interdisziplinaeres-sport-1022423\/","title":{"rendered":"Interdisziplin\u00e4res zum Thema Sport"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Springer Medizin ver\u00f6ffentlicht kostenfreies Supplement rund um den Fu\u00dfball<br \/> Heidelberg, 9. Juni 2011. Deutschland, ein Sommerm\u00e4rchen &#8211; das war 2006. Wom\u00f6glich wiederholt sich diese Euphorie, wenn in Deutschland der Ball wieder rollt anl\u00e4sslich der Weltmeisterschaft im Frauenfu\u00dfball. Um seine Leser schon heute auf die kommenden Spiele einzustimmen, hat Springer Medizin ein Sonderheft herausgebracht, das sich in 12 Beitr\u00e4gen interdisziplin\u00e4r mit dem Thema Sport auseinandersetzt. Das 36-seitige Sonder-heft liegt jeweils einmalig der Mai bzw. Juniausgabe von Der Orthop\u00e4de, Der Unfallchirurg und Der Chirurg bei und erreicht so kostenfrei die Abonnenten dieser Fachzeitschriften.<br \/> <!--more-->\u201eAls Marktf\u00fchrer im Fachinformationssektor Medizin\/Gesundheitspolitik stellen wir uns re-gelm\u00e4\u00dfig medizinischen, zumeist problematischen, Themen im Kontext Gesundheit. Dass sich Springer Medizin nun anl\u00e4sslich der ins Haus stehenden WM mit Fu\u00dfball auseinan-dersetzt, geh\u00f6rt zu den angenehmen Aufgaben,\u201c erl\u00e4utert der f\u00fcr das Sonderheft verant-wortliche Redakteur Werner R\u00f6\u00dfling. \u201eBei den Beitr\u00e4gen haben wir uns haupts\u00e4chlich auf bew\u00e4hrte Springer-Autoren gest\u00fctzt. Diese haben dabei gerne mitgewirkt.\u201c So behandelt zum Beispiel der Beitrag \u201eWas ist normal und wo f\u00e4ngt Doping an?\u201c von Professor Dr. Ute Karck, Frauenklinik Stuttgart, das Thema Hormonbehandlung der Frau und der Doping-experte Professor Dr. Wilfried Kindermann, Saarbr\u00fccken, schreibt \u00fcber \u201eEliteathleten\/ innen und Asthma\u201c. F\u00fchrende Notfallmediziner wie Professor Dr. Uwe Kreimeier, Priv. Doz. Dr. Karl-Georg Kanz, beide LMU M\u00fcnchen, und Professor Dr. Hans-Richard Arntz, Charit\u00e9 Berlin, berichten \u00fcber die Herausforderungen der Notfallmedizin bei Gro\u00dfereig-nissen. Neben medizinischen Beitr\u00e4gen setzen sich unsere Experten auch mit psycholo-gischen Aspekten des Sports auseinander, wie \u201eLernen aus dem Fu\u00dfball\u201c von den beiden Coachs Andreas Sachs und Dr. Jana Leidenfrost oder \u201eMentales Training\u201c von Professor Dr. Jan Mayer, Saarbr\u00fccken, Psychologischer Coach beim Deutschen Fu\u00dfballbund und Springerbuchautor.<br \/> Das Sonderheft, gedruckt in einer Auflage von 15.000 Exemplaren, besch\u00e4ftigt sich neben weiteren Beitr\u00e4gen z.B. auch mit den typischen Verletzungsmustern im Frauenfu\u00dfball und enth\u00e4lt einen Spielplan zum Herausnehmen.<br \/> Springer Medizin ist f\u00fchrender Anbieter von Fachinformationen im Gesundheitswesen in Deutschland. Die Produktpalette von Springer Medizin umfasst Zeitschriften, Zeitungen, B\u00fccher und eine Vielzahl von Online-Angeboten f\u00fcr alle Arztgruppen, Pharmazeuten, Heilberufe und medizinisch interessierte Laien. Wichtige Qualit\u00e4tsmerkmale aller Verlagsprodukte sind hohe wissenschaftliche Qualit\u00e4t, Fort- und Weiterbildung auf dem neuesten Stand der medizinischen Forschung, sowie exzellente Vernetzung zu wissen-schaftlichen Fachgesellschaften, Berufsverb\u00e4nden, medizinischen Stiftungen, Heraus-gebern und Fachautoren. Springer Medizin ist Teil von Springer Science+Business Media.<br \/> Pressekontakt und Belegheft: Uschi Kidane | Springer Medizin | Tel. 06221 487-8166 | uschi.kidane@springer.com<\/p> <p>Die bsmo GmbH ist Teil der Fachverlagsgruppe Springer Science+Business Media.<br \/> Schwedter Str. 263<br \/> D-10119 Berlin<\/p>","protected":false},"excerpt":{"rendered":"<p>Springer Medizin ver\u00f6ffentlicht kostenfreies Supplement rund um den Fu\u00dfball Heidelberg, 9. Juni 2011. Deutschland, ein Sommerm\u00e4rchen &#8211; das war 2006. Wom\u00f6glich wiederholt sich diese Euphorie, wenn in Deutschland der Ball wieder rollt anl\u00e4sslich der Weltmeisterschaft im Frauenfu\u00dfball. Um seine Leser schon heute auf die kommenden Spiele einzustimmen, hat Springer Medizin ein Sonderheft herausgebracht, das sich<\/p>\n","protected":false},"author":291,"featured_media":198214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-22423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-und-freizeit"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=22423"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22423\/revisions"}],"predecessor-version":[{"id":275844,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22423\/revisions\/275844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198214"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=22423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=22423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=22423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}