{"id":22496,"date":"2011-06-27T10:35:27","date_gmt":"2011-06-27T09:35:27","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=22496"},"modified":"2013-08-09T10:29:35","modified_gmt":"2013-08-09T09:29:35","slug":"onlinetexte-marketinginstrument","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/onlinetexte-marketinginstrument-1022496\/","title":{"rendered":"Einfache und klare Strukturen f\u00fcr eine angenehm lesbare Pressemeldung"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-22499\" title=\" Gesch\u00e4ftsf\u00fchrer Daniel Deppe\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/22496\/Daniel Deppe - Gesch\u00e4ftsf\u00fchrer ONLINETEXTE.com 500-199x300.jpg\" alt=\"\" width=\"101\" height=\"151\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/22496\/Daniel%20Deppe%20-%20Gesch\u00e4ftsf\u00fchrer%20ONLINETEXTE.com%20500-199x300.jpg 199w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/22496\/Daniel%20Deppe%20-%20Gesch\u00e4ftsf\u00fchrer%20ONLINETEXTE.com%20500.jpg 333w\" sizes=\"auto, (max-width: 101px) 100vw, 101px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Beckum \u2013 Jeder, der sich ein wenig mit Marketing im Web auskennt, wei\u00df, dass er um regelm\u00e4\u00dfige Pressemeldungen, die kostenlos im Internet verbreitet werden k\u00f6nnen, gar nicht herumkommt. Und wenn die Pressemeldung echten Erfolg erzielen soll, dann muss sie auch etwas hergeben.<br \/> \u201ePressemeldungen sollte man als etwas Klassisches in neuer Umgebung sehen. Wie in den Printmedien geht es um Aktuelles, um Neuerungen, um \u00c4nderungen. <!--more-->Eine plumpe Nacherz\u00e4hlung alter H\u00fcte kann man sich getrost schenken\u201c erkl\u00e4rt Daniel Deppe, Inhaber der Beckumer Textagentur ONLINETEXTE.com.<\/p> <p>Es d\u00fcrfte au\u00dfer Frage stehen, dass eine gute Pressemeldung auch wirklich \u201eetwas zu sagen\u201c haben muss. M\u00f6glichkeiten f\u00fcr diesen ansprechenden Inhalt k\u00f6nnen beispielsweise Produktneuheiten oder frische Dienstleistungen sein. Nat\u00fcrlich sind auch eine erhaltene Auszeichnung, ein Sponsoring, ein Jubil\u00e4um oder gemeinn\u00fctzige Aktivit\u00e4ten durchaus eine Pressemeldung wert.<\/p> <p>Eine weitere H\u00fcrde ist das Finden passender Worte. Das interessanteste und wichtigste Thema wird den Leser h\u00f6chstwahrscheinlich binnen Sekunden abschrecken oder beim n\u00e4heren Hinblicken erm\u00fcden, wenn der Autor der Meldung die angemessenen Worte nicht fand. \u201eEs hat sich herausgestellt, dass jede zweite Online-Pressemeldung h\u00f6chstens zu einem Viertel gelesen wird. Grund sind das klassische \u201eum den hei\u00dfen Brei reden\u201c, ein viel zu komplizierter Aufbau und die gern genommenen Sammlungen wichtig klingender Fachbegriffe, mit denen selbst so mancher Insider \u00fcberfordert ist.\u201c wei\u00df Daniel Deppe. \u201eEinfache und klare Strukturen machen die Pressemeldung angenehm lesbar. Und wer auf die wichtigsten Fragen (Wer? Wo? Was? Wann? Warum? Wie?) pr\u00e4zise Antworten gibt, hat schon eine solide Basis geschaffen!\u201c so Herr Deppe weiter.<\/p> <p>Die Textagentur ONLINETEXTE.com bietet neben zahlreichen vorproduzierten Texten auch die individuelle Erstellung von Pressemeldungen f\u00fcr unterschiedliche Verwendungszwecke an. Gesch\u00e4ftsf\u00fchrer Daniel Deppe gibt unter folgenden Kontaktdaten gern selbst Auskunft:<\/p> <p>E-Mail: office@onlinetexte.com<br \/> Tel. +49 2521 8579391<br \/> Fax +49 2521 8579354<\/p> <p>Pressekontakt<\/p> <p>ONLINETEXTE.com<br \/> Inhaber: Daniel Deppe<br \/> Im Soestkamp 11<br \/> 59269 Beckum<br \/> Tel. +49 2521 8579391<br \/> Fax +49 2521 8579354<br \/> E-Mail: office@onlinetexte.com<br \/> Internet: http:\/\/www.onlinetexte.com<\/p> <p>Firmenportr\u00e4t<\/p> <p>ONLINETEXTE.com startete im Fr\u00fchjahr 2007 mit einem bis dahin fast unbekannten Konzept. Texte f\u00fcr Webmaster, Blogs, Pressemeldungen oder Templates konnten vorgefertigt in einem Onlineshop ausgesucht, bestellt und dann einfach f\u00fcr die eigenen Projekte verwendet werden.<br \/> Dieser neuartige Ansatz entwickelte sich geradezu beispiellos. Denn die bereits fertig produzierten Texte landen ohne Wartefrist beim Kunden und bringen dabei, zus\u00e4tzlich zum ben\u00f6tigten Inhalt, immer auch neue journalistische Ideen mit. So sind heute unter der Leitung von Gesch\u00e4ftsf\u00fchrer Daniel Deppe ein gutes Dutzend Autorinnen und Autoren f\u00fcr ONLINETEXTE.com t\u00e4tig, um regelm\u00e4\u00dfig neue Artikel f\u00fcr den Onlineshop zu verfassen. Und nat\u00fcrlich auch, um ma\u00dfgeschneiderte Werke im individuellen Kundenauftrag zu erstellen.<\/p> <p><a href=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/22496\/Daniel Deppe - Gesch\u00e4ftsf\u00fchrer ONLINETEXTE.com 500.jpg\">Daniel Deppe &#8211; Gesch\u00e4ftsf\u00fchrer ONLINETEXTE.com 500.jpg (36 KB)<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Beckum \u2013 Jeder, der sich ein wenig mit Marketing im Web auskennt, wei\u00df, dass er um regelm\u00e4\u00dfige Pressemeldungen, die kostenlos im Internet verbreitet werden k\u00f6nnen, gar nicht herumkommt. Und wenn die Pressemeldung echten Erfolg erzielen soll, dann muss sie auch etwas hergeben. \u201ePressemeldungen sollte man als etwas Klassisches in neuer Umgebung sehen. Wie in den<\/p>\n","protected":false},"author":291,"featured_media":198212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-22496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=22496"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198212"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=22496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=22496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=22496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}