{"id":22513,"date":"2011-06-27T10:41:33","date_gmt":"2011-06-27T09:41:33","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=22513"},"modified":"2011-11-09T11:30:03","modified_gmt":"2011-11-09T10:30:03","slug":"sportler-sahnetorte","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/sportler-sahnetorte-1022513\/","title":{"rendered":"&#8222;Goldener Windbeutel&#8220; f\u00fcr Ferrero"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Berlin, 27. Juni 2011 &#8211; Foodwatch hat vergangenen Freitag dem Unternehmen Ferrero den &#8222;Goldenen Windbeutel 2011&#8220; verliehen, den Preis f\u00fcr die Werbel\u00fcge des Jahres. Der Grund: Entgegen der Werbeaussage handele es sich bei der Milchschnitte nicht um eine leichte Zwischenmahlzeit, sondern vielmehr um eine Kalorienbombe, die prozentual mehr Fett und Zucker enth\u00e4lt als eine Sahnetorte. &#8222;Schmeckt leicht. Belastet nicht. Ideal f\u00fcr zwischendurch&#8220;, so der Slogan von Ferrero. Nicht mit uns: In einer vorausgehenden Befragung straften mehr als 51.000 von 117.000 Verbrauchern die Milchschnitte ab.<\/p> <p><!--more-->Konzerne wie Ferrero versuchten auch unausgewogenen Produkten noch einen sportlichen Anstrich zu verleihen, so Foodwatch. Das Verpflichten von jungen, erfolgreichen Sportlern sei ein beliebtes Mittel dazu. F\u00fcr Werbegelder ignorierten diese offenbar ihre Verantwortung, die sie insbesondere Kindern und Jugendlichen gegen\u00fcber haben. Und w\u00fcrden damit Ihrer Vorbildfunktion nicht gerecht.<\/p> <p>Ferrero hat den Preis abgelehnt und zeigt sich nicht zum Gespr\u00e4ch bereit. &#8222;Ferrero zeigt den eigenen Kunden die kalte Schulter und ignoriert die Kritik von mehr als 50.000 Verbrauchern [&#8230;] Die Kunden sind f\u00fcr Ferrero offenbar nur so lange K\u00f6nig, wie sie stillschweigend ihr Geld f\u00fcr die Produkte des Konzerns hinlegen. Die Lebensmittelindustrie wird sich eine solche Ignoranz nicht mehr lange leisten k\u00f6nnen&#8220;, sagt Anne Markwardt von foodwatch.<\/p> <p>Die N\u00e4hrwertkennzeichnung erfolgt in Mitgliedsstaaten der EU in der Regel freiwillig. Verpflichtend ist sie hingegen immer dann, wenn auf dem Etikett oder in der Werbung eine Angabe zum N\u00e4hrwert gemacht wird. Bei unverpackten Produkten wie Hackfleisch oder K\u00e4se helfen neue Technologien den Verbrauchern dabei, genau zu erkennen, welche Inhaltsstoffe enthalten sind. &#8222;W\u00e4hrend der Verk\u00e4ufer das Produkt wiegt, erscheint auf dem Display der Waage eine genaue Produktbeschreibung. Alternativ auch ein QR-Code: Scannt der Verbraucher diesen mit der Kamera seines Smartphones ein, erscheinen auf dem Bildschirm des Smartphones alle relevanten Produktinformationen&#8220;, erkl\u00e4rt Peter Laudien-Weidenfeller, Director Global Retail Sales des Unternehmens Bizerba.<\/p> <p>Gl\u00fccklich am Preis vorbeigeschrammt ist auch &#8222;Nimm2&#8220; von Storck. Foodwatch begr\u00fcndet die Nominierung wie folgt: Der Hersteller r\u00fchre einen k\u00fcnstlichen Vitamincocktail in die Bonbonmasse und wolle das Produkt damit &#8222;gesundwerben&#8220;. Doch die zugesetzten Vitamine seien in der Regel v\u00f6llig \u00fcberfl\u00fcssig und w\u00fcrden ganz einfach wieder ausgeschieden. &#8222;Daf\u00fcr lernen Kinder, dass sie ihren Vitaminbedarf auch mit S\u00fc\u00dfigkeiten statt mit Obst und Gem\u00fcse decken k\u00f6nnen&#8220;.<\/p> <p>Mit auf der Liste der schwarzen Schafe stand auch &#8222;Activia&#8220; von Danone. Auch dieses Produkte halte nicht was es verspreche, sagt foodwatch: Der Joghurt sei keine Wunderwaffe gegen Verdauungsbeschwerden, da er die Verdauung nicht mal eben regulieren k\u00f6nne, wie es Danone aber suggeriere. Besser und g\u00fcnstiger seien Trockenpflaumen, Weizenkleie oder ein Spaziergang. Auch hier lautet das Fazit: Minimale Effekte, maximal aufgeblasen &#8211; und teuer verkauft.<\/p> <p>Firmenkontakt<br \/> KLARTEXT ONLINE<br \/> KLARTEXT ONLINE<br \/> Auf dem Heidgen 27<\/p> <p>53127 Bonn<br \/> Deutschland<\/p> <p>E-Mail: info@klartextonline.com<br \/> Homepage: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.klartextonline.com\" title=\"Trends in Wirtschaft, Handel und Industrie\" >http:\/\/www.klartextonline.com<\/a><br \/> Telefon: 0228<\/p> <p>Pressekontakt<br \/> KLARTEXT ONLINE<br \/> KLARTEXT ONLINE<br \/> Auf dem Heidgen 27<\/p> <p>53127 Bonn<br \/> Deutschland<\/p> <p>E-Mail: info@klartextonline.com<br \/> Homepage: http:\/\/www.klartextonline.com<br \/> Telefon: 0228<\/p>","protected":false},"excerpt":{"rendered":"<p>Berlin, 27. Juni 2011 &#8211; Foodwatch hat vergangenen Freitag dem Unternehmen Ferrero den &#8222;Goldenen Windbeutel 2011&#8220; verliehen, den Preis f\u00fcr die Werbel\u00fcge des Jahres. Der Grund: Entgegen der Werbeaussage handele es sich bei der Milchschnitte nicht um eine leichte Zwischenmahlzeit, sondern vielmehr um eine Kalorienbombe, die prozentual mehr Fett und Zucker enth\u00e4lt als eine Sahnetorte.<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-22513","post","type-post","status-publish","format-standard","hentry","category-ernahrung-umwelt-natur"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=22513"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/22513\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=22513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=22513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=22513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}