{"id":24924,"date":"2011-08-04T15:38:48","date_gmt":"2011-08-04T14:38:48","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=24924"},"modified":"2012-09-07T11:41:22","modified_gmt":"2012-09-07T10:41:22","slug":"immer-auf-nummer-sicher-mit-tiefkuehlkost","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/immer-auf-nummer-sicher-mit-tiefkuehlkost-1024924\/","title":{"rendered":"Absolut sichere Produkte mit Frischewert"},"content":{"rendered":"<p>(ddp direct) Die Vorteile von Tiefk\u00fchlkost (TKK) sprechen f\u00fcr sich selbst: Eine ganzj\u00e4hrige Verf\u00fcgbarkeit, die bedarfsgerechte Portionierbarkeit sowie die problemlose Zubereitung werden von den Verbrauchern als wesentliche TKK-Vorteile angesehen. Wichtiger aber noch &#8211; dies zeigen die anhaltenden Diskussionen um die Qualit\u00e4t von Lebensmitteln: Die Produktsicherheit sozusagen das Null-Risiko ist ein entscheidendes Leistungskriterium, das f\u00fcr TKK spricht.<\/p> <p>Dabei gilt der Grundsatz: Es werden nur qualitativ hochwertige Lebensmittel-Rohwaren verwendet und diese werden innerhalb k\u00fcrzester Zeit bei sehr niedrigen Temperaturen durch die so genannte Schockfrostung haltbar gemacht. <!--more-->Zudem m\u00fcssen die Rohwaren exakt den Anforderungen der Hersteller von TKK entsprechen, so dass beispielsweise der Anbau von Gem\u00fcse durch st\u00e4ndige Qualit\u00e4ts\u00fcberwachungen gew\u00e4hrleistet wird und die Ernte erst wenige Stunden vor der Weiterverarbeitung beginnt. Fische werden schon an Bord des Fangschiffes tiefgefroren. Die strengen Kriterien der Qualit\u00e4tssicherung gelten w\u00e4hrend der gesamten Produktion bis hin zur Verpackung, der Lagerung und dem Vertrieb der Produkte.<\/p> <p>Der Zeitfaktor ist entscheidend<br \/> Das Verarbeitungstempo bei der Produktion von Tiefk\u00fchlkost ist der entscheidende Faktor, um die Frische der Produkte garantieren zu k\u00f6nnen. Bei der industriellen Herstellung von Tiefk\u00fchlkost erfolgt das Absenken der Temperatur der verarbeiteten Lebensmittel bei circa<br \/> -30 \u00b0C bis -50 \u00b0C mit \u00e4u\u00dferst hohen, produktangepassten Gefriergeschwindigkeiten.<br \/> Diese sind abh\u00e4ngig von der Produktart, der Menge und dem Tiefgefrierverfahren. In der Regel sind die meisten Lebensmittel innerhalb von 4 bis 20 Minuten tiefgefroren. Danach werden die TK-Produkte st\u00e4ndig bei mindestens -18 \u00b0C gek\u00fchlt. Bei dieser Temperatur kommen die Zellaktivit\u00e4ten zum Stillstand, zudem sorgt sie stets f\u00fcr bakteriologisch einwandfreie und sichere Produkte. Die industrielle Schockfrostung ist damit die schonendste Art der Haltbarmachung ganz ohne Konservierungsstoffe.<\/p> <p>Vorsicht ist besser als Nachsicht<br \/> Alle Hersteller verf\u00fcgen \u00fcber ein l\u00fcckenloses Qualit\u00e4tsmanagement, das vor, w\u00e4hrend und nach dem Produktionsprozess zum Einsatz kommt. Die Qualit\u00e4tssicherung umfasst die Produktentwicklung, Erzeugung der Rohstoffe, die Anlieferung oder die etwaige Zwischenlagerung, Vorbereitung und Verarbeitung, Verpackung und Lagerung sowie die Logistik bis hin zur Produktbeobachtung im Markt.<\/p> <p>Immer auf der sicheren Seite<br \/> Die Tiefk\u00fchlung bringt noch weitere Vorteile mit sich: Tiefgefrorene Lebensmittel sind hygienisch absolut sichere Produkte mit Frischewert. Die Frische der tiefgek\u00fchlten Produkte wird durch die Schockfrostung lediglich in einen K\u00e4lteschlaf versetzt und bleibt bis zur Zubereitung zuhause erhalten auch nach l\u00e4ngerer Lagerdauer.<br \/> Die tiefen Temperaturen und die sachgerechte Verpackung sch\u00fctzen die Tiefk\u00fchlkost zudem vor Mikroorganismen und Verunreinigungen. Durch den Gefriervorgang werden viele mikrobiologische Prozesse, die in einem Lebensmittel zur Entstehung sch\u00e4dlicher Stoffe oder zum Lebensmittelverderb f\u00fchren k\u00f6nnen, gestoppt. Die meisten Gem\u00fcsesorten sowohl f\u00fcr naturbelassenes TK-Gem\u00fcse als auch f\u00fcr TK-Gem\u00fcsezubereitungen werden vor dem Gefriervorgang blanchiert. Dabei wird das Gem\u00fcse in Wasser oder wasserdampfges\u00e4ttigter Luft bei Temperaturen um die 100 \u00b0C erhitzt. Hierdurch werden Keime oder Bakterien (wie bspw. auch der EHEC-Erreger) vollst\u00e4ndig abget\u00f6tet. Das Blanchieren hat aber noch einen besonderen Effekt: Erbsen, Bohnen und Spinat behalten so ihre sch\u00f6ne nat\u00fcrliche Farbe.<\/p> <p>Genuss ohne Risiko<br \/> Gerade in einer Zeit, in der die Verbraucher oftmals eher verunsichert, als aufgekl\u00e4rt werden und die Sicherheit und Qualit\u00e4t von Lebensmitteln eine umso gr\u00f6\u00dfere Rolle spielen, kann die Tiefk\u00fchlkost mit ihren hohen Qualit\u00e4ts- und Sicherheitsstandards punkten. Es kommt also nicht von ungef\u00e4hr, dass jeder Bundesb\u00fcrger mittlerweile durchschnittlich 40,2 Kilo Tiefk\u00fchlkost pro Jahr verzehrt. Tiek\u00fchlkost garantiert Genuss ohne Risiko.<\/p> <p>Shortlink zu dieser Pressemitteilung:<br \/> http:\/\/shortpr.com\/5351ua<\/p> <p>Permanentlink zu dieser Pressemitteilung:<br \/> http:\/\/www.themenportal.de\/vermischtes\/immer-auf-nummer-sicher-mit-tiefkuehlkost-74884<\/p> <p>Firmenkontakt<br \/> Deutsches Tiefk\u00fchlinstitut<br \/> Carola Herckelrath<br \/> Reinhardtstra\u00dfe a 18<\/p> <p>10117 Berlin<br \/> Deutschland<\/p> <p>E-Mail: herckelrath@tiefkuehlkost.de<br \/> Homepage: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.tiefkuehlkost.de\/\" title=\"Informationsplattform f\u00fcr Tiefk\u00fchlkost\" >www.tiefkuehlkost.de<\/a>; www.frischer-als-frisch.de<br \/> Telefon: 030 2809362-12<\/p> <p>Pressekontakt<br \/> Deutsches Tiefk\u00fchlinstitut<br \/> Carola Herckelrath<br \/> Reinhardtstra\u00dfe a 18<\/p> <p>10117 Berlin<br \/> Deutschland<\/p> <p>E-Mail: herckelrath@tiefkuehlkost.de<br \/> Homepage:<br \/> Telefon: 030 2809362-12<\/p>","protected":false},"excerpt":{"rendered":"<p>(ddp direct) Die Vorteile von Tiefk\u00fchlkost (TKK) sprechen f\u00fcr sich selbst: Eine ganzj\u00e4hrige Verf\u00fcgbarkeit, die bedarfsgerechte Portionierbarkeit sowie die problemlose Zubereitung werden von den Verbrauchern als wesentliche TKK-Vorteile angesehen. Wichtiger aber noch &#8211; dies zeigen die anhaltenden Diskussionen um die Qualit\u00e4t von Lebensmitteln: Die Produktsicherheit sozusagen das Null-Risiko ist ein entscheidendes Leistungskriterium, das f\u00fcr TKK<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-24924","post","type-post","status-publish","format-standard","hentry","category-ernahrung-umwelt-natur"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/24924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=24924"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/24924\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=24924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=24924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=24924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}